{"id":30981,"date":"2013-12-18T03:36:16","date_gmt":"2013-12-18T07:36:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/10-curiosidades-sobre-nelson-mandela\/"},"modified":"2013-12-18T03:36:16","modified_gmt":"2013-12-18T07:36:16","slug":"10-curiosidades-sobre-nelson-mandela","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/10-curiosidades-sobre-nelson-mandela\/","title":{"rendered":"10 curiosidades sobre Nelson Mandela"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-30980\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_10_curiosidades_de_mandela.jpg\" width=\"300\" height=\"181\" alt=\"10_curiosidades_de_mandela\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_10_curiosidades_de_mandela.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_10_curiosidades_de_mandela-500x300.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>10 curiosidades sobre Nelson Mandela.&nbsp;El ex Presidente de S\u00fadafrica Nelson Mandela, falleci\u00f3 el d\u00eda 05\/12\/13 en Johannesburgo falleciendo a sus 95 a\u00f1os de edad.&nbsp;Hoy te vamos a presentar 10 Curiosidades de Nelson Mandela:<\/p>\n<p>  <!--more-->  <\/p>\n<p>1- Nelson Mandela se gradu\u00f3 de Derecho en la Universidad de Wiswatersrand, completando la carrera de Derecho. <\/p>\n<p> 2- Mandela pas\u00f3 27 a\u00f1os en prisi\u00f3n tras ser declarado culpable de sabotaje e intentos de derrocar al gobierno. <\/p>\n<p> 3- 18 de los 27 a\u00f1os de encarcelamiento los pas\u00f3 en la prisi\u00f3n de Robben Island, lugar en donde su reputaci\u00f3n creci\u00f3 hasta ser conocido como una figura legendaria que representaba la falta de libertad que padec\u00edan todos los hombres de raza negra. <\/p>\n<p> 4- El cari\u00f1oso apodo de Madiba que se ha ganado, es en realidad un t\u00edtulo honor\u00edfico otorgado por los ancianos del clan de Mandela, quien tambi\u00e9n ha sido llamado Tata. <\/p>\n<p> 5- A lo largo de 40 a\u00f1os ha recibido m\u00e1s de 250 premios y reconocimientos internacionales, incluyendo el Premio Nobel de la Paz en 1993. <\/p>\n<p> 6- Nelson Mandela naci\u00f3 en la tribu Thembu de la etnia Xhosa. Fue el primero de toda la tribu en asistir a la escuela a los 7 a\u00f1os, donde recibi\u00f3 educaci\u00f3n brit\u00e1nica. El nombre en el que era conocido en la tribu era Rolihlahla, pero una maestra de nombre Mdingane le llam\u00f3 Nelson. <\/p>\n<p> 7- \u00c9l y su primo Justice huyeron de Johannesburgo para evitar los matrimonios arreglados. En 1941 conoce a Walter Sisulu, quien lo ayud\u00f3 para que terminara la licenciatura en la Universidad de Sud\u00e1frica y empez\u00f3 a trabajar en un bufete de abogados de Lazar Sidelsky. <\/p>\n<p> 8- El 21 de marzo 1960 fue la matanza de Sharpeville, donde murieron 69 ciudadanos negros en una manifestaci\u00f3n pac\u00edfica en manos de la polic\u00eda. Fue entonces cuando Mandela decidi\u00f3 luchar en la clandestinidad y recorri\u00f3 en secreto todo el pa\u00eds para organizar una huelga. <\/p>\n<p> 9- Para 1961 logr\u00f3 salir de Sud\u00e1frica (sin autorizaci\u00f3n) y visit\u00f3 otros pa\u00edses africanos y Gran Breta\u00f1a, donde pidi\u00f3 apoyo para liberar su pa\u00eds. En 1962 fue detenido, acusado de rebeli\u00f3n y abandono ilegal del pa\u00eds. <\/p>\n<p> 10- Con 12 Hermanos naci\u00f3 en Mvezo, un poblado que ten\u00eda solo 300 habitantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>10 curiosidades sobre Nelson Mandela.&nbsp;El ex Presidente de S\u00fadafrica Nelson Mandela, falleci\u00f3 el d\u00eda 05\/12\/13 en Johannesburgo falleciendo a sus 95 a\u00f1os de edad.&nbsp;Hoy te vamos a presentar 10 Curiosidades de Nelson Mandela:<\/p>\n","protected":false},"author":3,"featured_media":30980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-30981","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=30981"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/30981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30980"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=30981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=30981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=30981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}