{"id":31003,"date":"2013-12-20T00:44:42","date_gmt":"2013-12-20T04:44:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/pastel-de-pera-y-manzana\/"},"modified":"2013-12-20T00:44:42","modified_gmt":"2013-12-20T04:44:42","slug":"pastel-de-pera-y-manzana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pastel-de-pera-y-manzana\/","title":{"rendered":"Pastel de pera y manzana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31001\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_Pastel_de_pera_y_manzana.jpg\" width=\"654\" height=\"441\" alt=\"Pastel_de_pera_y_manzana\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_Pastel_de_pera_y_manzana.jpg 654w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_Pastel_de_pera_y_manzana-300x202.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_Pastel_de_pera_y_manzana-75x52.jpg 75w\" sizes=\"auto, (max-width: 654px) 100vw, 654px\" \/>Los bizcochos y pasteles de fruta son una de mis debilidades y concretamente los que llevan manzana. Me sucede lo mismo con las tartas de manzana, que pruebo todas aquellas recetas que caen en mis manos, as\u00ed que cuando vi en una revista este&nbsp;pastel de pera y manzana, no pude resistirme a probarlo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El resultado es fant\u00e1stico. Realmente&nbsp;es una tarta tipo bizcocho ligero, mezcla entre pastel y cake, que es muy agradable al paladar y no resulta nada pesado ni dulz\u00f3n. Si lo decoramos con fruta \u00e1cida, como en mi caso con unas frambuesas, el contraste es muy bueno. \u00a1Probadlo!<\/p>\n<h2>Ingredientes para 4 personas<\/h2>\n<ul>\n<li>1 manzana, 2 peras, 2 huevos, 80 ml de leche, 80 g de az\u00facar, 80 g de harina, 8 g de levadura qu\u00edmica, 40 g de mantequilla, 1 pizca de sal, az\u00facar glas.<\/li>\n<\/ul>\n<h2>C\u00f3mo hacer pastel de peras y manzanas<\/h2>\n<p>Calentamos el horno a 180\u00ba&nbsp;con calor arriba abajo sin aire. Batimos los&nbsp;huevos&nbsp;con el az\u00facar y la pizca de sal hasta que esponjen. Agregamos poco a poco la leche y la mantequilla derretida tibia. Unimos con la harina y la levadura tamizadas mientras seguimos batiendo.<\/p>\n<p>En un molde redondo o cuadrado,&nbsp;engrasado y ligeramente enharinado de 20 cm, colocamos l\u00e1minas finas de manzana pelada, vertemos por encima la mitad de la masa, colocamos l\u00e1minas finas de&nbsp;pera&nbsp;y cubrimos con el resto de la masa.<\/p>\n<p>Horneamos durante una media hora, m\u00e1s o menos, hasta que el pastel est\u00e9 ligeramente dorado y cuajado. Dejamos que se temple un poco, lo desmoldamos y servimos espolvoreado de az\u00facar glas y unas frutas, si lo deseamos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31002\" alt=\"Pastel de pera y manzana. Receta  paso a paso\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/img.directoalpaladar.com_2013_12_receta-pastel-peras-y-manzanas-paso-a-paso.jpg\" width=\"650\" height=\"325\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/img.directoalpaladar.com_2013_12_receta-pastel-peras-y-manzanas-paso-a-paso.jpg 650w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/img.directoalpaladar.com_2013_12_receta-pastel-peras-y-manzanas-paso-a-paso-300x150.jpg 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>Tiempo de elaboraci\u00f3n | 1 hora<br \/>Dificultad | Baja<\/p>\n<h2>Degustaci\u00f3n<\/h2>\n<p>Este&nbsp;pastel de peras y manzanas&nbsp;resulta muy jugoso e ideal para tomar tanto templado como fr\u00edo, con lo cual podemos hacerlo con antelaci\u00f3n si nos interesa. La receta es apta para utilizar tambi\u00e9n con cualquier otra fruta de temporada con pulpa firme como pl\u00e1tano o mango.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los bizcochos y pasteles de fruta son una de mis debilidades y concretamente los que llevan manzana. Me sucede lo mismo con las tartas de manzana, que pruebo todas aquellas recetas que caen en mis manos, as\u00ed que cuando vi en una revista este&nbsp;pastel de pera y manzana, no pude resistirme a probarlo.<\/p>\n","protected":false},"author":3,"featured_media":31001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31003"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31001"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}