{"id":31009,"date":"2013-12-21T13:14:38","date_gmt":"2013-12-21T17:14:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/francisco-le-pide-a-la-curia-mas-profesionalismo-y-menos-bulto\/"},"modified":"2013-12-21T13:14:38","modified_gmt":"2013-12-21T17:14:38","slug":"francisco-le-pide-a-la-curia-mas-profesionalismo-y-menos-bulto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/francisco-le-pide-a-la-curia-mas-profesionalismo-y-menos-bulto\/","title":{"rendered":"Francisco le pide a la Curia m\u00e1s profesionalismo y menos bulto"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31008\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_papa_francisco_en_navidad.jpg\" width=\"770\" height=\"433\" alt=\"papa_francisco_en_navidad\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_papa_francisco_en_navidad.jpg 770w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_papa_francisco_en_navidad-300x168.jpg 300w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/>En medio de la&nbsp;reforma&nbsp;que est\u00e1 llevando a cabo, el&nbsp;Santo Padre&nbsp;recibi\u00f3 a los miembros del Gobierno vaticano para el tradicional&nbsp;saludo de Navidad&nbsp;y les pidi\u00f3&nbsp;evitar los rumores&nbsp;que conspiran contra su trabajo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El&nbsp;papa Francisco&nbsp;pidi\u00f3 hoy a los miembros de la Curia Romana, el Gobierno de la Iglesia cat\u00f3lica, que eviten los&nbsp;\u00abcotilleos\u00bb,&nbsp;pues estos solo&nbsp;da\u00f1an la calidad de las personas, del trabajo y el ambiente\u00bb.<\/p>\n<p>\u00abOs pido ejercer la objeci\u00f3n de conciencia para que nos opongamos a practicar una ley no escrita de nuestros ambientes, que por desgracia es la de los cotilleos\u00bb, les inst\u00f3 el papa, que desde que comenz\u00f3 su pontificado ha emprendido una&nbsp;reforma de la Curia,&nbsp;ayudado por una Comisi\u00f3n de ocho cardenales.<\/p>\n<p>Francisco recibi\u00f3 hoy a los miembros de la Curia para la tradicional felicitaci\u00f3n de Navidad y la ocasi\u00f3n sirvi\u00f3 al pont\u00edfice argentino para recordarles que sus principales caracter\u00edsticas tienen que ser&nbsp;la \u00abprofesionalidad y el servicio\u00bb.<\/p>\n<p>A los miembros de la Curia les puso el ejemplo \u00abdel papel de&nbsp;San Jos\u00e9,&nbsp;tan callado y tan necesario al lado de la Virgen Mar\u00eda\u00bb.<\/p>\n<p>\u00abPensemos en \u00e9l, en su preocupaci\u00f3n por su esposa y por el Ni\u00f1o.&nbsp;Esto nos dice mucho sobre nuestro servicio a la Iglesia\u00bb, agreg\u00f3.<\/p>\n<p>El papa comenz\u00f3 su mensaje agradeciendo a todos su \u00abservicio cotidiano: por el celo, la diligencia y la creatividad\u00bb y por el \u00abesfuerzo, no siempre f\u00e1cil, de colaborar en el trabajo, de escucharse y confrontarse, de valorar personalidades y cualidades diferentes en el respeto rec\u00edproco\u00bb.<\/p>\n<p>A los miembros de la Curia les explic\u00f3 que sus principales caracter\u00edsticas tienen que ser&nbsp;\u00abla profesionalidad, que significa competencia, estudio, y actualizaci\u00f3n\u00bb.<\/p>\n<p>Advirti\u00f3 de que \u00abcuando no hay profesionalidad, lentamente se va resbalando hacia el \u00e1rea de la mediocridad\u00bb.<\/p>\n<p>El pont\u00edfice, ex arzobispo de Buenos Aires, tambi\u00e9n expres\u00f3 su admiraci\u00f3n por los \u00abmonse\u00f1ores que siguen el modelo de los antiguos curiales, personas ejemplares, que trabajan con competencia, con rigor, con abnegaci\u00f3n, desempe\u00f1ando con esmero sus tareas de cada d\u00eda\u00bb.<\/p>\n<p>Y pidi\u00f3&nbsp;que sean estos modelos los que inspiren a quienes trabajan en la Curia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la&nbsp;reforma&nbsp;que est\u00e1 llevando a cabo, el&nbsp;Santo Padre&nbsp;recibi\u00f3 a los miembros del Gobierno vaticano para el tradicional&nbsp;saludo de Navidad&nbsp;y les pidi\u00f3&nbsp;evitar los rumores&nbsp;que conspiran contra su trabajo.<\/p>\n","protected":false},"author":3,"featured_media":31008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31009"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31008"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}