{"id":31017,"date":"2013-12-21T13:43:02","date_gmt":"2013-12-21T17:43:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cince-online-don-jon-un-chico-con-talento-trailer\/"},"modified":"2013-12-21T13:43:02","modified_gmt":"2013-12-21T17:43:02","slug":"cince-online-don-jon-un-chico-con-talento-trailer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cince-online-don-jon-un-chico-con-talento-trailer\/","title":{"rendered":"Cince Online &#8211; Don Jon, un chico con talento (TRAILER)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31016\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_don_jon_trailer.jpg\" width=\"606\" height=\"297\" alt=\"don_jon_trailer\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_don_jon_trailer.jpg 606w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_don_jon_trailer-300x147.jpg 300w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/>El chico a quien nos referimos es Joseph Gordon Levitt, que es, f\u00edjense bien, el actor principal de \u201cDon Jon\u201d, pero tambi\u00e9n su guionista y, por si todo eso fuera poco, tambi\u00e9n es el director de la pel\u00edcula.<\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 11px;\">Por supuesto, no es que vayamos a decir ahora que la cinta es una tremenda maravilla pero, aun siendo una buena pel\u00edcula est\u00e1 muy por encima de numerosos directores veteranos y, sobre todo, de muchos debutantes.<\/p>\n<p><\/span><span style=\"font-size: 11px;\">Adem\u00e1s, \u201cDon Jon\u201d no es una simple y anodina historia de amor mezclada con comedia que sigue los trillados y facilones senderos de las f\u00f3rmulas establecidas: chico y chica se enamoran, luego se separan y, al final, se arreglan para el esperado final feliz.<\/p>\n<p><\/span><span style=\"font-size: 11px;\">No, \u201cDon Jon\u201d no es tradicional, no es predecible y, por encima de todo ello, tampoco es una historia &nbsp;f\u00e1cil de digerir.<\/span><\/p>\n<p><span style=\"font-size: 11px;\">Trailer<br \/><iframe loading=\"lazy\" width=\"610\" height=\"360\" src=\"\/\/www.youtube.com\/embed\/ttSNSsH44uY?feature=player_detailpage\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe><br \/><\/span><span style=\"font-size: 11px;\"><br \/>Jon, el personaje central, a quien le dicen \u201cDon Juan\u201d por ser un chico conquistador, de esos que van a los lugares de diversi\u00f3n junto a sus dos amigos inseparables y, en tanto ellos miran y aprenden, \u00e9l se goza a una chica en la pista de baile, en los sillones del establecimiento y, luego, en su cama, de ella o suya, que da lo mismo. Jon, descendiente de italianos con un padre dicharachero, machista y vulgar, y una madre que ans\u00eda nietos y una hermana que se pasa casi todo el relato mirando de soslayo celular en mano hasta que dice las palabras que deciden todo el asunto, es un adicto al porno en Internet; goza sexualmente sus conquistas, pero piensa que se goza m\u00e1s con las chicas de la pantalla y el onanismo consabido y m\u00e1s que reiterado.<\/p>\n<p><\/span><span style=\"font-size: 11px;\">Pero, como en toda comedia rom\u00e1ntica, al fin conoce a la hermosa que ha de sacarle de Internet y que le permite cambiar los t\u00e9rminos de su confesi\u00f3n dominical al cura que nunca conoce y que le \u201cabsuelve\u201d siempre por igual, no importa lo que confiese.<\/p>\n<p><\/span><span style=\"font-size: 11px;\">Pero, insistimos sin poder contarles m\u00e1s detalles: no es lo mismo de siempre, no se apega a la f\u00f3rmula el amigo Gordon Levitt, hace respingar las narices de los reverentes, de los pacatos, y nos deja con un palmo de narices con un final que no tiene nada ni de final feliz ni de final acartonado porque usted, si posee un cerebro, comprende que no todo puede ser felicidad completa y que hay situaciones que parecen soluciones pero no pueden serlo. Buenas actuaciones de Gordon Levitt, Scarlett Johanson y los dem\u00e1s.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El chico a quien nos referimos es Joseph Gordon Levitt, que es, f\u00edjense bien, el actor principal de \u201cDon Jon\u201d, pero tambi\u00e9n su guionista y, por si todo eso fuera poco, tambi\u00e9n es el director de la pel\u00edcula.<\/p>\n","protected":false},"author":3,"featured_media":31016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31017"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31016"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}