{"id":31145,"date":"2013-12-30T13:58:46","date_gmt":"2013-12-30T17:58:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-10-mejores-series-de-television-de-2013\/"},"modified":"2013-12-30T13:58:46","modified_gmt":"2013-12-30T17:58:46","slug":"las-10-mejores-series-de-television-de-2013","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-10-mejores-series-de-television-de-2013\/","title":{"rendered":"Las 10 mejores series de televisi\u00f3n de 2013"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-31144\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_563620_10152112034457722_1095582574_n.jpg\" width=\"600\" height=\"400\" alt=\"563620_10152112034457722_1095582574_n\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_563620_10152112034457722_1095582574_n.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_563620_10152112034457722_1095582574_n-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>El final de a\u00f1o es raz\u00f3n para que un sinf\u00edn de conteos y listados comience a aparecer, y esta vez, las series de televisi\u00f3n no se pod\u00edan quedar atr\u00e1s, por eso y con informaci\u00f3n de Noticias 24 y Cineman\u00eda, en De10.mx hemos seleccionado nuestras 10 favoritas&#8230;<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p><strong>Breaking Bad:&nbsp;<\/strong>Sin duda, para los fan\u00e1ticos de las series de televisi\u00f3n, esta es la que se llev\u00f3 el 2013, y es que con su esperado final, esta&nbsp;<label datatype=\"t\">serie<\/label>&nbsp;logro grandes&nbsp;<label datatype=\"t\">audiencias<\/label>. Tras cinco temporadas, las aventuras del antih\u00e9roe Walter White, tuvieron un fin que, seguramente, pasar\u00e1 a la historia.<\/p>\n<p><strong>The Walking Dead:<\/strong>&nbsp;Basada en el c\u00f3mic de Robert Kirkman, esta serie es, por mucho, la favorita de todos aquellos que gustan de las historias de zombies. Cuenta la historia de Rick y un grupo de personas intentando sobrevivir al llamado \u00abApocalipsis zombie\u00bb<\/p>\n<p><strong><label datatype=\"t\">Juego<\/label>&nbsp;de Tronos:&nbsp;<\/strong>Esta saga fue escrita por George R.R. Martin y tra\u00edda a la pantalla chica por la cadena HBO. Se estren\u00f3 en 2011, pero este 2013 dio mucho de qu\u00e9 hablar debido a sus m\u00faltiples nominaciones a un gran n\u00famero de premios. Sin duda una de las favoritas del p\u00fablico.<\/p>\n<p><strong>The American Horror Story:<\/strong>&nbsp;La mezcla perfecta entre el drama y el terror fue encontrada en esta serie antol\u00f3gica, y es que cada temporada ha sido concebida con una miniserie independiente, con personajes y escenarios distintos que, sin duda te dejar\u00e1n con la boca abierta y queriendo m\u00e1s&#8230;<\/p>\n<p><strong>The Good Wife:&nbsp;<\/strong>Sin duda, esta serie es un drama en el cual las historias de sus protagonistas se entrelazan con casos judiciales; una de las favoritas de este 2013.<\/p>\n<p><strong>Dexter:&nbsp;<\/strong>Protagonizada por Michael C. Hall, esta serie est\u00e1 ambientada en Miami y se basa en la novela Darkly Dreaming Dexter, de Jeff Lindsay; ha tenido cr\u00edticas muy buenas y gran popularidad desde su estreno en 2006 hasta el \u00faltimo cap\u00edtulo transmitido, el 22 de septiembre del 2013.<\/p>\n<p><strong>Homeland:&nbsp;<\/strong>Basada en una serie israel\u00ed, \u00e9sta se encuentra protagonizada por Claire Danes y cuenta la historia de una agente de la Agencia Central de Inteligencia, quien llega a creer que un marine fue hecho prisionero de guerra de Al-Qaeda.<\/p>\n<p><strong>Orange is the new black:<\/strong>&nbsp;Producida por Lionsgate Television, esta serie se emiti\u00f3 por primera vez en Netflix, en julio del 2013. Se basa en el libro autobiogr\u00e1fico de Piper Kerman y relata su vida desde la c\u00e1rcel.<\/p>\n<p><strong>The Bridge:&nbsp;<\/strong>Esta serie estadounidense es protagonizada por el mexicano Demi\u00e1n Bichir, se estren\u00f3 en julio del 2013 y es transmitida por la cadena FOX. La tem\u00e1tica es bastante controvertida, pues se basa en la pol\u00e9mica de las conocidas como \u00abMueras de Ju\u00e1rez\u00bb.<\/p>\n<p><strong>Scandal:<\/strong>&nbsp;Olivia Pope es una abogada experta en las crisis y los esc\u00e1ndalos, tanto, que el presidente de los Estados Unidos es su cliente, dej\u00e1ndole como misi\u00f3n proteger y defender su imagen&#8230;<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/de10.com.mx\/top10\/2013\/las-10-mejores-series-de-television-de-2013-17750.html\" title=\"http:\/\/de10.com.mx\/top10\/2013\/las-10-mejores-series-de-television-de-2013-17750.html\">http:\/\/de10.com.mx\/top10\/2013\/las-10-mejores-series-de-television-de-201&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El final de a\u00f1o es raz\u00f3n para que un sinf\u00edn de conteos y listados comience a aparecer, y esta vez, las series de televisi\u00f3n no se pod\u00edan quedar atr\u00e1s, por eso y con informaci\u00f3n de Noticias 24 y Cineman\u00eda, en De10.mx hemos seleccionado nuestras 10 favoritas&#8230;<\/p>\n","protected":false},"author":3,"featured_media":31144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31145"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31144"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}