{"id":31152,"date":"2013-12-30T14:05:37","date_gmt":"2013-12-30T18:05:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-10-temas-mas-buscados-en-google-del-2013\/"},"modified":"2013-12-30T14:05:37","modified_gmt":"2013-12-30T18:05:37","slug":"los-10-temas-mas-buscados-en-google-del-2013","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-10-temas-mas-buscados-en-google-del-2013\/","title":{"rendered":"Los 10 temas m\u00e1s buscados en Google del 2013"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31151\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_10_mas_buscados_por_google.png\" width=\"620\" height=\"333\" alt=\"10_mas_buscados_por_google\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_10_mas_buscados_por_google.png 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/12\/sosua_images_10_mas_buscados_por_google-300x161.png 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>Esta es la lista de los 10 temas m\u00e1s buscado en Google del 2013, la cual es encabezada por el fallecimiento del expresidente sudafricano Nelson Mandela, seguido por el deceso de Paul Walker.<\/div>\n<p>  <!--more-->  <\/p>\n<div>\n<p>La compa\u00f1\u00eda de Mountain View nuevamente ha publicado el&nbsp;<strong>Google Zeitgeist<\/strong>, esta vez en la edici\u00f3n&nbsp;<strong>2013<\/strong>, conde re\u00fane lo&nbsp;<strong>m\u00e1s buscado&nbsp;<\/strong>de este a\u00f1o en el famoso motor de b\u00fasqueda de Internet.<\/p>\n<p>El ex presidente sudafricano&nbsp;<strong>Nelson Mandela<\/strong>, que falleci\u00f3 este mes, ocup\u00f3 el primer lugar, seguido del actor de cine&nbsp;<strong>Paul Walker<\/strong>, de \u00abFast &amp; Furious\u00bb, que muri\u00f3 en un accidente automovil\u00edstico el 30 de noviembre.<\/p>\n<p>Esta es la lista completa de lo m\u00e1s buscado en Google del 2013:<\/p>\n<p>&nbsp;&#8211; Nelson Mandela<\/p>\n<p>&nbsp;&#8211; Paul Walker<\/p>\n<p>&nbsp;&#8211; iPhone 5s<\/p>\n<p>&nbsp;&#8211; Cory Monteith<\/p>\n<p>&nbsp;&#8211; Harlem Shake<\/p>\n<p>&nbsp;&#8211; Boston Marathon<\/p>\n<p>&nbsp;&#8211; Royal Baby<\/p>\n<p>&nbsp;&#8211; Samsung Galaxy s4<\/p>\n<p>&nbsp;&#8211; PlayStation 4<\/p>\n<p>&nbsp;&#8211; North Korea.<\/p>\n<p>La revisi\u00f3n anual de Google tiene lugar despu\u00e9s de las que efectuaron en las dos \u00faltimas semanas sus principales rivales en la b\u00fasqueda en la red: Bing de Microsoft Corp., Yahoo Inc. y Ask.com.<\/p>\n<\/p><\/div>\n<div>\n<div>\n<div data-video=\"Lv-sY_z8MNs\"><iframe loading=\"lazy\" id=\"tubeplayer-player-container1388414253251\" frameborder=\"0\" allowfullscreen=\"1\" title=\"YouTube video player\" width=\"620\" height=\"415\" src=\"http:\/\/www.youtube.com\/embed\/Lv-sY_z8MNs?autoplay=0&amp;autohide=1&amp;controls=1&amp;rel=0&amp;fs=1&amp;wmode=transparent&amp;showinfo=0&amp;modestbranding=1&amp;start=0&amp;theme=dark&amp;color=red&amp;enablejsapi=1&amp;origin=http%3A%2F%2Fwww.lv12.com.ar\"><\/iframe><\/div>\n<div>10 temas m\u00e1s buscado en Google del 2013<\/div>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esta es la lista de los 10 temas m\u00e1s buscado en Google del 2013, la cual es encabezada por el fallecimiento del expresidente sudafricano Nelson Mandela, seguido por el deceso de Paul Walker.<\/p>\n","protected":false},"author":3,"featured_media":31151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31152"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31151"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}