{"id":31210,"date":"2014-01-01T16:02:25","date_gmt":"2014-01-01T20:02:25","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/scarlett-johansson-entrena-como-un-hombre\/"},"modified":"2014-01-01T16:02:25","modified_gmt":"2014-01-01T20:02:25","slug":"scarlett-johansson-entrena-como-un-hombre","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/scarlett-johansson-entrena-como-un-hombre\/","title":{"rendered":"Scarlett Johansson entrena como un hombre"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-31209\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Scarlett-Johansson-2013-hd-wallpaper-1024x576.jpg\" width=\"600\" height=\"400\" alt=\"Scarlett-Johansson-2013-hd-wallpaper-1024x576\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Scarlett-Johansson-2013-hd-wallpaper-1024x576.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Scarlett-Johansson-2013-hd-wallpaper-1024x576-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Aunque la mayor\u00eda de las mujeres siempre se decanta por ejercicios de cardio en los gimnasios, la actriz Scarlett Johansson revela que su verdadera pasi\u00f3n es usar las m\u00e1quinas de musculaci\u00f3n como hacen los hombres.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>\u00abVoy al gimnasio dos veces por semana pero si estoy preparando un personaje a lo mejor me toca ir todos los d\u00edas. No me gusta hacer cardio, prefiero levantar pesas y realizar ejercicios espec\u00edficos para tonificar mis m\u00fasculos. Para ser sinceros, entreno como un chico\u00bb, cont\u00f3 la actriz a la edici\u00f3n francesa de la revista ELLE.<\/p>\n<p>Pero la femineidad de la atractiva int\u00e9rprete sale a la luz cuando se trata de cuidar su piel, ya que lleva a cabo una exhaustiva rutina de&nbsp;<label datatype=\"t\">belleza<\/label>&nbsp;y nunca se olvida de retirar el<label datatype=\"t\">maquillaje<\/label>&nbsp;de su rostro antes de irse a la cama.<\/p>\n<p>\u00abSiempre me han encantado las sombras de ojos. Cuando era m\u00e1s joven, recuerdo que mi<label datatype=\"t\">madre<\/label>&nbsp;se arreglaba mucho para salir y he heredado el mismo h\u00e1bito. Por la tarde, me pinto los labios de color rojo y acent\u00fao mi mirada. Me gusta tener una mirada expresiva por eso abuso de la m\u00e1scara de pesta\u00f1as\u00bb, afirm\u00f3 la artista.<\/p>\n<p>Adem\u00e1s, Scarlett revel\u00f3 uno de sus mejores trucos para tener una piel perfecta: utilizar el \u00e1cido zumo de lim\u00f3n como t\u00f3nico facial.<\/p>\n<p>\u00abUso el zumo de lim\u00f3n diluido con un poco de agua como t\u00f3nico para que mi piel resplandezca y para reducir las marcas. Es perfecto para los d\u00edas previos a una alfombra roja\u00bb, confes\u00f3.<\/p>\n<p>Bangshowbiz<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque la mayor\u00eda de las mujeres siempre se decanta por ejercicios de cardio en los gimnasios, la actriz Scarlett Johansson revela que su verdadera pasi\u00f3n es usar las m\u00e1quinas de musculaci\u00f3n como hacen los hombres.<\/p>\n","protected":false},"author":3,"featured_media":31209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31210"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31209"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}