{"id":31274,"date":"2014-01-05T16:20:37","date_gmt":"2014-01-05T20:20:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/tradicional-rosca-de-reyes\/"},"modified":"2014-01-05T16:20:37","modified_gmt":"2014-01-05T20:20:37","slug":"tradicional-rosca-de-reyes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tradicional-rosca-de-reyes\/","title":{"rendered":"Tradicional Rosca de Reyes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-31273\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_rosca_de_reyes.jpg\" width=\"600\" height=\"400\" alt=\"rosca_de_reyes\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_rosca_de_reyes.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_rosca_de_reyes-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Sorprende a tu&nbsp;<label datatype=\"t\">familia<\/label>&nbsp;con tus habilidades culinarias preparando esta tradicional y deliciosa rosca de reyes. \u00a1Les encantar\u00e1!<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p><strong>Ingredientes<\/strong><br \/>1 kg. de harina<br \/>300 gramos de az\u00facar<br \/>300 gramos de manteca Inca<br \/>200 ml. de agua<br \/>5 huevos<br \/>30 gramos de levadura fresca (o 10 gramos de levadura en polvo instant\u00e1nea)<br \/>1 cucharada de agua de azahar<br \/>1 cucharada de sal<br \/>Acitr\u00f3n y calabazate, cortados en cuadritos<br \/>100 gramos de nueces<br \/>1 naranja cristalizada, cortada en tiritas<br \/>Mu\u00f1equitos<\/p>\n<p><strong>Preparaci\u00f3n<\/strong><br \/>1. Haz una fuente con la harina y pon en el centro el az\u00facar, los huevos, el agua, el agua de azahar y la levadura. Incorpora bien los ingredientes y agrega sal. Mezcla bien. Amasa hasta que la pasta no se pegue a la mesa y quede el\u00e1stica.<br \/>2. Agrega poco a poco la manteca en cuadritos y contin\u00faa amasando hasta que la pasta quede transparente.<br \/>3. Deja reposar por 4 horas. Forma una tira redonda y alargada, de 5 a 8 cm. aproximadamente y dale forma a la rosca. Introduce los mu\u00f1equitos, col\u00f3cala sobre una charola para hornear, previamente engrasada.<br \/>4. Deja reposar hasta que la pasta duplique su tama\u00f1o.&nbsp;<label datatype=\"t\">Bate<\/label>&nbsp;un huevo y barniza la rosca. Dec\u00f3rala con las frutas cristalizadas.<br \/>5. Hornea durante 1 hora a 180\u00baC.<br \/>6. Sirve.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.comerico.com\/platillos\/postres\/674354\/tradicional-rosca-reyes\/\" title=\"http:\/\/www.comerico.com\/platillos\/postres\/674354\/tradicional-rosca-reyes\/\">http:\/\/www.comerico.com\/platillos\/postres\/674354\/tradicional-rosca-reyes\/<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sorprende a tu&nbsp;familia&nbsp;con tus habilidades culinarias preparando esta tradicional y deliciosa rosca de reyes. \u00a1Les encantar\u00e1!<\/p>\n","protected":false},"author":3,"featured_media":31273,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31274"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31273"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}