{"id":31280,"date":"2014-01-05T16:51:41","date_gmt":"2014-01-05T20:51:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/fallece-cantante-nelson-ned-el-pequeno-gigante-a-los-66-anos\/"},"modified":"2014-01-05T16:51:41","modified_gmt":"2014-01-05T20:51:41","slug":"fallece-cantante-nelson-ned-el-pequeno-gigante-a-los-66-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fallece-cantante-nelson-ned-el-pequeno-gigante-a-los-66-anos\/","title":{"rendered":"Fallece Cantante Nelson Ned (El Peque\u00f1o Gigante) a los 66 a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31279\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_nelson_ned.jpg\" width=\"225\" height=\"225\" alt=\"nelson_ned\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_nelson_ned.jpg 225w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_nelson_ned-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_nelson_ned-120x120.jpg 120w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>El bolerista brasile\u00f1o Nelson Ned falleci\u00f3 este domingo a los 66 a\u00f1os, luego de que fuera hospitalizado en Cot\u00eda, en la regi\u00f3n metropolitana de Sao Paulo, con un cuadro grave de neumon\u00eda. <!--more--> <\/p>\n<p>Destaca cables informativos que horas antes, la Asesor\u00eda de Prensa de la Secretar\u00eda de Salud del Estado de Sao Paulo comunic\u00f3 que el artista, quien viv\u00eda desde el \u00faltimo 24 de diciembre en una cl\u00ednica de reposo, hab\u00eda ingresado en el Hospital Regional de Cot\u00eda en \u201cestado grave\u201d, pero \u201cestable\u201d, con una \u201cinfecci\u00f3n respiratoria aguda\u201d, neumon\u00eda y problemas en la vejiga.<\/p>\n<p>Paz a los restos de tan grande cantante, que no obstante ser de corto tama\u00f1o fue un gigante ser humano y cantautor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El bolerista brasile\u00f1o Nelson Ned falleci\u00f3 este domingo a los 66 a\u00f1os, luego de que fuera hospitalizado en Cot\u00eda, en la regi\u00f3n metropolitana de Sao Paulo, con un cuadro grave de neumon\u00eda.<\/p>\n","protected":false},"author":3,"featured_media":31279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31280"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31279"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}