{"id":31460,"date":"2014-01-14T02:28:09","date_gmt":"2014-01-14T06:28:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cavada-y-michael-seran-los-presentadores-del-soberano\/"},"modified":"2014-01-14T02:28:09","modified_gmt":"2014-01-14T06:28:09","slug":"cavada-y-michael-seran-los-presentadores-del-soberano","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cavada-y-michael-seran-los-presentadores-del-soberano\/","title":{"rendered":"Cavada y Michael ser\u00e1n los presentadores del Soberano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31459\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Roberto-Cavada-y-Michael-Miguel-Holgun.jpg\" width=\"559\" height=\"363\" alt=\"Roberto-Cavada-y-Michael-Miguel-Holgun\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Roberto-Cavada-y-Michael-Miguel-Holgun.jpg 559w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Roberto-Cavada-y-Michael-Miguel-Holgun-300x194.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_Roberto-Cavada-y-Michael-Miguel-Holgun-400x260.jpg 400w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/>El \u201chombre noticia\u201d, Roberto Cavada y el popular presentador y animador de televisi\u00f3n Michael Miguel Holgu\u00edn han sido escogidos como los conductores de la edici\u00f3n correspondiente al 2014 de Premios Soberano. <!--more--> <\/p>\n<p>As\u00ed lo anunci\u00f3 Ren\u00e9 Brea, productor del evento que organizan la Asociaci\u00f3n de Cronistas de Arte (Acroarte) y Cervecer\u00eda Nacional Dominicana (CND).<\/p>\n<p>\u201cAs\u00ed como hemos puesto el o\u00eddo en el pueblo para lo musical, hemos puesto el otro para saber lo que est\u00e1 viendo la gente en la televisi\u00f3n. Estas encuestas arrojan a Roberto Cavada y a Michael Miguel Holgu\u00edn como los favoritos de los televidentes en sus \u00e1reas\u201d, explic\u00f3 Brea.<\/p>\n<p>\u201cApostamos a la combinaci\u00f3n de sus talentos y experiencias para una noche excepcional en la que ofreceremos al p\u00fablico lo que quiere\u201d, agreg\u00f3 el productor. El espect\u00e1culo de premiaci\u00f3n se celebrar\u00e1 el pr\u00f3ximo 18 de marzo y ser\u00e1 transmitido local e internacionalmente a trav\u00e9s de Telemicro, canal 5 y Telemicro Internacional, respectivamente. La producci\u00f3n del Soberano 2014 ser\u00e1 una entrega especial que recoger\u00e1 lo mejor del arte y el espect\u00e1culo a nivel nacional, un tributo al talento y al ingenio de nuestros artistas, una fiesta nacional, asegur\u00f3 el productor.<\/p>\n<p>Premios Soberano es la fiesta art\u00edstica m\u00e1s importante que se realiza en el pa\u00eds. Un evento que reconoce lo mejor en el arte y comunicaci\u00f3n. Una plataforma de exposici\u00f3n para el talento nacional. El actual presidente de Acroarte es Jos\u00e9 Antonio Aybar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u201chombre noticia\u201d, Roberto Cavada y el popular presentador y animador de televisi\u00f3n Michael Miguel Holgu\u00edn han sido escogidos como los conductores de la edici\u00f3n correspondiente al 2014 de Premios Soberano.<\/p>\n","protected":false},"author":3,"featured_media":31459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31460"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31459"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}