{"id":31467,"date":"2014-01-14T05:04:32","date_gmt":"2014-01-14T09:04:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/revelan-miguel-vargas-recibio-prestamo-privilegiado-de-rd585-mm-del-banreservas\/"},"modified":"2014-01-14T05:04:32","modified_gmt":"2014-01-14T09:04:32","slug":"revelan-miguel-vargas-recibio-prestamo-privilegiado-de-rd585-mm-del-banreservas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/revelan-miguel-vargas-recibio-prestamo-privilegiado-de-rd585-mm-del-banreservas\/","title":{"rendered":"Revelan Miguel Vargas recibi\u00f3 pr\u00e9stamo privilegiado de RD$585 MM del Banreservas"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-30053\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/10\/sosua_images_miguel_vargas_maldonado.jpg\" width=\"477\" height=\"444\" alt=\"miguel_vargas_maldonado\" \/>SANTO DOMINGO.<\/strong>&#8211; Dirigentes del Partido Revolucionario Dominicano (PRD) presentaron la documentaci\u00f3n de un pr\u00e9stamo de 585 millones de pesos (15 millones de d\u00f3lares) otorgados por el estatal Banco de Reservas a Miguel Vargas Maldonado en el mes de diciembre del 2011, \u00abaprobado en tiempo record\u00bb en violaci\u00f3n de la normativa prudencial de la entidad, con la opini\u00f3n negativa de la gerencia de valuaciones y con la advertencia de que la capacidad de pago de la empresa beneficiaria era insuficiente.<\/p>\n<p>  <!--more-->  <\/p>\n<p>De acuerdo a la denuncia presentada en rueda de prensa, el pr\u00e9stamo fue concedido a Vargas Maldonado en d\u00f3lares norteamericanos a nombre de la firma \u00abGeneral de Galer\u00edas Comerciales Mundo Mall, S.A.\u00bb, donde solo aparec\u00edan como accionistas el presidente del PRD, su hijo Miguel Paul Vargas Garc\u00eda y la secretaria Gisela Altagracia Patxot Cartacio.<\/p>\n<p>Vargas Maldonado es vicepresidente a nivel mundial de la Internacional Socialista, presidente del Comit\u00e9 para Am\u00e9rica Latina y El Caribe, y vicepresidente del Parlamento Latinoamericano, entidades que deber\u00e1n fijar una posici\u00f3n sobre el esc\u00e1ndalo en que est\u00e1 envuelto el pol\u00edtico dominicano, quien tambi\u00e9n prolong\u00f3 su mandato ilegalmente al frente del PRD, se indic\u00f3 en la conferencia de prensa.&nbsp;<\/p>\n<p>Al definir la transacci\u00f3n financiera como una operaci\u00f3n pol\u00edtica previamente aprobada por las altas instancias del poder pol\u00edtico en el Estado Dominicano, los denunciantes afirmaron que la gruesa suma de dinero fue entregada a Vargas Maldonado como una compensaci\u00f3n por los trabajos pol\u00edticos que hizo a favor del PLD antes, durante y despu\u00e9s de las elecciones del 2012.<\/p>\n<p>Resaltaron que el acuerdo se hizo cinco meses antes de las elecciones, coincidiendo con una declaraci\u00f3n p\u00fablica de Vargas Maldonado de que no se montar\u00eda en la patana del candidato presidencial de su partido, Hip\u00f3lito Mej\u00eda.<\/p>\n<p>Los detalles de la transacci\u00f3n financiera fueron ofrecidos por exvicepresidenta de la Rep\u00fablica, Milagros Ortiz Bosch y l reputado m\u00e9dico Jes\u00fas Feris Iglesias, acompa\u00f1ados de reconocidos dirigentes del PRD que tambi\u00e9n suscribieron el documento de la denuncia.<br \/><strong><br \/>Responsables de la denuncia<\/strong><\/p>\n<p>Entre los firmantes figuran el excanciller Hugo Tolentino Dipp, la exsecretaria de Educaci\u00f3n, Ivelisse Prats De P\u00e9rez, el pasado presidente del PRD Ram\u00f3n Alburquerque, el vicepresidente, Roberto Fulcar, el economista Arturo Mart\u00ednez Moya, y los dirigentes Eligio J\u00e1quez, Rafael -Fafa- Taveras, Tony Pe\u00f1a Guaba, Nora Nivar, Bonaparte Gautreaux Pi\u00f1eiro, Rafael Santos, Eugenio Cede\u00f1o, Betzaida Santana, Julio Cordero, Isidro Torres, Jos\u00e9 Garc\u00eda Ram\u00edrez, Sof\u00eda Leonor S\u00e1nchez Baret y Antonio Almonte.<\/p>\n<p>La doctora Ortiz Bosch explic\u00f3 que seg\u00fan los documentos relacionados con la operaci\u00f3n, el 8 de diciembre del 2011, el Banco de Reservas, \u00abpese al cuestionamiento del Comit\u00e9 de Evaluaciones de Cr\u00e9dito, aprob\u00f3 una facilidad crediticia al vapor por US$15 millones de d\u00f3lares, equivalente a RD$ 585,000.000.00 millones de pesos, a favor de&nbsp; Vargas Maldonado, facilidad aprobada el 13 de diciembre del 2011 y desembolsada en el primer trimestre del a\u00f1o 2012, en pleno proceso electoral\u00bb<\/p>\n<p><strong>Ni un solo block<\/strong><\/p>\n<p>Indic\u00f3 que aunque la solicitud fue justificada como una operaci\u00f3n empresarial con el supuesto prop\u00f3sito de desarrollar un proyecto inmobiliario en un solar ubicado entre las avenidas Kennedy y San Mart\u00edn, pr\u00f3ximo a la Avenida M\u00e1ximo G\u00f3mez, a dos a\u00f1os de recibido el pr\u00e9stamo, en el lugar no se ha colocado en solo block y el inmueble aparece cubierto de maleza. \u00abSi no lo invirti\u00f3 en el proyecto inmobiliario, como establec\u00eda el acuerdo con el Banco de Reservas, donde est\u00e1 el dinero?, se pregunt\u00f3 Ortiz Bosch.<\/p>\n<p>\u00abLa evaluaci\u00f3n crediticia de Miguel Vargas, hecha por la Gerencia de An\u00e1lisis de Cr\u00e9dito, fue calificada en el nivel de riesgo D (cliente de dif\u00edcil cobro) que seg\u00fan define el Reglamento de Evaluaci\u00f3n de Activos (REA), normativa aprobada por la Junta Monetaria en su resoluci\u00f3n 29\/11\/04, hac\u00eda inaplicable este pr\u00e9stamo\u00bb, apunt\u00f3 en su exposici\u00f3n la pasada vicepresidenta de la Rep\u00fablica.<\/p>\n<p>\u00abEl Banco de Reservas viol\u00f3 la normativa prudencial que dispone que los pr\u00e9stamos en d\u00f3lares se conceden solo a empresas que generan divisas, que exportan bienes o servicios de manera comprobable y cuantificable, identificando, adem\u00e1s, el pa\u00eds de destino de los bienes o servicios a exportar. Nada de eso se hizo; se otorg\u00f3 el pr\u00e9stamo a una empresa que no genera divisas, sin la seguridad de que dispondr\u00e1 del flujo de efectivo en moneda extranjera para devolver el principal y los intereses\u00bb, indicaron los dirigentes perrede\u00edstas mediante un documento le\u00eddo por la ex vicepresidenta de la Rep\u00fablica, Milagros Ortiz Bosch.<\/p>\n<p><strong>Los rumores confirmados<br \/><\/strong><br \/>El doctor Feris Iglesias, m\u00e9dico y dirigente del PRD resalt\u00f3 en su intervenci\u00f3n que durante el proceso electoral del 2012 y posteriormente \u00abtanto en el Partido como en amplios sectores de la sociedad, exist\u00edan razones para cuestionar la inexplicable postura de quien en ese momento ocupaba la presidencia de la organizaci\u00f3n. Los rumores para hacer cre\u00edbles necesitan de pruebas y en el caso del pr\u00e9stamo del Banreservas, era indispensable encontrar la documentaci\u00f3n oficial de una sospechosa transacci\u00f3n entregada en manos del dirigente de mayor jerarqu\u00eda institucional en medio de la contienda electoral\u00bb.<\/p>\n<p>\u00abEn un pa\u00eds de reconocida debilidad institucional resulta anormal que un pr\u00e9stamo de alt\u00edsimo monto se asigne con tanta rapidez. Sobre todo, a una persona que el reporte desfavorable de dos profesionales del Banco de Reservas, como Vianelkys Bencosme y Miledys Taveras, establec\u00eda con claridad la improcedencia del pr\u00e9stamo.<\/p>\n<p><strong>Los documentos del Banco&nbsp;<\/strong><\/p>\n<p>Los documentos presentados en la rueda de prensa sobre la operaci\u00f3n financiera entre el presidente del PRD y el banco estatal, incluyen copias de un informe t\u00e9cnico con los datos generales del cliente; un memorando dirigido al Consejo de Directores a la firma del administrador del Banco de Reservas, Vicente Bengoa; la resoluci\u00f3n de fecha 13 de diciembre del 2011 mediante la cual se aprob\u00f3 un cr\u00e9dito a t\u00e9rmino por US$15,000,000.00, equivalente a RD$585,000,000.00, calculado a la tasa de cambio de 39 pesos por cada d\u00f3lar, y el contrato de cr\u00e9dito suscrito entre el Banco de Reservas y el ingeniero Miguel Vargas.&nbsp;<\/p>\n<p>De acuerdo a la documentaci\u00f3n, el pr\u00e9stamo fue aprobado en un tiempo record de 11 d\u00edas \u00aba pesar de que la empresa sombrilla que us\u00f3 Miguel Vargas ten\u00eda clasificaci\u00f3n \u00abD\u00bb, que la hac\u00eda inelegible para un financiamiento, adem\u00e1s de que las garant\u00edas ofertadas fueron rechazadas previamente por la Gerencia de Valuaciones del Banco porque las mensuras no estaban actualizadas como requiere la normativa de la Superintendencia de Bancos y las garant\u00edas no eran polivalentes o no serv\u00edan para varios prop\u00f3sitos, como lo exige la regla bancaria.<\/p>\n<p>\u00abLos t\u00e9cnicos del Banco de Reservas reportaron al Consejo de Directores que la empresa de Vargas Maldonado presentaba p\u00e9rdidas en los primeros a\u00f1os, que la capacidad de pago era insuficiente, que influ\u00eda para la clasificaci\u00f3n de riego \u00abD\u00bb, que no hab\u00eda reportado ingresos durante los a\u00f1os 2009, 2010, y que las proyecciones de ingresos netos para el per\u00edodo 2012-2018 se sustentaban en la venta de apartamentos para lo que no exist\u00edan informaciones concretas de planos, permisos, presupuestos y cronogramas\u00bb, apunta la declaraci\u00f3n de los dirigentes del PRD.<\/p>\n<p><strong>Miguel Vargas se referir\u00e1 \u00aboportunamente\u00bb a la denuncia<\/strong><\/p>\n<p>El presidente del Partido Revolucionario Dominicano (PRD), Miguel Vargas, &nbsp;respondi\u00f3 esta tarde que se referir\u00e1 \u00aboportunamente\u00bb a las declaraciones \u00abmalintencionadas, aviesas, distorsionadas\u00bb, ofrecidas por dirigentes perrede\u00edstas del sector de Hip\u00f3lito Mej\u00eda.<\/p>\n<p>Vargas acus\u00f3 a los denunciantes de caracterizarse de mantener siempre \u00abun comportamiento irrespetuoso y perturbador de la marcha institucional de nuestro partido\u00bb.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.&#8211; Dirigentes del Partido Revolucionario Dominicano (PRD) presentaron la documentaci\u00f3n de un pr\u00e9stamo de 585 millones de pesos (15 millones de d\u00f3lares) otorgados por el estatal Banco de Reservas a Miguel Vargas Maldonado en el mes de diciembre del 2011, \u00abaprobado en tiempo record\u00bb en violaci\u00f3n de la normativa prudencial de la entidad, con la opini\u00f3n negativa de la gerencia de valuaciones y con la advertencia de que la capacidad de pago de la empresa beneficiaria era insuficiente.<\/p>\n","protected":false},"author":3,"featured_media":30053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31467"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30053"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}