{"id":31531,"date":"2014-01-16T05:23:45","date_gmt":"2014-01-16T09:23:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/vargas-confirma-tomo-prestamo-al-banco-de-reservas-pero-niega-haya-sido-irregular\/"},"modified":"2014-01-16T05:23:45","modified_gmt":"2014-01-16T09:23:45","slug":"vargas-confirma-tomo-prestamo-al-banco-de-reservas-pero-niega-haya-sido-irregular","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vargas-confirma-tomo-prestamo-al-banco-de-reservas-pero-niega-haya-sido-irregular\/","title":{"rendered":"Vargas confirma tom\u00f3 pr\u00e9stamo al Banco de Reservas pero niega haya sido irregular"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31530\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_miguel_vargas_maldonado2013.jpg\" width=\"259\" height=\"194\" alt=\"miguel_vargas_maldonado2013\" \/>DICE HA PAGADO 1.7 MILLONES DE DOLARES DE INTERESES.&nbsp;<span style=\"font-size: 11px;\">El presidente del Partido Revolucionario Dominicano (PRD)&nbsp; neg\u00f3&nbsp; esta tarde &nbsp;que fuera irregular el pr\u00e9stamo &nbsp;por unos 15 millones de d\u00f3lares que tom\u00f3 con el Banco de Reservas.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p>Miguel Vargas&nbsp; Maldonado dijo que hasta la fecha, su empresa,&nbsp; General de Galer\u00edas Comerciales Mundo Mall, S.A., ha pagado&nbsp; 1.7 millones de d\u00f3lares de intereses, a una tasa fija de 9% en d\u00f3lares.<\/p>\n<\/p>\n<p>\u201cSe trata de una declaraci\u00f3n aviesa, malintencionada y divisionista\u201d, la que hizo el pasado lunes, el sector que en los \u00faltimos a\u00f1os se ha caracterizado por mantener un comportamiento irrespetuoso y perturbador de la marcha de la institucionalidad de nuestro&nbsp; partido\u201d, dijo Vargas, durante una rueda de prensa en el Hotel Embajador.<\/p>\n<p>Agreg\u00f3 que esa denuncia tiene motivaciones estrictamente pol\u00edticas.<\/p>\n<p>Aclar\u00f3 que el&nbsp; proceso&nbsp; para el &nbsp;pr\u00e9stamo dur\u00f3 siete meses,&nbsp; de julio 2011 a febrero del 2012.<\/p>\n<p>Dijo que su empresa tiene un capital suscrito y pagado&nbsp; superior a los 600 millones de pesos y activos por m\u00e1s de 4&nbsp; mil millones de pesos.<\/p>\n<p>Mostr\u00f3 adem\u00e1s copia del un pr\u00e9stamo con la prestigiosa firma financiera internacional JP Morgan, el 19 de mayo del 2011, por 15 millones d\u00f3lares, otorgado en un tiempo de sesenta d\u00edas a una tasa de 7.3% inter\u00e9s anual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DICE HA PAGADO 1.7 MILLONES DE DOLARES DE INTERESES.&nbsp;El presidente del Partido Revolucionario Dominicano (PRD)&nbsp; neg\u00f3&nbsp; esta tarde &nbsp;que fuera irregular el pr\u00e9stamo &nbsp;por unos 15 millones de d\u00f3lares que tom\u00f3 con el Banco de Reservas.<\/p>\n","protected":false},"author":3,"featured_media":31530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31531"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31530"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}