{"id":31682,"date":"2014-01-20T16:00:00","date_gmt":"2014-01-20T20:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-blackphone-el-smartphone-que-quiere-ser-la-pesadilla-de-los-espias\/"},"modified":"2014-01-20T16:00:00","modified_gmt":"2014-01-20T20:00:00","slug":"el-blackphone-el-smartphone-que-quiere-ser-la-pesadilla-de-los-espias","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-blackphone-el-smartphone-que-quiere-ser-la-pesadilla-de-los-espias\/","title":{"rendered":"El Blackphone, el smartphone que quiere ser la pesadilla de los esp\u00edas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-31681\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_05717601157ca2bbb0d9fc67e2daa8a11a201cbf.jpg\" width=\"600\" height=\"400\" alt=\"05717601157ca2bbb0d9fc67e2daa8a11a201cbf\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_05717601157ca2bbb0d9fc67e2daa8a11a201cbf.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_05717601157ca2bbb0d9fc67e2daa8a11a201cbf-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Es negro, se parece a un tel\u00e9fono inteligente cualquiera, pero el Blackphone tiene una cosa m\u00e1s: sus creadores prometen a sus propietarios que tendr\u00e1n comunicaciones seguras, al amparo de los \u00abgrandes o\u00eddos\u00bb gubernamentales o de los piratas inform\u00e1ticos.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>En pleno debate sobre la extensi\u00f3n de la vigilancia de los servicios de inteligencia estadounidenses, el lanzamiento del Blackphone, concebido por la firma estadounidense Silent Circle y la espa\u00f1ola Geeksphone, no se habr\u00eda beneficiado de una mejor publicidad.<\/p>\n<p>Pero el jefe de Silent Circle, Mike Janke, dice no haber buscado esa oportuna publicidad. Su<label datatype=\"t\">empresa<\/label>, explic\u00f3 a la AFP, trabajaba sobre ese&nbsp;<label datatype=\"t\">aparato<\/label>&nbsp;desde mucho antes que el exconsultor de la agencia de inteligencia NSA Edward Snowden comenzar\u00e1 a divulgar documentos secretos acerca del espionaje estadounidense.<\/p>\n<p>\u00abHicimos esto porque el problema de las comunicaciones seguras no estaba regulado\u00bb, se\u00f1al\u00f3 este exmiembro del cuerpo de \u00e9lite de la marina estadounidense Navy Seal, quien se uni\u00f3 a compa\u00f1eros de armas y expertos en criptograf\u00eda de Silicon Valley para crear la empresa Silent Circle.<\/p>\n<p>\u00abOfrecemos a los&nbsp;<label datatype=\"t\">usuarios<\/label>&nbsp;la posibilidad de comunicarse de manera encriptada a trav\u00e9s de videos, textos o de llamadas orales sobre redes compatibles IP\u00bb, destac\u00f3 Janke.<\/p>\n<p>Su empresa no se estrena con el Blackphone. En el pasado colabor\u00f3 con multinacionales y hasta con el gobierno de T\u00edbet en el exilio.<\/p>\n<p>Las habilidades de Silent Circle han que hecho que \u00abcasi todos los grandes fabricantes de smartphones se volviesen hacia nosotros\u00bb para trabajar en un aparato seguro.<\/p>\n<p>Finalmente, la elecci\u00f3n de la compa\u00f1\u00eda se inclin\u00f3 hacia la peque\u00f1a sociedad espa\u00f1ola Geeksphone que recientemente lanz\u00f3 un tel\u00e9fono inteligente que funciona con el sistema de navegaci\u00f3n Firefox.<\/p>\n<p>Silent Circle, detall\u00f3 Janke, ha dotado a su Blackphone de PrivatOS, una versi\u00f3n modificada de Android, el sistema desarrollado por Google.<\/p>\n<p>\u00abGoogle no sabe qui\u00e9n es usted\u00bb<\/p>\n<p>El nuevo tel\u00e9fono ser\u00e1 develado el 24 de febrero en el Mobile World Congress, el gran sal\u00f3n de telefon\u00eda m\u00f3vil que se celebra cada a\u00f1o en Barcelona.<\/p>\n<p>Su precio sigue siendo un misterio, pero Janke asegur\u00f3 que el Blackphone se vender\u00e1 desbloqueado por una cifra inferior al valor del iPhone 5S o del Galaxy S4 de Samsung.<\/p>\n<p>El aparato ofrece toda la gama de servicios de un tel\u00e9fono inteligente, pero con una gran diferecia: \u00abUsted puede ir a Google y navegar en Internet, pero Google no sabe qui\u00e9n es usted\u00bb, destac\u00f3 Janke.<\/p>\n<p>El centro de almacenamiento de datos, cuya capacidad es \u00abm\u00ednima\u00bb, est\u00e1 situado en Suiza, explic\u00f3 este emprendedor.<\/p>\n<p>\u00abTodo lo que sabremos sobre usted es el nombre que nos da y un n\u00famero de tel\u00e9fono de 10 d\u00edgitos\u00bb, indic\u00f3.<\/p>\n<p>De esa manera, si llega a Suiza una orden judicial, la compa\u00f1\u00eda solo podr\u00eda facilitar un nombre, el del propietario del tel\u00e9fono.<\/p>\n<p>Janke estima que se vender\u00e1n \u00abvarios millones\u00bb de Blackphones al a\u00f1o siguiente de su lanzamiento.<\/p>\n<p>El inter\u00e9s es mundial \u00abporque la NSA no est\u00e1 sola, 72 pa\u00edses cuentan con medios similares a los de la NSA. Nos esp\u00edan y se esp\u00edan entre ellos. Aunque viva en Kenia, en Alemania o en Argentina, en todas partes hay las mismas amenazas\u00bb, advirti\u00f3.<\/p>\n<p>\u00abEstamos seguros de que la encriptaci\u00f3n funciona\u00bb, insisti\u00f3. Seg\u00fan \u00e9l, las agencias de inteligencia no se cansan en intentar forzar las comunicaciones encriptadas -una t\u00e9cnica que demanda mucho tiempo- y prefieren insertar virus inform\u00e1ticos en los correos, capaces luego de interceptar los mensajes.<\/p>\n<p>\u00abEl tel\u00e9fono 100% seguro no existe\u00bb, matiz\u00f3 Janke. \u00abNada puede protegerle contra las artima\u00f1as. Pero este tel\u00e9fono ha hecho much\u00edsimo para proteger su vida privada\u00bb, concluy\u00f3. AFP<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es negro, se parece a un tel\u00e9fono inteligente cualquiera, pero el Blackphone tiene una cosa m\u00e1s: sus creadores prometen a sus propietarios que tendr\u00e1n comunicaciones seguras, al amparo de los \u00abgrandes o\u00eddos\u00bb gubernamentales o de los piratas inform\u00e1ticos.<\/p>\n","protected":false},"author":3,"featured_media":31681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31682"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31681"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}