{"id":31718,"date":"2014-01-22T04:00:00","date_gmt":"2014-01-22T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-7-pecados-capitales-de-la-belleza\/"},"modified":"2014-01-22T04:00:00","modified_gmt":"2014-01-22T08:00:00","slug":"los-7-pecados-capitales-de-la-belleza","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-7-pecados-capitales-de-la-belleza\/","title":{"rendered":"Los 7 \u201cpecados capitales\u201d de la belleza"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-31717\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_caraFGJHGSG.jpg\" width=\"600\" height=\"400\" alt=\"caraFGJHGSG\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_caraFGJHGSG.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_caraFGJHGSG-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Una encuesta realizada por el sitio Escentual.com y recogida por Daily Mail, eligi\u00f3 los 7 pecados capitales de la&nbsp;<label datatype=\"t\">belleza<\/label>, resultando ganadoras las cejas excesivamente pintadas.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Sin embargo, esta \u00faltima&nbsp;<label datatype=\"t\">tendencia<\/label>&nbsp;es recurrente en celebridades como la&nbsp;<label datatype=\"t\">modelo<\/label>&nbsp;Cara Delevingne.<\/p>\n<p>El estudio aplicado a 1.000 personas, tambi\u00e9n arroj\u00f3 que el 78% de las mujeres juzga negativamente a una mujer mal maquillada e incluso un 22% podr\u00eda incluso negarse a socializar con chicas as\u00ed.<\/p>\n<p>Por otro lado, este sondeo mostr\u00f3 que las f\u00e9minas son casi cinco veces m\u00e1s propensas que los hombres a juzgar a una cong\u00e9nere por su apariencia.<\/p>\n<p>A continuaci\u00f3n te mostramos cu\u00e1les son los peores \u201ccr\u00edmenes\u201d de belleza, seg\u00fan esta encuesta.<\/p>\n<p>1. Cejas excesivamente pintadas (21,2%)<\/p>\n<p>2. Marcas de base (20,4%)<\/p>\n<p>3. Bronceado falso disparejo (16,4%)<\/p>\n<p>4. Labios con corrector o base (9.3%)<\/p>\n<p>5. Cejas demasiado depiladas (8,7%)<\/p>\n<p>6. Pesta\u00f1as pegoteadas (6,7%)<\/p>\n<p>7. Polvo apelmazado en la cara (4,5%)<\/p>\n<p>Emma Leslie, de Escentual.com, dijo que muchos de estos \u201cpecados\u201d de belleza pueden ser f\u00e1cilmente evitados, poniendo un poco m\u00e1s de atenci\u00f3n al momento de maquillarse.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.biobiochile.cl\/2014\/01\/21\/los-7-pecados-capitales-de-la-belleza.shtml\" target=\"_blank\">BioBioChile<\/a>&nbsp;En la foto Cara Delevingne\/EFE<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una encuesta realizada por el sitio Escentual.com y recogida por Daily Mail, eligi\u00f3 los 7 pecados capitales de la&nbsp;belleza, resultando ganadoras las cejas excesivamente pintadas.<\/p>\n","protected":false},"author":3,"featured_media":31717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-31718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31718"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31717"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}