{"id":31762,"date":"2014-01-24T14:21:54","date_gmt":"2014-01-24T18:21:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/escogido-vence-licey-y-gana-primero-final\/"},"modified":"2014-01-24T14:21:54","modified_gmt":"2014-01-24T18:21:54","slug":"escogido-vence-licey-y-gana-primero-final","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/escogido-vence-licey-y-gana-primero-final\/","title":{"rendered":"Escogido vence Licey y gana primero Final"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31761\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_escogido_celebra.jpg\" width=\"960\" height=\"637\" alt=\"escogido_celebra\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_escogido_celebra.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_escogido_celebra-300x199.jpg 300w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/>SANTO DOMINGO.- Los Leones del Escogido derrotaron a los Tigres del Licey con marcador de 6 carreras por 5 para obtener su primera victoria de la Serie Final del Torneo de Beisbol Profesional Dominicano.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La victoria fue para Evan MacLane (1-0) al trabajar seis entradas y un tercio, tolerando ocho hits y cuatro carreras, sin boletos y con cuatro ponches.<\/p>\n<p>A MacLane le siguieron Jorge de Le\u00f3n, Ram\u00f3n Garc\u00eda, Pedro Feliciano, Armando Rodr\u00edguez, Claudio Galv\u00e1 y Jos\u00e9 Valdez. Valdez tir\u00f3 una entrada y dos tercios para el salvamento.<\/p>\n<p>La derrota fue para Francisley Bueno (0-1) con dos entradas y dos tercios de cuatro hits y cinco carreras, dos de ellas limpias.&nbsp;<\/p>\n<p>Tambi\u00e9n dio un boleto y ponch\u00f3 uno.A Bueno le siguieron Juan Sosa, Pedro Figueroa, Greg Aquino, Willy Collazo, Francisco Rosario, Juan Cede\u00f1o, Warner Madrigal y Carlos M\u00e1rmol.<\/p>\n<p>La serie se pone 3-1 a favor de los Tigres, la cual contin\u00faa este viernes en el Estadio Quisqueya a partir de las 7:30 de la noche.<\/p>\n<p><b>LAS CARRERAS<\/b><\/p>\n<p>Los Leones del Escogido hicieron tres carreras en el primer episodio, fruto de dos errores del torpedero Anderson Hern\u00e1ndez,, un balk de Esmil Rogers y un sencillo productor de Jes\u00fas Feliciano Leones 3 Licey 0<\/p>\n<p>Juan Francisco dispara cuadrangular en el segundo inning. &nbsp;Leones 3 Licey 1<\/p>\n<p>En la tercera entrada Carlos Santana conecta jonr\u00f3n con un compa\u00f1ero a bordo. Leones 5 Licey 1<\/p>\n<p>En la sexta, Eury P\u00e9rez peg\u00f3 un sencillo remolcador de Erick Almonte. Leones 6 Licey 1<\/p>\n<p>En la parte baja del sexto inning el Licey anota una carrera. Leones 6 Licey 2<\/p>\n<p>Termina el s\u00e9ptimo para el Escogido sin carreras. Leones 6 Licey 2<\/p>\n<p>Baja de la s\u00e9ptima entrada sencillo al centro. Licey pone corredor en primera con un out. Otro hit azul pone corredores en tercera y segunda con un out. Nuevo lanzador por el Escogido. Ram\u00f3n Garc\u00eda con dos corredores en base. Engels Beltr\u00e9 pega sencillo y empuja dos. Leones 6 Licey 4<\/p>\n<p>Iniciando el octavo el Licey nuevo pitcher Francisco Rosario. Batea el Escogido. Miguel Olivo pega doble al central. Golpeado Luis P\u00e9rez y hay dos corredores en base con un out. Nuevo lanzador por el Licey Juan Cede\u00f1o, quien realiza el segundo out. Sin embargo, el manager Jos\u00e9 Offerman llama otro pitcher. Se trata de Warner Madrigal. Se va el inning. Leones 6 Licey 4<\/p>\n<p>Juan Francisco inicia el octavo episodio por los Tigres con sencillo. Armando Rodr\u00edguez es el nuevo lanzador por el Escogido. F\u00e9lix P\u00e9rez pega hit y Licey tiene corredores en primera y segunda base con un out. Otro lanzador por el Escogido y lo es Jos\u00e9 Valdez. Se escapa la pelota y los corredores avanzan a segunda y tercera. Anderson Hern\u00e1ndez batea fly de sacrificio. Leones 6 Licey 5<\/p>\n<p>En la parte alta del noveno el nuevo lanzador azul es Carlos M\u00e1rmol. Fly de Carlos Santana primer out. Se poncha Melky Mesa para el segundo out. Jes\u00fas Feliciano base bolas. Julio Lugo pega hit. Escogido tiene dos corredores en base con dos outs. Abraham Almonte es ponchado. Leones 6 Licey 5<\/p>\n<p>Cierre del noveno se poncha Ren\u00e9 Rivera para el primer out. Emilio Bonifacio falla al jard\u00edn central para el segundo out. Engels Beltr\u00e9 falla. Final del partido. Leones 6 Licey 5.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Los Leones del Escogido derrotaron a los Tigres del Licey con marcador de 6 carreras por 5 para obtener su primera victoria de la Serie Final del Torneo de Beisbol Profesional Dominicano.<\/p>\n","protected":false},"author":3,"featured_media":31761,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-31762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31762"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31761"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}