{"id":31842,"date":"2014-01-27T23:22:44","date_gmt":"2014-01-28T03:22:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/hallan-en-suecia-una-atlantida-de-la-edad-de-piedra\/"},"modified":"2014-01-27T23:22:44","modified_gmt":"2014-01-28T03:22:44","slug":"hallan-en-suecia-una-atlantida-de-la-edad-de-piedra","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hallan-en-suecia-una-atlantida-de-la-edad-de-piedra\/","title":{"rendered":"Hallan en Suecia una &#8216;Atl\u00e1ntida&#8217; de la Edad de Piedra"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31841\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_atlantida_de_la_era_de_piedra.jpg\" width=\"630\" height=\"354\" alt=\"atlantida_de_la_era_de_piedra\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_atlantida_de_la_era_de_piedra.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_atlantida_de_la_era_de_piedra-300x168.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/>Un grupo de buceadores suecos ha descubierto artefactos de la Edad de Piedra \u00ab\u00fanicos en su especie\u00bb que pertenecieron a n\u00f3madas de hace 11.000 a\u00f1os, lo que ha llevado a algunos a bautizar el descubrimiento como &#8216;la Atl\u00e1ntida sueca&#8217;.<\/p>\n<p>  <!--more-->  <\/p>\n<div id=\"article_text\">Los artefactos fueron descubiertos por el profesor Bj\u00f6rn Nilsson, de la Universidad Soderton, y por un equipo de la Universidad de Lund durante un buceo arqueol\u00f3gico en Hano, frente a la costa del condado de Escania, en Suecia, seg\u00fan informa \u2018The Local&#8217;. <\/p>\n<p>\u00abLo que tenemos aqu\u00ed es tal vez uno de los&nbsp;asentamientos m\u00e1s antiguos&nbsp;de los primeros sitios permanentes en Escania y en Suecia\u00bb, expres\u00f3 el l\u00edder del&nbsp;proyecto Bj\u00f6rn Nilsson.<\/p>\n<p>Enterrados a una profundidad de 16 metros, los investigadores han descubierto madera, herramientas de s\u00edlex, cuernos de animales y cuerdas.<\/p>\n<p>Entre los objetos hallados m\u00e1s destacados se encuentra un arp\u00f3n obtenido a partir de hueso de animal y los huesos de un animal primitivo llamado uro.&nbsp;<\/p>\n<p>El buen estado de conservaci\u00f3n de muchos objetos se explica debido a que el lugar de buceo es rico en un sedimento llamado \u2018gyttja\u2019.<\/p>\n<\/p><\/div>\n<p>[<a href=\"%20http:\/actualidad.rt.com\/ciencias\/view\/118239-buzos-suecos-hallan-atlantida-edad-piedra?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=ciencias\">Fuente<\/a>]<a href=\"http:\/\/actualidad.rt.com\/ciencias\/view\/118239-buzos-suecos-hallan-atlantida-edad-piedra?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=ciencias\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de buceadores suecos ha descubierto artefactos de la Edad de Piedra \u00ab\u00fanicos en su especie\u00bb que pertenecieron a n\u00f3madas de hace 11.000 a\u00f1os, lo que ha llevado a algunos a bautizar el descubrimiento como &#8216;la Atl\u00e1ntida sueca&#8217;.<\/p>\n","protected":false},"author":3,"featured_media":31841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-31842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=31842"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/31842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31841"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=31842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=31842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=31842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}