{"id":32146,"date":"2014-02-06T09:21:19","date_gmt":"2014-02-06T13:21:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-frio-no-da-tregua-a-los-dominicanos-y-otras-etnias-en-nueva-york\/"},"modified":"2014-02-06T09:21:19","modified_gmt":"2014-02-06T13:21:19","slug":"el-frio-no-da-tregua-a-los-dominicanos-y-otras-etnias-en-nueva-york","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-frio-no-da-tregua-a-los-dominicanos-y-otras-etnias-en-nueva-york\/","title":{"rendered":"El fr\u00edo no da tregua a los dominicanos y otras etnias en Nueva York"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32145\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_ny_y_el_frio.jpg\" width=\"760\" height=\"473\" alt=\"ny_y_el_frio\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_ny_y_el_frio.jpg 760w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_ny_y_el_frio-300x186.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_ny_y_el_frio-400x250.jpg 400w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/>Nueva York, 5 de febrero 2014.- La ciudad de Nueva York, donde reside aproximadamente un mill\u00f3n de dominicanos, a\u00fan no ha podido quitarse de encima el manto de unas 10 pulgadas de nieve que calleron el pasado lunes y hoy mi\u00e9rcoles la urbe amaneci\u00f3 fea, t\u00e9trica y sus calles y avenidas muy peligrosas, convirti\u00e9ndose en trampas resbaladizas y ni hablar de las aceras, debido a la segunda tormenta invernal que la azota en esta semana, con hielo, nieve y lluvia.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los condados de Manhattan, El Bronx, Brooklyn, Queens y Staten Island se mantienen cubiertos de nieve, al igual que toda la regi\u00f3n que componen otros estados de la Union Americana. Cientos de familias dominicanas residentes en la Gran Manzana est\u00e1n sufriendo temperaturas congelantes en el interior de los apartamentos donde residen porque los due\u00f1os de los edificios no dan calefaccion.<\/p>\n<p>Es una situaci\u00f3n com\u00fan para miles de neoyorquinos y seg\u00fan datos oficiales del Departamento de Vivienda, el martes de la semana pasada hubo 2,175 quejas por falta de calefacci\u00f3n.<\/p>\n<p>El n\u00famero de quejas en la actual \u201ctemporada de calefacci\u00f3n\u201d (del 1\u00ba de octubre al 31 de mayo) es de 137,846, y ya supera al total de la temporada pasada (124,076). Los caseros est\u00e1n obligados a proveer calefaccion entre los meses del 1 de octubre al 31 de mayo, entre 6 de la ma\u00f1ana y 10 de la noche, si la temperatura est\u00e9 en menos de 55 grados Fahrenheit (12 grados C. Durante la noche, entre las 10 de la noche y las 6 de la ma\u00f1ana debe ser por lo menos de 55 grados F. Se anticipa que para el pr\u00f3ximo domingo otra tormenta azotar\u00e1 el \u00e1rea, con mayor intensidad.<\/p>\n<p>Las temperaturas m\u00e1ximas estar\u00e1n hoy a 31 grados Fahrenheit y las y las minimas a 24, el viento a 28 kil\u00f3metros por horas, nublado oscuro totalmente y la visibilidad es de 3 kil\u00f3metros. Enviado por <a href=\"mailto:prensaNYaRD@yahoo.com\">prensaNYaRD@yahoo.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York, 5 de febrero 2014.- La ciudad de Nueva York, donde reside aproximadamente un mill\u00f3n de dominicanos, a\u00fan no ha podido quitarse de encima el manto de unas 10 pulgadas de nieve que calleron el pasado lunes y hoy mi\u00e9rcoles la urbe amaneci\u00f3 fea, t\u00e9trica y sus calles y avenidas muy peligrosas, convirti\u00e9ndose en trampas resbaladizas y ni hablar de las aceras, debido a la segunda tormenta invernal que la azota en esta semana, con hielo, nieve y lluvia.<\/p>\n","protected":false},"author":3,"featured_media":32145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-32146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32146"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32145"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}