{"id":32502,"date":"2014-02-16T17:26:32","date_gmt":"2014-02-16T21:26:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cosas-que-no-pasaran-si-facebook-no-existiera\/"},"modified":"2014-02-16T17:26:32","modified_gmt":"2014-02-16T21:26:32","slug":"cosas-que-no-pasaran-si-facebook-no-existiera","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cosas-que-no-pasaran-si-facebook-no-existiera\/","title":{"rendered":"Cosas que no pasaran si Facebook no existiera"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-25709\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Facebook-banner54245.jpeg\" width=\"650\" height=\"317\" alt=\"Facebook-banner54245\" \/>Cosas que no pasaran si Facebook no existiera.&nbsp;Este mes la red social m\u00e1s popular del mundo,&nbsp;<label>Facebook<\/label>, cumpli\u00f3 10 a\u00f1os conectando y deleitando a sus millones de&nbsp;<label>usuarios<\/label>. Y para celebrarlo, algunos medios reflexionaron en torno a la forma en que esta plataforma ha cambiado la&nbsp;<label>vida<\/label>&nbsp;de quienes la utilizan. <!--more-->  <\/p>\n<p>En este contexto, te dejamos con una recopilaci\u00f3n de The Huffington Post y BioBioChile sobre las 15 cosas que no pasaban antes de que existiera Facebook.<\/p>\n<p>\u00bfCu\u00e1les agregar\u00edas?<\/p>\n<p>1.- Nadie pod\u00eda \u201cDarte un toque\u201d tan f\u00e1cilmente.<\/p>\n<p>2.- Antes de que naciera Facebook tus \u201camigos\u201d no publicaban fotos que fueran comprometedoras (y que no quer\u00edas que nadie viera\u2026 en la vida).<\/p>\n<p>3.- Cuando te gustaba un chico(a) le ped\u00edas su n\u00famero de tel\u00e9fono\u2026 Ahora, la mayor\u00eda le pregunta si lo puede agregar a sus contactos.<\/p>\n<p>4.- No perd\u00edas tanto tiempo \u201canalizando\u201d a las amigas virtuales de tus amigos, jugando a la \u00faltima aplicaci\u00f3n de moda o suspirando con fotos de gatitos y perritos.<\/p>\n<p>5.- Antes te desesperabas cuando no encontrabas los cartuchos de tu consola de videojuegos o cuando la revista de tu \u00eddolo juvenil se agotaba en el kiosko. En los tiempos de Facebook, sientes que se te va la vida cuando te quedas m\u00e1s de dos horas sin conexi\u00f3n.<\/p>\n<p>6.- No recib\u00edas tantos piropos (ni solicitudes de gente que te \u201cpsicopatea\u201d en silencio).<\/p>\n<p>7.- No te daban ganas de comer tantas cosas ricas al mismo tiempo (las fotos de sushi, cupcakes y hamburguesas tienen vida propia en la plataforma).<\/p>\n<p>8.- Antes de Facebook, las personas no volv\u00edan a ver a la mayor\u00eda de sus compa\u00f1eros de colegio o universidad.<\/p>\n<p>9.- Los posts, memes, videos de Vine y YouTube que postean tus amigos no formaban parte de tu d\u00eda a d\u00eda.<\/p>\n<p>10.- Nunca te saludaba tanta gente para tu cumplea\u00f1os.<\/p>\n<p>11.- No ten\u00edas idea de lo que era sentirse traicionado hasta que te etiquetaron en una foto donde todos salen bien\u2026 menos t\u00fa.<\/p>\n<p>12.- Antes te emocionabas con la compra de un nuevo cassette, el revelado de tus fotos an\u00e1logas o la emisi\u00f3n de un cap\u00edtulo de \u201cLos Thundercats\u201d\u2026 Ahora por la cantidad de \u201cMe gusta\u201d que obtienen tus publicaciones.<\/p>\n<p>13.- Nunca hab\u00edas visto tantas fotos de fiestas, beb\u00e9s y matrimonios juntas.<\/p>\n<p>14.- No pon\u00edas \u201cMe gusta\u201d a cosas que, para ser sinceros, te dan lo mismo.<\/p>\n<p>15.- Antes de Facebook las personas te conoc\u00edan tal como eras (ahora, primero suelen encantarse con tu versi\u00f3n \u201cdigitalmente mejorada\u201d).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosas que no pasaran si Facebook no existiera.&nbsp;Este mes la red social m\u00e1s popular del mundo,&nbsp;Facebook, cumpli\u00f3 10 a\u00f1os conectando y deleitando a sus millones de&nbsp;usuarios. Y para celebrarlo, algunos medios reflexionaron en torno a la forma en que esta plataforma ha cambiado la&nbsp;vida&nbsp;de quienes la utilizan.<\/p>\n","protected":false},"author":3,"featured_media":25709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-32502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32502"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25709"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}