{"id":32506,"date":"2014-02-16T18:16:27","date_gmt":"2014-02-16T22:16:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/60-de-usuarios-de-iphone-tiene-lealtad-ciega-productos-apple\/"},"modified":"2014-02-16T18:16:27","modified_gmt":"2014-02-16T22:16:27","slug":"60-de-usuarios-de-iphone-tiene-lealtad-ciega-productos-apple","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/60-de-usuarios-de-iphone-tiene-lealtad-ciega-productos-apple\/","title":{"rendered":"60% de usuarios de iPhone tiene lealtad ciega productos Apple"},"content":{"rendered":"<p style=\"margin: 0px 0px 15px; padding: 0px; line-height: 1.6; color: #252324; font-size: 13px; text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"irc_mut size-full wp-image-32505\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_apple_bolsa-300x224.jpg\" width=\"300\" height=\"224\" alt=\"apple_bolsa-300x224\" style=\"color: #333333; font-family: Tahoma, Helvetica, Arial, sans-serif; font-size: 11.818181991577148px; line-height: 1.3em; margin-top: 126px;\" \/>Un estudio reciente ha revelado que&nbsp;una gran parte de los usuarios de iPhone admiten profesar una lealtad ciega hacia los productos de Apple. Al parecer muchos de los due\u00f1os de estos smartphones estar\u00edan dispuestos a comprar casi cualquier producto fabricado por dicha empresa.<br \/> <!--more--> <\/p>\n<p>El trabajo fue realizado por&nbsp;SIMOnleContracts.co.uk sobre una muestra base de 2 mil usuarios de iPhone. Un 60% de los encuestados admiti\u00f3 tener una lealtad ciega hacia Apple.&nbsp;El 78% se\u00f1al\u00f3 que no podr\u00eda imaginar utilizar otro dispositivo que no fuera un iPhone. El dato curioso es que&nbsp;solo el 50% se\u00f1al\u00f3 estar impresionado por los iPhone. Lo se\u00f1alado parece apuntar a que mientras los usuarios est\u00e1n felices y c\u00f3modos con los productos que emplean, el arraigo en muchos casos no tiene tanto que ver con la fascinaci\u00f3n y m\u00e1s con la fuerza de la costumbre.<\/p>\n<p>Por otro lado, el 54% de los usuarios de iPhone encuestados han sido due\u00f1os de otro iPhone de forma previa a su actual modelo. El 37% se\u00f1al\u00f3 que la raz\u00f3n para su paso a un nuevo iPhone fue la familiaridad con la interfaz del sistema operativo iOS. El 25% apunt\u00f3 que su permanencia en el mundo Apple ten\u00eda que ver con caracter\u00edsticas como el iMessage y Face Time. Solo el 28% declar\u00f3 que el nuevo iPhone era el mejor modelo de Smartphone para ellos. Entre aquellos que han pasado a iPhone desde otras marcas, el 17% procede de BlackBerry, el 14% de Nokia Phone, el 9% de Samsung, 4% de HTC y 2% de Sony.<\/p>\n<p>Del total encuestado el 52% estaba utilizando un iPhone 5, el 29% la versi\u00f3n 4 o 4S y solo el 9% ten\u00eda un iPhone 3 o 3GS. Una de cada 10 personas ten\u00eda uno de los \u00faltimos dos modelos, un 5C o 5S.<\/p>\n<p>Roshan Bholah, fundador de SIMOnlyContracts, se\u00f1al\u00f3: \u201cEs interesante ver la lealtad ciega entre los usuarios de iPhone. Ellos ya no consideran otros tel\u00e9fonos m\u00f3viles del mercado, solo por confianza en Apple y quiz\u00e1s por el gusto de ser asociados con la marca. Sin embargo, el dicho de si no est\u00e1 roto no lo arregles puede ser verdadero en este caso. Est\u00e1 claro que ellos tienen una experiencia positiva con el producto. Es la lealtad a la que todas las marcas esperan llegar con sus clientes\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un estudio reciente ha revelado que&nbsp;una gran parte de los usuarios de iPhone admiten profesar una lealtad ciega hacia los productos de Apple. Al parecer muchos de los due\u00f1os de estos smartphones estar\u00edan dispuestos a comprar casi cualquier producto fabricado por dicha empresa.<\/p>\n","protected":false},"author":3,"featured_media":32505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-32506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32506"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32505"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}