{"id":32602,"date":"2014-02-20T18:02:35","date_gmt":"2014-02-20T22:02:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/enamorarse-en-la-era-del-internet\/"},"modified":"2014-02-20T18:02:35","modified_gmt":"2014-02-20T22:02:35","slug":"enamorarse-en-la-era-del-internet","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/enamorarse-en-la-era-del-internet\/","title":{"rendered":"Enamorarse en la era del Internet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32600\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_siquesi-960x623.jpg\" width=\"881\" height=\"623\" alt=\"siquesi-960x623\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_siquesi-960x623.jpg 881w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_siquesi-960x623-300x212.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_siquesi-960x623-75x52.jpg 75w\" sizes=\"auto, (max-width: 881px) 100vw, 881px\" \/>El&nbsp;amor siempre ha sido una tem\u00e1tica importante en la historia de la humanidad, no podemos olvidar a las parejas que aunque se encontraban separadas por miles de kil\u00f3metros, se escribian rom\u00e1nticas cartas de amor, tal cual novela de&nbsp;Jane Austen. Pero&nbsp;las formas de contactar al ser amado evolucionaron y la era del Interntet lleg\u00f3 para quedarse. <!--more-->  <\/p>\n<p>En la actualidad todo tipo de detalles pueden ser compartido, como una fotograf\u00eda del atuendo a utilizar, una mascota paseando por la calle hasta el almuerzo que est\u00e1s por comer. As\u00ed mismo aplicaciones como las de videoconferencias, la red social&nbsp;Facebook&nbsp; o el famoso&nbsp;Whatsapp, se han convertido en distintas plataformas que complementan no s\u00f3lo las relaciones rom\u00e1nticas, sino que todo tipo de relaciones en la actualidad.<\/p>\n<p>Seg\u00fan estudios de&nbsp;Pew Research Center, un 25% de parejas adultas se enviaron mensajes telef\u00f3nicos mientras estaban en el mismo espacio f\u00edsico, mientras que un 9% admiti\u00f3 que resolvi\u00f3 un conflicto por mensaje te texto.<\/p>\n<p>Te dejamos las estad\u00edsticas que confirman lo importante del Internet en las relaciones sentimentales:<\/p>\n<div id=\"attachment_443304\" align=\"aligncenter\" width=\"700\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32601\" alt=\"CNN M\u00e9xico\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/static.betazeta.com_www.belelu.com_up_2014_02_amor.jpg\" width=\"700\" height=\"2068\" \/>CNN M\u00e9xico<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;amor siempre ha sido una tem\u00e1tica importante en la historia de la humanidad, no podemos olvidar a las parejas que aunque se encontraban separadas por miles de kil\u00f3metros, se escribian rom\u00e1nticas cartas de amor, tal cual novela de&nbsp;Jane Austen. Pero&nbsp;las formas de contactar al ser amado evolucionaron y la era del Interntet lleg\u00f3 para quedarse.<\/p>\n","protected":false},"author":3,"featured_media":32600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-32602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32602"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32600"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}