{"id":32768,"date":"2014-03-03T13:31:18","date_gmt":"2014-03-03T17:31:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/icomprobado-comida-chatarra-aumenta-infertilidad-masculina\/"},"modified":"2014-03-03T13:31:18","modified_gmt":"2014-03-03T17:31:18","slug":"icomprobado-comida-chatarra-aumenta-infertilidad-masculina","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/icomprobado-comida-chatarra-aumenta-infertilidad-masculina\/","title":{"rendered":"\u00a1Comprobado! Comida chatarra aumenta infertilidad masculina"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-31510\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/01\/sosua_images_comida_chatarra.jpg\" width=\"660\" height=\"496\" alt=\"comida_chatarra\" \/>Un estudio presentado en la Reuni\u00f3n Anual de la Sociedad Americana de Medicina Reproductiva determin\u00f3 que un alto consumo de comida chatarra en los hombres los har\u00eda m\u00e1s propensos a la infertilidad.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El an\u00e1lisis se llev\u00f3 a cabo en 188 hombres, entre los 18 y los 22 a\u00f1os. Los resultados mostraron que una alimentaci\u00f3n con altos contenidos de grasas trans tiene un impacto negativo en el sistema reproductivo.<\/p>\n<p> \u201cLa principal conclusi\u00f3n de nuestro trabajo es que una dieta saludable parece ser beneficiosa para la calidad del sistema reproductivo. Una mayor ingesta de pescado, frutas frescas, cereales integrales, legumbres y verduras parece mejorar la movilidad de las c\u00e9lulas reproductivas masculinas\u201d, explic\u00f3 Audrey Gaskins, autor principal del estudio.<\/p>\n<p> Sin embargo, el experto se\u00f1al\u00f3 que es necesario trabajar m\u00e1s para explorar la relaci\u00f3n exacta entre la nutrici\u00f3n y la infertilidad masculina.<\/p>\n<p> Por otro lado, Edward Kim, presidente de la Sociedad de Reproducci\u00f3n Masculina y Urolog\u00eda, apunt\u00f3 que a\u00fan estudian \u201cel impacto de la nutrici\u00f3n en la fertilidad masculina, pero incluso estos estudios iniciales apuntan a un v\u00ednculo entre una buena dieta y la salud reproductiva para los hombres\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un estudio presentado en la Reuni\u00f3n Anual de la Sociedad Americana de Medicina Reproductiva determin\u00f3 que un alto consumo de comida chatarra en los hombres los har\u00eda m\u00e1s propensos a la infertilidad.<\/p>\n","protected":false},"author":3,"featured_media":31510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-32768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32768"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/31510"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}