{"id":32803,"date":"2014-03-03T23:20:48","date_gmt":"2014-03-04T03:20:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/5-ejercicios-para-reducir-grasa-y-tonificar-tus-brazos\/"},"modified":"2014-03-03T23:20:48","modified_gmt":"2014-03-04T03:20:48","slug":"5-ejercicios-para-reducir-grasa-y-tonificar-tus-brazos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/5-ejercicios-para-reducir-grasa-y-tonificar-tus-brazos\/","title":{"rendered":"5 ejercicios para reducir grasa y tonificar tus brazos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32800\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_brazos-700x325.jpg\" width=\"700\" height=\"325\" alt=\"brazos-700x325\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_brazos-700x325.jpg 700w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_brazos-700x325-300x139.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>Los&nbsp;brazos&nbsp;son partes del cuerpo donde se suele acumular una importante cantidad de grasa. Es por ello que a muchas personas les gusta ejercitarlos para conseguir que luzcan mejor. Es as\u00ed que a continuaci\u00f3n te presentamos algunos consejos y ejercicios para que sepas c\u00f3mo tonificar los brazos. La mayor\u00eda de ellos son muy sencillos y se pueden hacer en casa.<\/p>\n<p>  <!--more-->  <\/p>\n<h2>Flexiones<\/h2>\n<p>Las flexiones son uno de los mejores ejercicios que existen para tonificar los brazos. Aunque en un inicio pueden resultar dif\u00edciles y muy cansadas, lo cierto es que con el paso del tiempo dan muy buenos resultados.&nbsp;Haciendo flexiones no solo ejercitar\u00e1s los brazos, sino que tambi\u00e9n el pecho, el&nbsp;abdomen&nbsp;y la parte alta de la espalda.<\/p>\n<p>Hacer las flexiones es muy sencillo. Para ello te debes de colocar boca abajo, sobre alguna esterilla, y levantar todo el peso de tu cuerpo hasta que tus brazos est\u00e9n bien estirados. Las palmas de las manos tienen que estar bien firmes y abiertas sobre el piso para que sea m\u00e1s f\u00e1cil empujar con fuerza. En cada flexi\u00f3n nuestro cuerpo tiene que llegar lo m\u00e1s bajo posible, rozando pr\u00e1cticamente con el piso.<\/p>\n<h2>Pesas y mancuernillas<\/h2>\n<p>Este tipo de ejercicio es muy popular entre quienes quieren tonificar sus brazos. Como algunos otros, su pr\u00e1ctica es muy sencilla ya que no se necesita de un equipamiento especial. Sin embargo, es muy importante tener en cuenta la cantidad de peso que debemos cargar debido a que si realizamos un esfuerzo muy grande nuestros m\u00fasculos pueden lesionarse.<\/p>\n<p>Por lo tanto,&nbsp;lo mejor es comenzar con pesos bajos que ayuden a que nuestros brazos se acostumbren a las pesas y mancuernillas. Una recomendaci\u00f3n es consultar a un especialista. Por su parte, para hacer este tipo de ejercicio solo tiene que estar de pie con las&nbsp;piernas&nbsp;abiertas a la altura de los hombros y levantar las pesas en un \u00e1ngulo de 90 grados con los codos. Se debe de mantener la espalda recta y bajar las pesas a la altura de la cadera de forma lenta y segura.<\/p>\n<h2>Estirar los tr\u00edceps<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32801\" alt=\"Ejercicios para adelgazar los brazos\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/cdn.mejorconsalud.com_wp-content_uploads_2013_04_Ejercicios-para-adelgazar-los-brazos.jpg\" width=\"500\" height=\"352\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/cdn.mejorconsalud.com_wp-content_uploads_2013_04_Ejercicios-para-adelgazar-los-brazos.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/cdn.mejorconsalud.com_wp-content_uploads_2013_04_Ejercicios-para-adelgazar-los-brazos-300x211.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Otro ejercicio que tiene buenos resultados es el de ejercitar los tr\u00edceps. Adem\u00e1s, es muy f\u00e1cil de hacer. Para ello basta con que te coloques en el borde de una silla o un banco que est\u00e9 bien firme. Los dedos de tus&nbsp;manos&nbsp;deben de pasar por debajo del borde y tus piernas formar un \u00e1ngulo de 90 grados respecto al piso. Aseg\u00farate de que las plantas de tus pies queden firmes.<\/p>\n<p>Despu\u00e9s de esto debes de levantar pausadamente tu cuerpo, logrando que tus piernas se separen ligeramente del piso. Es muy importante que tus brazos queden bien estirados. Posteriormente baja tu cuerpo hasta que los brazos queden ligeramente doblados.Esta rutina la tienes que repetir varias veces.<\/p>\n<h2>Levantamiento de pesas por encima de la cabeza<\/h2>\n<p>Este tipo de ejercicio consiste en levantar pesas o mancuernillas m\u00e1s all\u00e1 de la&nbsp;cabeza. Por supuesto, es muy sencillo de hacer y da resultados muy buenos.&nbsp;Basta con tener unas pesas o mancuernillas no muy pesadas, de aproximadamente un kilo y medio. Recuerda que debes de tener bien sujetas las pesas ya que est\u00e1n estar\u00e1n en un momento por encima de tu cabeza.<\/p>\n<p>Para hacer este ejercicio comienza con ponerte de pie, con las piernas abiertas a la altura de los hombros. Posteriormente levanta las pesas o mancuernillas con los brazos bien estirados, haciendo que estos se toquen arriba de tu cabeza. Despu\u00e9s baja el peso lentamente hasta que tus brazos est\u00e9n a un lado de tu cadera y piernas.<\/p>\n<h2>Nadar<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32802\" alt=\"nadar3\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/cdn.mejorconsalud.com_wp-content_uploads_2013_09_nadar3.jpg\" width=\"500\" height=\"300\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/cdn.mejorconsalud.com_wp-content_uploads_2013_09_nadar3.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/cdn.mejorconsalud.com_wp-content_uploads_2013_09_nadar3-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Como bien sabemos,&nbsp;nadar es una de las actividades f\u00edsicas que nos ayudan a ejercitar muchas partes de nuestro cuerpo con muy buenos resultados. Por lo tanto, gracias a ella tambi\u00e9n podemos tonificar nuestros brazos. Sin embargo, en este caso se necesita contar con una piscina o un cuerpo de agua que nos permita realizar dicha actividad.<\/p>\n<p>Lo mejor es realizar aquellos estilos donde se utiliza sobre todo la fuerza de los brazos. Aunque en realidad en todos ellos es necesario, en algunos casos su presencia e importancia es mayor, por lo que pueden ser de gran ayuda para tonificar nuestros brazos. Si no sabemos c\u00f3mo hacerlo, lo mejor es consultar a un entrenador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los&nbsp;brazos&nbsp;son partes del cuerpo donde se suele acumular una importante cantidad de grasa. Es por ello que a muchas personas les gusta ejercitarlos para conseguir que luzcan mejor. Es as\u00ed que a continuaci\u00f3n te presentamos algunos consejos y ejercicios para que sepas c\u00f3mo tonificar los brazos. La mayor\u00eda de ellos son muy sencillos y se pueden hacer en casa.<\/p>\n","protected":false},"author":3,"featured_media":32800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-32803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32803"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32800"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}