{"id":32978,"date":"2014-03-09T16:14:31","date_gmt":"2014-03-09T20:14:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/muere-guillo-perez-maestro-de-la-pintura-dominicana\/"},"modified":"2014-03-09T16:14:31","modified_gmt":"2014-03-09T20:14:31","slug":"muere-guillo-perez-maestro-de-la-pintura-dominicana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-guillo-perez-maestro-de-la-pintura-dominicana\/","title":{"rendered":"Muere Guillo P\u00e9rez, maestro de la pintura dominicana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32977\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_Guillo-Perez.jpg\" width=\"640\" height=\"469\" alt=\"Guillo-Perez\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_Guillo-Perez.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_Guillo-Perez-300x219.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>La paleta de colores de la pintura dominicana abada de perder uno de sus m\u00e1s espectaculares pinceles: Guillo P\u00e9rez, natural de Moca y nacido en 1926, acaba de fallecer por padecimiento de una cr\u00f3nica enfermedad que le abat\u00eda desde hace algunos a\u00f1os.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Se produjo su deceso hace unas horas en su residencia del Ensanche Piantini. Sus restos morales ser\u00e1n velados a partir de&nbsp; las primeras horas de la tarde, en Capillas La Paz, del Funeraria Blandino en la avenida Abraham Lincoln, apunta el cr\u00ectico y curador de arte Abil Peralta Aguero, asesor cultural de la C\u00e0mada de Diputados.<\/p>\n<p>Su fallecimiento despide la vida de uno de los m\u00e1s fecundos creadores de nuestra pintura, enlutece los artistas y deja plasmada una obra singular y diferenciada por el fuerte colorismo de sus empastes.<\/p>\n<p>Guillo P\u00e9rez Chac\u00f3n, quien hab\u00eda nacido en San V\u00edctor, de Moca, Provincia Espaillat, &nbsp;el 3 de marzo de 1926, hab\u00eda logrado trascendencia y diferenciaci\u00f3n por su obra expresionista y abstracta, en un universo figurativo que incluyo monumentos coloniales, y de Jerusal\u00e9n, marinas, figuras humanas, &nbsp;los elementos del ingenio azucarero (desde la ca\u00f1a hasta los bueyes), los paisajes, los caser\u00edos, los &nbsp;gallos, &nbsp;las flores y &nbsp;las hojas de pl\u00e1tanos.<\/p>\n<p>Su principal logro en el lienzo es el &nbsp;equilibrio de la luz del Caribe con una visi\u00f3n po\u00e9tica contemplativa.<\/p>\n<p><span style=\"font-size: 11px;\">Se caracterizaba por el uso de la esp\u00e1tula para lograr impactantes efectos de colorido fuerte y centrado en una masa pict\u00f3rica que le caracteriz\u00f3 desde sus inicios de carrera, luego de haber estudiado en la Escuela de Artes de Santiago de los Caballeros en el a\u00f1o 1950. En 1952 fue nombrado profesor y se estableci\u00f3 en Santo Domingo en 1955 donde inici\u00f3 una serie de exposiciones, tanto individuales como colectiva.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La paleta de colores de la pintura dominicana abada de perder uno de sus m\u00e1s espectaculares pinceles: Guillo P\u00e9rez, natural de Moca y nacido en 1926, acaba de fallecer por padecimiento de una cr\u00f3nica enfermedad que le abat\u00eda desde hace algunos a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":32977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-32978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32978"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32977"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}