{"id":32984,"date":"2014-03-12T02:45:35","date_gmt":"2014-03-12T06:45:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/diez-consejos-para-que-tu-hijo-tenga-unos-dientes-sanos\/"},"modified":"2014-03-12T02:45:35","modified_gmt":"2014-03-12T06:45:35","slug":"diez-consejos-para-que-tu-hijo-tenga-unos-dientes-sanos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/diez-consejos-para-que-tu-hijo-tenga-unos-dientes-sanos\/","title":{"rendered":"Diez consejos para que tu hijo tenga unos dientes sanos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-32983\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_dientes_xoptimizadax--644x362.jpg\" width=\"644\" height=\"362\" alt=\"dientes_xoptimizadax--644x362\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_dientes_xoptimizadax--644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_dientes_xoptimizadax--644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/>Adquirir unos buenos h\u00e1bitos bucodentales desde la infancia es una garant\u00eda para tener de por vida una boca sana. Es una forma de prevenir cualquier problema en la dentadura, como aconseja Vitaldent a trav\u00e9s de su&nbsp;canal de YouTube.&nbsp;Gustavo Cama\u00f1as,director d\u00e9dico de Vitaldent, ofrece a los padres sencillos consejos para inculcar a sus hijos el h\u00e1bito de lavarse los dientes todos los d\u00edas y as\u00ed evitarles posibles problemas bucodentales en el futuro:<\/p>\n<p>  <!--more-->  <\/p>\n<p>1. Limpieza oral desde el primer d\u00eda.&nbsp;La higiene de la boca no se debe limitar a cuando hay dientes. Los padres deben&nbsp;limpiar diariamente las enc\u00edas del beb\u00e9&nbsp;con una gasa h\u00fameda en agua tibia para evitar bacterias.<\/p>\n<p>2. Los dientes de leche tambi\u00e9n hay que cuidarlos.&nbsp;Los dientes de leche hay que cuidarlos de la misma forma que los permanentes, ya que cumplen funciones tan importantes como la de masticar o hablar. Si el ni\u00f1o presenta caries en un diente temporal, el riesgo de que el diente permanente resulte infectado es mucho mayor.<\/p>\n<p>3. Los padres deben supervisar el cepillado de sus hijos.&nbsp;En cuanto salen los primeros dientes hay que empezar a limpiarlos con un cepillo con cabezal peque\u00f1o de cerdas suaves y preferiblemente sin pasta dental para evitar que los ni\u00f1os la ingieran. A partir de los tres a\u00f1os, el ni\u00f1o puede participar en el cepillado, pero siembre bajo la supervisi\u00f3n de un adulto para asegurar que lo hace correctamente.<\/p>\n<p>4. Ense\u00f1arles a cepillarse los dientes.&nbsp;Para que los m\u00e1s peque\u00f1os aprendan a cepillarse correctamente, sin dejarse ninguna pieza y sin riesgo de erosionar su esmalte, es recomendable establecer un orden met\u00f3dico para que lo recuerden f\u00e1cilmente: cepillar de arriba abajo y de abajo arriba, incluso las enc\u00edas para evitar la acumulaci\u00f3n de sarro entre la enc\u00eda y el diente, cepillar las muelas y la cara interna de los dientes, utilizar seda dental para retirar los restos que se quedan entre los dientes y finalmente limpiar la lengua.<\/p>\n<p>5. Explorar peri\u00f3dicamente la boca.&nbsp;Los padres deben revisar la boca de sus hijos para detectar la presencia de sarro, flemones o posibles caries. Esta exploraci\u00f3n tambi\u00e9n servir\u00e1 para evaluar la erupci\u00f3n dentaria primaria y observar si hay alg\u00fan defecto en el esmalte, ya que un color extra\u00f1o de la pieza dental puede indicar alguna dolencia.<\/p>\n<p>6. Ser un buen ejemplo.&nbsp;Los ni\u00f1os suelen imitar el comportamiento de los mayores. Hay que compartir el momento del cepillado de los dientes con los hijos al menos dos veces al d\u00eda, especialmente por la noche antes de dormir. El cepillado nocturno es el m\u00e1s importante, ya que mientras dormimos la salivaci\u00f3n disminuye y los dientes est\u00e1n menos protegidos frente a las bacterias que producen las caries.<\/p>\n<p>7. Diversi\u00f3n.&nbsp;Se aconseja convertir el cepillado en algo divertido, acompa\u00f1\u00e1ndolo con peque\u00f1os juegos para crear una rutina amena en los m\u00e1s peque\u00f1os.<\/p>\n<p>8. Limitar el consumo de dulces.&nbsp;No hay que eliminar los dulces de la dieta del ni\u00f1o, pero s\u00ed controlar y limitar su consumo, ya que aumenta el riesgo de sufrir caries.<\/p>\n<p>9. Reemplazar su cepillo de dientes.&nbsp;El cepillo de dientes del ni\u00f1o debe adecuarse a la edad del menor. Los padres tambi\u00e9n deben encargarse de cambiarlo cada tres meses, que es lo recomendado por los profesionales.<\/p>\n<p>10. Visitar al dentista peri\u00f3dicamente.&nbsp;Lo id\u00f3neo es que el ni\u00f1o acuda al dentista cuando haya cumplido los dos a\u00f1os y medio o tres o si ya tiene todos los dientes temporales. En ese momento el dentista podr\u00e1 realizarle una primera exploraci\u00f3n del estado de su boca y valorar si la dieta que lleva es correcta, as\u00ed como la higiene dental. Lo m\u00e1s importante es que el ni\u00f1o acuda sin ninguna patolog\u00eda para que \u00e9ste no asocie al odont\u00f3logo con dolor o miedo. A partir de los 7 u 8 a\u00f1os, los ni\u00f1os ya pueden hacerse una primera limpieza dental. Adem\u00e1s, las visitas tempranas al odont\u00f3logo nos ayudar\u00e1n a diagnosticar problemas como una mal posici\u00f3n dental o la mordida cruzada que en la edad infantil se pueden solucionar f\u00e1cilmente gracias a la ortodoncia, mejorando as\u00ed la sonrisa y la salud del ni\u00f1o, la masticaci\u00f3n e, incluso, la fonaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adquirir unos buenos h\u00e1bitos bucodentales desde la infancia es una garant\u00eda para tener de por vida una boca sana. Es una forma de prevenir cualquier problema en la dentadura, como aconseja Vitaldent a trav\u00e9s de su&nbsp;canal de YouTube.&nbsp;Gustavo Cama\u00f1as,director d\u00e9dico de Vitaldent, ofrece a los padres sencillos consejos para inculcar a sus hijos el h\u00e1bito de lavarse los dientes todos los d\u00edas y as\u00ed evitarles posibles problemas bucodentales en el futuro:<\/p>\n","protected":false},"author":3,"featured_media":32983,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-32984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=32984"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/32984\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32983"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=32984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=32984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=32984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}