{"id":33053,"date":"2014-03-13T01:43:19","date_gmt":"2014-03-13T05:43:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/senadores-reaccionan-ante-sentencia-sobre-loma-miranda\/"},"modified":"2014-03-13T01:43:19","modified_gmt":"2014-03-13T05:43:19","slug":"senadores-reaccionan-ante-sentencia-sobre-loma-miranda","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/senadores-reaccionan-ante-sentencia-sobre-loma-miranda\/","title":{"rendered":"Senadores reaccionan ante sentencia sobre Loma Miranda"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-33052\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_Loma-Miranda-300x225.jpg\" width=\"300\" height=\"225\" alt=\"Loma-Miranda-300x225\" \/>Este mi\u00e9rcoles el&nbsp;<strong>Tribunal Superior Administrativo<\/strong>&nbsp;prohibi\u00f3 a la&nbsp;<strong>Direcci\u00f3n de Miner\u00eda<\/strong>&nbsp;y al<strong>&nbsp;Ministerio de Medio Ambiente<\/strong>abstenerse de autorizar la extracci\u00f3n de minerales en&nbsp;<strong>Loma Miranda<\/strong>.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Ante tal decisi\u00f3n, los senadores reaccionaron frente a la sentencia del Tribunal Superior Administrativo que proh\u00edbe la explotaci\u00f3n minera en Loma Miranda.<\/p>\n<p>El Tribunal Superior Administrativo est\u00e1 apoderado de un recurso de amparo preventivo de la&nbsp;<strong>Fundaci\u00f3n Justicia y Transparencia<\/strong>, el Ministerio de Medio Ambiente y la Direcci\u00f3n de Miner\u00eda en contra del Senado para evitar la explotaci\u00f3n de los yacimientos minerales de Loma Miranda.<\/p>\n<p>El juzgado aplaz\u00f3 la audiencia para el 2 de abril, adem\u00e1s de poner en causa a la empresa&nbsp;<strong>FALCONDO<\/strong>&nbsp;a fin de que sea parte del proceso.<\/p>\n<p>El senador<strong>&nbsp;Rafael Calder\u00f3n<\/strong>, Presidente de la comisi\u00f3n que estudia Loma Miranda, prometi\u00f3 que rendir\u00e1 un informe final ante el pleno en los pr\u00f3ximos d\u00edas, pero no especific\u00f3 cu\u00e1ndo.<\/p>\n<p>El senado recibi\u00f3 de la<strong>&nbsp;C\u00e1mara de Diputados<\/strong>&nbsp;un proyecto que declara a Loma Miranda \u00e1rea natural protegida, pero luego de casi cinco meses de estudio todav\u00eda no se producen resultados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles el&nbsp;Tribunal Superior Administrativo&nbsp;prohibi\u00f3 a la&nbsp;Direcci\u00f3n de Miner\u00eda&nbsp;y al&nbsp;Ministerio de Medio Ambienteabstenerse de autorizar la extracci\u00f3n de minerales en&nbsp;Loma Miranda.<\/p>\n","protected":false},"author":3,"featured_media":33052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-33053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33053"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33052"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}