{"id":33068,"date":"2014-03-13T23:46:26","date_gmt":"2014-03-14T03:46:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/indotel-estudia-proceso-venta-de-orange-dominicana-a-altice\/"},"modified":"2014-03-13T23:46:26","modified_gmt":"2014-03-14T03:46:26","slug":"indotel-estudia-proceso-venta-de-orange-dominicana-a-altice","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/indotel-estudia-proceso-venta-de-orange-dominicana-a-altice\/","title":{"rendered":"Indotel estudia proceso venta de Orange Dominicana a Altice"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-30733\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/11\/sosua_images_orange-corp.jpg\" width=\"640\" height=\"411\" alt=\"orange-corp\" \/>El presidente del&nbsp;Instituto Dominicano de las Telecomunicaciones (Indotel), Gede\u00f3n Santos, inform\u00f3 hoy que t\u00e9cnicos del \u00f3rgano regulador estudian los documentos que avalan el proceso de venta de&nbsp;Orange Dominicana a la empresa francesa Altice,&nbsp;al tiempo que garantiz\u00f3 el traspaso \u201csin trauma\u201d de las acciones de esta telef\u00f3nica.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Santos se refiri\u00f3 a algunos reclamos surgidos en torno a las frecuencias que usa Orange Dominicana para ofertar sus servicios de telefon\u00eda.<\/p>\n<p>Al respecto, Santos se\u00f1al\u00f3 que el \u00f3rgano regulador ha optado primero \u201cpor sentar las partes encontradas en un proceso de negociaci\u00f3n, con Indotel como mediador\u201d.<\/p>\n<p>\u201cPuedo adelantar que como mediadores hemos ayudado a que las partes est\u00e9n llegando a acuerdos. &nbsp;Pronto el pa\u00eds se enterar\u00e1 de los puntos a los &nbsp;que se llegaron y, por lo tanto, el proceso de venta o traspaso de las acciones de la empresa Orange Dominicana a Altice, es muy posible que se haga sin trauma sobre la base de un acuerdo entre los empresarios\u201d, subray\u00f3 el funcionario seg\u00fan una nota de prensa enviada por la entidad que preside.<\/p>\n<p><a href=\"http:\/\/hoy.com.do\/indotel-asegura-traspaso-de-orange\/\" target=\"_blank\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del&nbsp;Instituto Dominicano de las Telecomunicaciones (Indotel), Gede\u00f3n Santos, inform\u00f3 hoy que t\u00e9cnicos del \u00f3rgano regulador estudian los documentos que avalan el proceso de venta de&nbsp;Orange Dominicana a la empresa francesa Altice,&nbsp;al tiempo que garantiz\u00f3 el traspaso \u201csin trauma\u201d de las acciones de esta telef\u00f3nica.<\/p>\n","protected":false},"author":3,"featured_media":30733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-33068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33068"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/30733"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}