{"id":33161,"date":"2014-03-19T16:14:51","date_gmt":"2014-03-19T20:14:51","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ipor-que-los-pasajeros-del-vuelo-mh370-de-malaysia-airlines-no-usaron-sus-moviles\/"},"modified":"2014-03-19T16:14:51","modified_gmt":"2014-03-19T20:14:51","slug":"ipor-que-los-pasajeros-del-vuelo-mh370-de-malaysia-airlines-no-usaron-sus-moviles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ipor-que-los-pasajeros-del-vuelo-mh370-de-malaysia-airlines-no-usaron-sus-moviles\/","title":{"rendered":"\u00bfPor qu\u00e9 los pasajeros del vuelo MH370 de Malaysia Airlines no usaron sus m\u00f3viles?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-33160\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_espera-telefonos--644x362.jpg\" width=\"644\" height=\"362\" alt=\"espera-telefonos--644x362\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_espera-telefonos--644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_espera-telefonos--644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/>En la era de los \u00absmartphones\u00bb y las redes sociales, la desaparici\u00f3n del vuelo&nbsp;<a title=\"MH370\" href=\"http:\/\/www.abc.es\/hemeroteca\/(MH370\">MH370<\/a>&nbsp;de&nbsp;<a title=\"Malaysia Airlines\" href=\"http:\/\/www.abc.es\/hemeroteca\/malaysia+airlines\">Malaysia Airlines&nbsp;<\/a>plantea un interrogante m\u00e1s: \u00bfPor qu\u00e9 los pasajeros no contactaron con sus familiares, como durante los atentados del&nbsp;11-S?<\/p>\n<p>  <!--more-->  <\/p>\n<p>La ausencia de llamadas telef\u00f3nicas y correos electr\u00f3nicos podr\u00edan constituir una pista en la investigaci\u00f3n de&nbsp;<a title=\"qu\u00e9 pudo haber ocurrido al Boeing 777\" href=\"http:\/\/www.abc.es\/internacional\/20140319\/abci-sido-vuelo-mh370-teorias-201403191105.html\">qu\u00e9 pudo haber ocurrido al Boeing 777&nbsp;<\/a>que se dirig\u00eda a Pek\u00edn desde&nbsp;Kuala Lumpur&nbsp;con 239 personas a bordo. En este intrigante caso que va camino de convertirse en uno de los mayores misterios de la historia de la aeron\u00e1utica,&nbsp;este aspecto podr\u00eda indicar que el avi\u00f3n volaba alto o por encima del agua. O que los pasajeros quedaron inconscientes por una despresurizaci\u00f3n de la cabina.<\/p>\n<p>Seg\u00fan los expertos, si hubieran volado cerca de una red de telefon\u00eda terrestre, los pasajeros habr\u00edan podido utilizar sus m\u00f3viles y otros aparatos electr\u00f3nicos. Pero muchos se muestran esc\u00e9pticos respecto a la posibilidad de establecer un contacto telef\u00f3nico y de mantenerlo en vuelo a gran velocidad, en particular a altitud de crucero.<\/p>\n<p>Para establecer contacto entre un m\u00f3vil y una red (\u00ab<a title=\"handshake\" href=\"http:\/\/es.wikipedia.org\/wiki\/Handshaking\" target=\"_blank\">handshake<\/a>\u00bb), har\u00eda falta una se\u00f1al suficientemente fuerte desde ambos lados. Para el consultor en telecomunicaciones&nbsp;Koh Chee Koon,&nbsp;esta conexi\u00f3n es \u00abte\u00f3ricamente\u00bb posible&nbsp;si el avi\u00f3n volaba entre los 23.000 pies (7.000 metros) y los 45.000 pies tras haber perdido el contacto con el control a\u00e9reo, como indican informaciones no confirmadas.<\/p>\n<p>Sin embargo, dada la limitada potencia de los tel\u00e9fonos m\u00f3viles normales y el obst\u00e1culo de la cabina de la aeronave, para contar con una conexi\u00f3n de calidad aceptable&nbsp;\u00abhabr\u00eda que tener suerte\u00bb,a\u00f1ade. Los aviones utilizados en los atentados del 11 de septiembre de 2001 en Estados Unidos volaban relativamente bajo, sobre una zona cubierta por redes de telefon\u00eda m\u00f3vil. Y la mayor\u00eda de las llamadas se realizaron desde tel\u00e9fonos a bordo, no desde m\u00f3viles.<\/p>\n<p>Algunas compa\u00f1\u00edas a\u00e9reas han permitido recientemente el<a title=\"uso de m\u00f3viles en vuelo,\" href=\"http:\/\/www.abc.es\/tecnologia\/moviles\/20140120\/abci-aviones-smartphone-fases-vuelo-201401172101.html\">&nbsp;uso de m\u00f3viles en vuelo,<\/a>&nbsp;gracias a la instalaci\u00f3n de una red interior en el aparato, pero este servicio no estaba disponible en el vuelo MH370, seg\u00fan Malaysia Airlines.<\/p>\n<h4>Imposible en mitad del oc\u00e9ano<\/h4>\n<p>Sin este sistema, un m\u00f3vil no puede ser utilizado por encima de los 500 metros de altitud por un avi\u00f3n de l\u00ednea, y por debajo, no muy lejos de una torre, seg\u00fan&nbsp;A.K. Dewdney, profesor de inform\u00e1tica de la Universidad de Ontario en Canad\u00e1. \u00abNing\u00fan m\u00f3vil podr\u00eda lograr conectarse en un avi\u00f3n en mitad del oc\u00e9ano, incluso a baja altitud\u00bb, asegura.<\/p>\n<p>\u00abA una altitud de crucero normal, ning\u00fan tel\u00e9fono m\u00f3vil podr\u00eda contactar con tierra\u00bb, en cualquier caso, insiste Dewdney, que ha investigado el tema desde el 11-S. El patr\u00f3n de Malaysia Airlines,Ahmad Jauhari Yahya, explic\u00f3 el lunes que no hab\u00eda ninguna prueba de que los pasajeros hubieran tratado de telefonear, si bien se\u00f1al\u00f3 que \u00abmillones\u00bb de datos del tel\u00e9fono a\u00fan no se hab\u00edan analizado.<\/p>\n<p>Reforzando el misterio, los medios de comunicaci\u00f3n chinos recogen que<a title=\"los familiares intentaron llamar con sus m\u00f3viles a pasajeros del avi\u00f3n tras la desaparici\u00f3n y los tel\u00e9fonos daban se\u00f1al\" href=\"http:\/\/www.abc.es\/internacional\/20140312\/abci-inquietante-tono-moviles-pasajeros-201403121101.html\">los familiares intentaron llamar con sus m\u00f3viles a pasajeros del avi\u00f3n tras la desaparici\u00f3n y los tel\u00e9fonos daban se\u00f1al<\/a>. Pero para los expertos,esto no es una prueba de que los tel\u00e9fonos funcionaran. A pesar de que nadie contest\u00f3 a las llamadas, las tentativas de contacto entre una red y los m\u00f3viles a bordo -que algunos pasajeros podr\u00edan haberse olvidado de apagar-&nbsp;podr\u00edan dar datos sobre la trayectoria del avi\u00f3n&nbsp;tras su desaparici\u00f3n.<\/p>\n<p>Pero para trazar estas \u00abhandshakes\u00bb, los investigadores se enfrentan a la dificultad de recoger cada n\u00famero de identificaci\u00f3n de los tel\u00e9fonos de los pasajeros, as\u00ed como los datos de los operadores en los pa\u00edses que pudieron sobrevolar y algunos, como Birmania, cuentan todav\u00eda con redes embrionarias.<\/p>\n<p>Tras haber girado una hora despu\u00e9s de su despegue de Kuala Lumpur y haber atravesado Malasia, el Boeing sobrevol\u00f3 probablemente una zona cubierta por una red. Pero despu\u00e9s, los cambios de \u00abhandshakes\u00bb dependen de la altitud del avi\u00f3n y de su proximidad a torres voladas. \u00abLa polic\u00eda localiza los m\u00f3viles a partir de la \u00faltima llamada\u00bb, indicaKen Dulaney, analista del gabinete de investigaci\u00f3n Gartner. Pero esto solo es posible si los dispositivos se encuentran al alcance de una red.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la era de los \u00absmartphones\u00bb y las redes sociales, la desaparici\u00f3n del vuelo&nbsp;MH370&nbsp;de&nbsp;Malaysia Airlines&nbsp;plantea un interrogante m\u00e1s: \u00bfPor qu\u00e9 los pasajeros no contactaron con sus familiares, como durante los atentados del&nbsp;11-S?<\/p>\n","protected":false},"author":3,"featured_media":33160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-33161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33161"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33160"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}