{"id":33439,"date":"2014-03-31T17:13:30","date_gmt":"2014-03-31T21:13:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-doodle-de-google-celebra-los-cien-anos-de-octavio-paz-2\/"},"modified":"2014-03-31T17:13:30","modified_gmt":"2014-03-31T21:13:30","slug":"el-doodle-de-google-celebra-los-cien-anos-de-octavio-paz-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-doodle-de-google-celebra-los-cien-anos-de-octavio-paz-2\/","title":{"rendered":"El doodle de Google celebra los cien a\u00f1os de Octavio Paz"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-33434\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_13962410284602.jpg\" width=\"600\" height=\"400\" alt=\"13962410284602\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_13962410284602.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/03\/sosua_images_13962410284602-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Los cien a\u00f1os que hoy cumplir\u00eda Octavio Paz son raz\u00f3n m\u00e1s que suficiente para que el doodle de&nbsp;<label datatype=\"t\">Google<\/label>&nbsp;homenaje\u00e9 al escritor, poeta, ensayista y pol\u00edtico mexicano. Para ello, Google utiliza una&nbsp;<label datatype=\"t\">imagen<\/label>&nbsp;tan dif\u00edcil de catalogar como la obra del escritor.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>El surrealismo, el incoformismo y el mundo on\u00edrico de Octavio Paz queda reflejado en una ilustraci\u00f3n que intenta dibujar los famosos topoemas que el poeta mexicano invent\u00f3.<\/p>\n<p>La obesi\u00f3n de Octavio Paz de huir del tiempo le llev\u00f3 a crear una poes\u00eda espacial que el propio autor bautiz\u00f3 como &#8216;topoemas&#8217;, la conjugaci\u00f3n de topo m\u00e1s poemas. Una poes\u00eda opuesta a la poes\u00eda temporal y discursiva. Una poes\u00eda casi metaf\u00edsica, como el doodle que Google dedica al autor.<\/p>\n<p>En los topoemas, igual que ocurr\u00eda en la poes\u00eda de los movimientos de&nbsp;<label datatype=\"t\">vanguardia<\/label>, se le da importancia al poder sugerente y expresivo de las im\u00e1genes pl\u00e1sticas.<\/p>\n<p>Octavio Paz es el poeta mexicano m\u00e1s reconocido en el mundo y uno de los m\u00e1s venerados, y es por ello que no s\u00f3lo Google se rinde ante su figura. M\u00e9xico se rinde ante el polifac\u00e9tico escritor con una serie de actividades convocadas para festejar los cien a\u00f1os de su nacimiento.<\/p>\n<p>Los textos que escribi\u00f3 Paz son los principales protagonistas de los homenajes y han sido numerosas las publicaciones que se est\u00e1n sacando.<\/p>\n<p>Figura como ejemplo una antolog\u00eda de textos preparada por Danubio Torres Fierro que la Comisi\u00f3n Nacional de Textos Gratuitos (Conaliteg) editar\u00e1 y distribuir\u00e1 entre 1,8 millones de estudiantes.<\/p>\n<p>Traductor, editor de revistas imprescindibles, pero sobretodo ensayista y poeta, Octavio Paz fue autor de una obra inagotable y el gobierno mexicano aspira ahora a renovar el inter\u00e9s por su lectura, especialmente entre los j\u00f3venes.<\/p>\n<p>Paz, fallecido en 1998, fue tambi\u00e9n un influyente personaje p\u00fablico cuyas posiciones pol\u00edticas generaron controversia en parte de la izquierda mexicana, que lo ve\u00eda demasiado cercano al PRI (Partido Revolucionario Institucional), hegem\u00f3nico en M\u00e9xico durante m\u00e1s de 70 a\u00f1os.<\/p>\n<p>Paz lleg\u00f3 a la cima de la literatura al obtener el premio Cervantes en 1981 y el Nobel en 1990. Tan profunda era su erudici\u00f3n, su omnipresencia en toda clase de debates y la influencia acumulada que lleg\u00f3 a infundir temor entre los dem\u00e1s escritores mexicanos, que suspiraban por la aceptaci\u00f3n de Paz al considerarla una suerte de consagraci\u00f3n.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.elmundo.es\/cultura\/2014\/03\/31\/5338f2f6268e3ec86e8b456b.html\" target=\"_blank\">El Mundo<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los cien a\u00f1os que hoy cumplir\u00eda Octavio Paz son raz\u00f3n m\u00e1s que suficiente para que el doodle de&nbsp;Google&nbsp;homenaje\u00e9 al escritor, poeta, ensayista y pol\u00edtico mexicano. Para ello, Google utiliza una&nbsp;imagen&nbsp;tan dif\u00edcil de catalogar como la obra del escritor.<\/p>\n","protected":false},"author":3,"featured_media":33434,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-33439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33439"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33434"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}