{"id":33627,"date":"2014-04-04T19:30:52","date_gmt":"2014-04-04T23:30:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/vine-introduce-mensajes-privados-en-su-aplicacion\/"},"modified":"2014-04-04T19:30:52","modified_gmt":"2014-04-04T23:30:52","slug":"vine-introduce-mensajes-privados-en-su-aplicacion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vine-introduce-mensajes-privados-en-su-aplicacion\/","title":{"rendered":"Vine introduce mensajes privados en su aplicaci\u00f3n"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-33626\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_153728_messages_principal.jpg\" width=\"600\" height=\"400\" alt=\"153728_messages_principal\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_153728_messages_principal.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_153728_messages_principal-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Vine, la red social de los&nbsp;<label datatype=\"t\">videos<\/label>&nbsp;de seis segundos propiedad de Twitter, ha anunciado que ahora los&nbsp;<label datatype=\"t\">usuarios<\/label>&nbsp;de esta aplicaci\u00f3n podr\u00e1n enviarse mensajes privados tanto en formato de texto como,&nbsp;<label datatype=\"t\">claro<\/label>, en video.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Inclusive los mensajes podr\u00e1n ser enviados a amigos que no est\u00e9n registrados en Vine, as\u00ed como a varias personas a la vez (generando una conversaci\u00f3n propia con uno mismo).<\/p>\n<p>Los usuarios podr\u00e1n escoger si desean recibir mensajes privados de cualquier viner o s\u00f3lo de las personas que siguen.<\/p>\n<p>Esta nueva funci\u00f3n est\u00e1 disponible tanto en la aplicaci\u00f3n de Vine para iOS como en la versi\u00f3n para Android.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.sdpnoticias.com\/tecnologia\/2014\/04\/03\/vine-introduce-mensajes-privados-en-su-aplicacion\" target=\"_blank\">SDP Noticias<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vine, la red social de los&nbsp;videos&nbsp;de seis segundos propiedad de Twitter, ha anunciado que ahora los&nbsp;usuarios&nbsp;de esta aplicaci\u00f3n podr\u00e1n enviarse mensajes privados tanto en formato de texto como,&nbsp;claro, en video.<\/p>\n","protected":false},"author":3,"featured_media":33626,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-33627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33627"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33626"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}