{"id":33724,"date":"2014-04-07T17:54:18","date_gmt":"2014-04-07T21:54:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/google-lanzaria-un-nuevo-sistema-de-television-android-tv\/"},"modified":"2014-12-01T10:20:29","modified_gmt":"2014-12-01T14:20:29","slug":"google-lanzaria-un-nuevo-sistema-de-television-android-tv","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-lanzaria-un-nuevo-sistema-de-television-android-tv\/","title":{"rendered":"Google lanzar\u00eda un nuevo sistema de televisi\u00f3n: Android TV"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-33461\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_1921032.jpg\" width=\"600\" height=\"400\" alt=\"1921032\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_1921032.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_1921032-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>El&nbsp;<label datatype=\"t\">servicio<\/label>, que vendr\u00eda a reemplazar a&nbsp;<label datatype=\"t\">Google<\/label><label datatype=\"t\">TV<\/label>, tendr\u00eda un men\u00fa bastante similar a sus principales competidores y tendr\u00eda en mente ganarse un lugar en la sala de estar de los hogares.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>En 2012, Eric Schmidt, ejecutivo de Google, anunciaba con mucha parafernalia un nuevo producto de la empresa: Google TV. Un dispositivo que promet\u00eda revolucionar la televisi\u00f3n como ning\u00fan otro aparato y pasar por encima de la competencia existente. En perspectiva, Schmidt estaba equivocado y este proyecto, como tantos otros de la compa\u00f1\u00eda, no tuvo buenos frutos.<\/p>\n<p>Pero su mal desempe\u00f1o no se vio traducido en un impedimento. Es m\u00e1s, al parecer, impuls\u00f3 a realizar algo mejor. Y al menos eso asegura el sitio especializado en tecnolog\u00eda, The Verge, que filtr\u00f3 im\u00e1genes de lo que ser\u00eda la unificaci\u00f3n de dispositivos para el televisor de Google bajo el nombre de Android TV.<\/p>\n<p>Seg\u00fan los documentos obtenidos por el sitio, Google estar\u00eda por lanzar esta nueva plataforma, pero este no ser\u00eda un intento m\u00e1s de llevar tu celular inteligente al televisor, sino que crear\u00eda una \u00abinterface de entretenimiento, no una software computacional\u00bb, de manera fluida, r\u00e1pida y simp\u00e1tica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-33721\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/informe21.com_sites_default_files_imagepicker_e_Editor ER_123.jpg\" alt=\"Image\" width=\"620\" height=\"375\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/informe21.com_sites_default_files_imagepicker_e_Editor%20ER_123.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/informe21.com_sites_default_files_imagepicker_e_Editor%20ER_123-300x181.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>En la pr\u00e1ctica, y seg\u00fan muestran las im\u00e1genes filtradas, el dispositivo utilizar\u00eda una carta de pel\u00edculas, series, aplicaciones y juegos, todo controlado a trav\u00e9s de un mando remoto de cuatro direcciones y tmabi\u00e9n tendr\u00eda soporte de voz y notificaciones. Algo muy similar a lo que anunci\u00f3 Amazon hace algunos d\u00edas con Fire TV (sistema basado en Android). Tal como en esa plataforma y en Apple TV, este aparato permitir\u00eda utilizar el sistema de Google u otros servicios como Netflix, Vevo, Hulu, Pandora, etc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-33723\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/informe21.com_sites_default_files_imagepicker_e_Editor ER_321.jpg\" alt=\"Image\" width=\"620\" height=\"375\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/informe21.com_sites_default_files_imagepicker_e_Editor%20ER_321.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/informe21.com_sites_default_files_imagepicker_e_Editor%20ER_321-300x181.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Por la informaci\u00f3n que se tiene hasta ahora, Android TV no superar\u00eda a sus rivales directos en t\u00e9rminos de hardware o de disponibilidad de servicios, y menos a los reyes del entretenimiento de la sala de estar como la Xbox One o Playstation 4, pero si muestra la intenci\u00f3n de Google por hacerse un lugar frente al sill\u00f3n del hogar.<\/p>\n<p>Quiz\u00e1s esta vez Google s\u00ed tenga raz\u00f3n y obtenga buenos frutos de su dispositivo.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.latercera.com\/noticia\/tendencias\/2014\/04\/659-572738-9-google-lanzaria-un-nuevo-sistema-de-television-android-tv.shtml\" target=\"_blank\">La Tercera<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;servicio, que vendr\u00eda a reemplazar a&nbsp;GoogleTV, tendr\u00eda un men\u00fa bastante similar a sus principales competidores y tendr\u00eda en mente ganarse un lugar en la sala de estar de los hogares.<\/p>\n","protected":false},"author":3,"featured_media":33461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-33724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33724"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33724\/revisions"}],"predecessor-version":[{"id":33832,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33724\/revisions\/33832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33461"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}