{"id":33750,"date":"2014-04-07T23:39:05","date_gmt":"2014-04-08T03:39:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/muere-la-madre-de-anthony-santos-2\/"},"modified":"2014-04-07T23:39:05","modified_gmt":"2014-04-08T03:39:05","slug":"muere-la-madre-de-anthony-santos-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-la-madre-de-anthony-santos-2\/","title":{"rendered":"Muere la madre de Anthony Santos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-33747\" alt=\"anthony_santos_noti_0\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_anthony_santos_noti_0.png\" height=\"180\" width=\"250\" \/>Elsa N\u00fa\u00f1ez, de 65 a\u00f1os de edad, acudi\u00f3 a un centro de salud aquejada de problemas estomacales y durante el chequeo sufri\u00f3 un paro card\u00edaco.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La madre del bachatero Anthony Santos muri\u00f3 pr\u00f3ximo al mediod\u00eda de hoy en el Hospital Metropolitano de Santiago (HOMS), seg\u00fan inform\u00f3 el m\u00e1nager del artista Lenny Ram\u00edrez.<\/p>\n<p>La se\u00f1ora Elsa N\u00fa\u00f1ez, de 65 a\u00f1os de edad, acudi\u00f3 en la ma\u00f1ana de hoy al centro de salud mencionado aquejada de problemas estomacales y durante el chequeo sufri\u00f3 un paro card\u00edaco que le quit\u00f3 la vida.<\/p>\n<p>\u201cElla comi\u00f3 algo la noche del domingo que le cay\u00f3 mal y en la ma\u00f1ana de este lunes acudi\u00f3 a Santiago para chequearse y sufri\u00f3 un ataque card\u00edaco\u201d, dijo Lenny Ram\u00edrez.<\/p>\n<p>Est\u00e1 siendo velada en su residencia de Las Matas de Santa Cruz y ser\u00e1 sepultada este martes en el cementerio municipal de dicha comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elsa N\u00fa\u00f1ez, de 65 a\u00f1os de edad, acudi\u00f3 a un centro de salud aquejada de problemas estomacales y durante el chequeo sufri\u00f3 un paro card\u00edaco.<\/p>\n","protected":false},"author":3,"featured_media":33747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-33750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33750"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33747"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}