{"id":33771,"date":"2014-04-07T18:36:22","date_gmt":"2014-04-07T22:36:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/microsoft-podria-seguir-a-amazon-y-netflix-produciendo-series-de-tv-3\/"},"modified":"2014-12-01T10:19:37","modified_gmt":"2014-12-01T14:19:37","slug":"microsoft-podria-seguir-a-amazon-y-netflix-produciendo-series-de-tv-3","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/microsoft-podria-seguir-a-amazon-y-netflix-produciendo-series-de-tv-3\/","title":{"rendered":"Microsoft podr\u00eda seguir a Amazon y Netflix produciendo series de TV"},"content":{"rendered":"<p data-textannotation-id=\"c8af962f42e0057b51cfb09b635639c7\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-33744\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_peliculas_msn.jpg\" width=\"604\" height=\"314\" alt=\"peliculas_msn\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_peliculas_msn.jpg 604w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/04\/sosua_images_peliculas_msn-300x155.jpg 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/>Amazon y Netflix ya est\u00e1n en ello, Yahoo podr\u00eda hacerlo muy pronto y Microsoft, seg\u00fanBloomberg, ser\u00e1 el siguiente. La compa\u00f1\u00eda est\u00e1 trabajando en sus propias series de televisi\u00f3n a trav\u00e9s de su nuevo estudio de televisi\u00f3n de Xbox. Entre los proyectos que estrenar\u00e1 a nivel mundial en junio est\u00e1n series de animaci\u00f3n, programas de f\u00fatbol y una serie digital sobre el juego&nbsp;Halo&nbsp;producida por Steven Spielberg.<\/p>\n<p>  <!--more--> <\/p>\n<aside data-ids=\"1556913357\">\n<div>\n<div>\n<div>\n<p data-textannotation-id=\"aef73d1480fb852ddad0ae3f56118668\">Se ven\u00eda hablando de \u00e9l desde hace semanas, y ya lo tenemos aqu\u00ed. Amazon acaba de presentar en Nueva York su nuevo dispositivo para streaming.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/aside>\n<p data-textannotation-id=\"41cd93fac36163a718c020b048e4712f\">No basta con tener el mejor aparato en tu sal\u00f3n para ver contenido, sea una&nbsp;set-top-box&nbsp;como&nbsp;Amazon Fire TV&nbsp;o una consola como la Xbox One. Tambi\u00e9n debes tener el mejor contenido. Eso lo saben bien Amazon y Netflix, que ya trabajan en producir sus propias series y&nbsp;shows. Seg\u00fan el&nbsp;WSJ, Yahoo podr\u00eda ser el siguiente en hacer lo mismo yBloomberg&nbsp;se\u00f1ala que Microsoft ya est\u00e1 en ello.<\/p>\n<p data-textannotation-id=\"d9534aa4d98409ec03c01a16e8f2065f\">Entre el contenido que prepara Microsoft, y que se estrenar\u00e1 a nivel mundial a trav\u00e9s de la suscripci\u00f3n a Xbox LIVE, est\u00e1n&nbsp;shows&nbsp;de la actriz y monologuista&nbsp;Sarah Silverman, series de animaci\u00f3n en&nbsp;stop-motion&nbsp;y programas sobre f\u00fatbol que se estrenar\u00e1n a tiempo para el Mundial de f\u00fatbol de Brasil. Es decir, muy pronto.<\/p>\n<p data-textannotation-id=\"7338afb6a57b99cd2f0daeb98a1914c5\">La idea de Microsoft es atraer a m\u00e1s consumidores a la Xbox One y al servicio de suscripci\u00f3n Xbox Live, para ir mucho m\u00e1s all\u00e1 de los juegos. Las series que la compa\u00f1\u00eda estrenar\u00e1 tendr\u00e1n adem\u00e1s funciones que dejar\u00e1n a los espectadores interactuar entre ellos en tiempo real y con los programas. Microsoft de momento no ha anunciado nada oficial, pero probablemente no tardaremos en conocer todos los detalles.<\/p>\n<p data-textannotation-id=\"7338afb6a57b99cd2f0daeb98a1914c5\">\n<p data-textannotation-id=\"7338afb6a57b99cd2f0daeb98a1914c5\">[v\u00eda&nbsp;<a href=\"http:\/\/www.bloomberg.com\/news\/2014-04-07\/microsoft-goes-hollywood-in-amazon-like-programming-push.html\" target=\"_blank\" sl-processed=\"1\">Bloomberg<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amazon y Netflix ya est\u00e1n en ello, Yahoo podr\u00eda hacerlo muy pronto y Microsoft, seg\u00fanBloomberg, ser\u00e1 el siguiente. La compa\u00f1\u00eda est\u00e1 trabajando en sus propias series de televisi\u00f3n a trav\u00e9s de su nuevo estudio de televisi\u00f3n de Xbox. Entre los proyectos que estrenar\u00e1 a nivel mundial en junio est\u00e1n series de animaci\u00f3n, programas de f\u00fatbol y una serie digital sobre el juego&nbsp;Halo&nbsp;producida por Steven Spielberg.<\/p>\n","protected":false},"author":3,"featured_media":33744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-33771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33771"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33771\/revisions"}],"predecessor-version":[{"id":33829,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33771\/revisions\/33829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33744"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}