{"id":33967,"date":"2014-11-30T08:31:17","date_gmt":"2014-11-30T12:31:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=33967"},"modified":"2014-12-05T08:36:07","modified_gmt":"2014-12-05T12:36:07","slug":"juan-carlos-morales-pla-logra-con-exito-nado-travesia-solidaria-de-sosua-a-san-felipe-de-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/juan-carlos-morales-pla-logra-con-exito-nado-travesia-solidaria-de-sosua-a-san-felipe-de-puerto-plata\/","title":{"rendered":"Juan Carlos Morales Pla logra con \u00e9xito nado traves\u00eda solidaria de Sos\u00faa a San Felipe de Puerto Plata"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/JUAN-CARLOS-MORALES-2-300x200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33968 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/JUAN-CARLOS-MORALES-2-300x200.jpg\" alt=\"JUAN-CARLOS-MORALES-2-300x200\" width=\"300\" height=\"200\" \/><\/a>Puerto Plata.-<\/strong>En un tiempo de 5 horas 56 minutos, Juan Carlos Morales Pl\u00e1 logr\u00f3 exitosamente el pasado s\u00e1bado su traves\u00eda solidaria, haciendo un recorrido de 16.9 kil\u00f3metros de nado continuo desde Playa Sos\u00faa (Los Charamicos) de Sos\u00faa hasta El Pueblito San Felipe de Puerto Plata.<!--more--><\/p>\n<p>Con un clima favorable, la bendici\u00f3n del padre Edward Gilbert y la ovaci\u00f3n de todos los que se dieron cita a la salida, el nadador aficionado inici\u00f3 su desaf\u00edo en las aguas del Atl\u00e1ntico a las 7:40 am, llegando a la meta fijada a las 1:36 de la tarde, dando durante todo el trayecto unas 9,823 brazadas con las que cumpli\u00f3 su proeza.<\/p>\n<p>La haza\u00f1a del atleta puertoplate\u00f1o fue monitoreada y asistida en todo momento por un gran equipo de profesionales, encabezado por el doctor Benjam\u00edn Payano, y Augusto Garc\u00eda, directivos de Sportlab, organizaci\u00f3n sin fines de lucro que tiene a su cargo la responsabilidad de desarrollar deportistas de alto rendimiento, destacando al reconocido ex nadador de ultradistancia Marcos D\u00edaz, quien por m\u00e1s de una d\u00e9cada confi\u00f3 el seguimiento de su carrera a dicha \u00a0instituci\u00f3n deportiva.<\/p>\n<p>Para llevar a cabo el proyecto Traves\u00eda Solidaria, Juan Carlos Morales Pla se inspir\u00f3 en honrar la memoria de destacados j\u00f3venes de la provincia de Puerto Plata que fallecieron a destiempo y que dejaron un legado deportivo inspirador, entre ellos, su hijo, Carlos Eduardo Morales V\u00e1squez, Javier Rosario, Junior Santana, Jos\u00e9 Carlos Gonz\u00e1lez Imbert, Antonio Cocco, Fredd\u00edn Cabrera, Orlando Rodr\u00edguez, Carlos Jos\u00e9 Ure\u00f1a, Steven Almonte Troche y m\u00e1s recientemente Oscar Taveras.<\/p>\n<p>A\u00a0partir de este evento se comenz\u00f3 a gestar la fundaci\u00f3n que llevar\u00e1 el nombre de Carlos Eduardo Morales, con el fin de ayudar a promover, incentivar y promocionar el deporte en todos los niveles sociales de la juventud en Rep\u00fablica Dominicana, brindando apoyo a cientos de j\u00f3venes con habilidades innatas para poder desarrollar sus entrenamientos.<\/p>\n<p>La esperada llegada del puertoplate\u00f1o se llev\u00f3 a cabo ante una gran multitud de p\u00fablico que reconoci\u00f3 el valor de la iniciativa y celebr\u00f3 la proeza y el gesto del nadador. Entre las autoridades y personalidades que participaron en la ceremonia de recibimiento se citan el gobernador provincial, doctor Iv\u00e1n Rivera, el viceministro de Turismo para la regi\u00f3n Norte, Julio Almonte; el diputado Jos\u00e9 Ignacio Paliza, y el Capit\u00e1n de Nav\u00edo Frank Polanco de los Santos, Comandante de la Zona Naval Norte; el director provincial del ministerio de Medio Ambiente, Carlos Finke; el director provincial de Deportes, Neftal\u00ed Lamouth y el actual campe\u00f3n de nataci\u00f3n Miguel Portes.<\/p>\n<p>Tambi\u00e9n apoyaron la Traves\u00eda Solidaria de Juan Carlos Morales Pla el ex nadador de ultradistancia\u00a0 y actual viceministro de Deportes, Marcos D\u00edaz, quien a trav\u00e9s de su fundaci\u00f3n dio seguimiento y apoyo directo a todo el proyecto. D\u00edaz, junto a su esposa Nathalia Bentz, hicieron entrega de un donativo de googles al director del Club Deportivo La Carabela de Col\u00f3n, Juri Fabri, para los entrenamientos de nataci\u00f3n en aguas abiertas de los ni\u00f1os y j\u00f3venes del municipio de la Isabela que se preparan en esta disciplina deportiva.<\/p>\n<p>Asimismo, Carib Wind Cabarete, Fantas\u00eda 90.5 FM y Puerto Plata Swimming Club, donaron gorros de nado para dichos fines, mientras que Ocean World les ofreci\u00f3 un recorrido por sus instalaciones a los j\u00f3venes atletas.<\/p>\n<p>Tras realizarse los chequeos m\u00e9dicos de lugar, Juan Carlos Morales Pla, con visible emoci\u00f3n se dirigi\u00f3 a los presentes, pronunciando unas palabras de agradecimiento a todos los que les apoyaron con su Traves\u00eda Solidaria.<\/p>\n<p>\u201cGratitud y amor a todos los que de alguna manera u otra estuvieron conmigo y me llevaron en sus oraciones para hacer realidad esta meta. A toda mi familia, especialmente a mi esposa Fernanda V\u00e1squez de Morales y a mis hijas Damaris y Carla Victoria; \u00a0al equipo t\u00e9cnico, Fundaci\u00f3n Marcos D\u00edaz, SportLab, Puerto Plata Swimming Club, Total Training, Academia Stono, a todos los patrocinadores y al pueblo de Puerto Plata, porque juntos demostramos que todos los objetivos que nos proponemos en la vida pueden \u00a0lograrse con fe, perseverancia, disciplina y dedicaci\u00f3n\u201d, dijo.<\/p>\n<p>Con este recorrido Morales, de 47 a\u00f1os, se convierte en el segundo nadador que logra un trayecto de ultradistancia en las aguas del Atl\u00e1ntico, constituy\u00e9ndose en un ejemplo viviente de inspiraci\u00f3n, dejando un legado de esperanza, de vida y transformaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Plata.-En un tiempo de 5 horas 56 minutos, Juan Carlos Morales Pl\u00e1 logr\u00f3 exitosamente el pasado s\u00e1bado su traves\u00eda solidaria, haciendo un recorrido de 16.9 kil\u00f3metros de nado continuo desde Playa Sos\u00faa (Los Charamicos) de Sos\u00faa hasta El Pueblito San Felipe de Puerto Plata.<\/p>\n","protected":false},"author":3,"featured_media":33968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-33967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=33967"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33967\/revisions"}],"predecessor-version":[{"id":33969,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/33967\/revisions\/33969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/33968"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=33967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=33967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=33967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}