{"id":34097,"date":"2014-12-08T10:22:05","date_gmt":"2014-12-08T14:22:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=34097"},"modified":"2014-12-08T10:22:05","modified_gmt":"2014-12-08T14:22:05","slug":"instituto-dominicano-de-aviacion-civil-exigira-que-los-drones-sean-operados-por-pilotos-certificados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/instituto-dominicano-de-aviacion-civil-exigira-que-los-drones-sean-operados-por-pilotos-certificados\/","title":{"rendered":"Instituto Dominicano de Aviaci\u00f3n Civil exigir\u00e1 que los Drones sean operados por pilotos certificados"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/drones-internet-facebook.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34098 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/drones-internet-facebook-300x168.jpg\" alt=\"drones-internet-facebook\" width=\"300\" height=\"168\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/drones-internet-facebook-300x168.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/drones-internet-facebook.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La aparici\u00f3n de los drones en el pa\u00eds trajo una novedad. Era el dispositivo con autonom\u00eda de vuelo capaz de tomar im\u00e1genes y v\u00eddeo en altas resoluciones desde las alturas. Concomitantemente lleg\u00f3 la posibilidad de que estos aparatos sirvieran como mensajeros, llevando paquetes por los aires con precisi\u00f3n y ahorro de costes.<!--more--><\/p>\n<p>Esa \u00faltima posibilidad conllevar\u00eda a regulaciones por parte de las autoridades, que aunque aseguran aun es incipiente la presencia de drones, tambi\u00e9n reconoce la importancia de actuar antes de que se convierta en una realidad sobre la que haya que actuar en urgencia.<\/p>\n<p>El tema aqu\u00ed es que la Organizaci\u00f3n de Aviaci\u00f3n Civil Internacional (OACI) trabaja en los protocolos de regulaci\u00f3n de los aparatos no tripulados, una gu\u00eda que esperan las autoridades locales para tomarla como referencia al momento de regular su uso en el pa\u00eds.<\/p>\n<p>\u201cEse es un proceso nuevo, no solo para nosotros, la propia OACI est\u00e1 iniciando el proceso para crear una regulaci\u00f3n.<\/p>\n<p>Yo creo que aqu\u00ed nos vamos a abocar dentro de poco a examinar eso\u201d, explic\u00f3 Alejandro Herrera, director del IDAC desde marzo de 2011.<\/p>\n<p>La OACI, de hecho, apenas ha comenzado la elaboraci\u00f3n del material gu\u00eda y de orientaciones ante el nuevo evento tecnol\u00f3gico. En algunos casos, advierte el director del IDAC, se ha comenzado a exigir que un piloto certificado, experimentado, sea quien maneje los artefactos.<\/p>\n<p>El dato de las alturas y las zonas por las que volar\u00edan los drones en Santo Domingo es uno de los temas de mayor importancia en la eventual regulaci\u00f3n. \u201cYa sea a trav\u00e9s de un reglamento o una resoluci\u00f3n pero vamos a tener que normalizar esta actividad, yo creo que ser\u00e1 de las tareas del 2015\u201d, indic\u00f3 el funcionario.<\/p>\n<p><a href=\"http:\/\/www.listindiario.com\/la-republica\/2014\/12\/8\/348321\/IDAC-exigira-que-los-drones-sean-operados-por-pilotos-certificados\" target=\"_blank\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aparici\u00f3n de los drones en el pa\u00eds trajo una novedad. Era el dispositivo con autonom\u00eda de vuelo capaz de tomar im\u00e1genes y v\u00eddeo en altas resoluciones desde las alturas. Concomitantemente lleg\u00f3 la posibilidad de que estos aparatos sirvieran como mensajeros, llevando paquetes por los aires con precisi\u00f3n y ahorro de costes.<\/p>\n","protected":false},"author":3,"featured_media":34098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-34097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=34097"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34097\/revisions"}],"predecessor-version":[{"id":34099,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34097\/revisions\/34099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/34098"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=34097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=34097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=34097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}