{"id":34419,"date":"2014-12-16T06:20:50","date_gmt":"2014-12-16T10:20:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=34419"},"modified":"2014-12-16T06:20:50","modified_gmt":"2014-12-16T10:20:50","slug":"receta-facil-de-salsa-de-cebolla-y-vino-tinto","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/receta-facil-de-salsa-de-cebolla-y-vino-tinto\/","title":{"rendered":"Receta f\u00e1cil de salsa de cebolla y vino tinto"},"content":{"rendered":"<div class=\"descripcion\">\n<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/receta-de-salsa-de-cebolla-y-vino.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34420 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/receta-de-salsa-de-cebolla-y-vino.jpg\" alt=\"receta de salsa de cebolla y vino\" width=\"418\" height=\"235\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/receta-de-salsa-de-cebolla-y-vino.jpg 1600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/receta-de-salsa-de-cebolla-y-vino-300x168.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/receta-de-salsa-de-cebolla-y-vino-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/a>Si necesitas una salsa con un gran sabor para aderezar tus carnes, no busques mas, aqu\u00ed tienes una elaboraci\u00f3n sencilla y con la que conseguir\u00e1s que tus carnes resalten todo su sabor, sean del tipo que sean, ya que les aporta mucho cuerpo e intensidad.<!--more--><\/div>\n<div><\/div>\n<div>Es muy f\u00e1cil de preparar, como podr\u00e1s ver, tan solo lleva unos poco ingredientes, los justos y necesarios, aunque ya sabes que siempre le puedes aportar tu toque con algunas de tus hierbas preferidas, con las que podr\u00e1s darle ese toque de frescor o de monta\u00f1a, como prefieras.<\/div>\n<div>\n<p>Yo te aconsejo que el caldo que utilices sea de carne, aunque tambi\u00e9n puedes utilizarlo de ave o similar, si no tuvieras, yo alguna vez que otra he utilizado concentrado de carne diluido en agua, eso si ve con cuidado con la sal, ya sabes que los concentrados llevan mucha.<\/p>\n<\/div>\n<div class=\"separator\">Espero haberte aportado una muy buena idea para aderezar tus platos de carne, en breve te dar\u00e9 alguna idea para que puedas utilizar esta receta, con alguna elaboraci\u00f3n. Espero tus comentarios, como siempre.<\/div>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/dE66BeNWsgs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<\/div>\n<p><strong>Tiempo:<\/strong><\/p>\n<div class=\"datos\">\n<p>50 minutos<\/p>\n<h4>Valor Cal\u00f3rico:<\/h4>\n<p>bajo<\/p>\n<h4>Dificultad:<\/h4>\n<p>baja<\/p>\n<\/div>\n<div class=\"ingredientes\">\n<h4>Ingredientes<\/h4>\n<ul>\n<li>4 Cebollas<\/li>\n<li>1 Cucharada peque\u00f1a de pimienta en grano<\/li>\n<li>200 ml de vino tinto<\/li>\n<li>500 ml de caldo de carne<\/li>\n<li>3 Cucharadas de aceite de oliva<\/li>\n<li>Sal al gusto<\/li>\n<\/ul>\n<div class=\"separator\"><a href=\"http:\/\/2.bp.blogspot.com\/-Hv3q5mNtDXE\/VI35i8yJNMI\/AAAAAAAAEqY\/prZGl_KnKvo\/s1600\/ingredientes%2Bsalsa%2Bde%2Bcebolla%2By%2Bvino.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/2.bp.blogspot.com\/-Hv3q5mNtDXE\/VI35i8yJNMI\/AAAAAAAAEqY\/prZGl_KnKvo\/s1600\/ingredientes%2Bsalsa%2Bde%2Bcebolla%2By%2Bvino.jpg\" alt=\"C\u00f3mo hacer salsa de cebolla y vino tinto\" width=\"320\" height=\"180\" border=\"0\" \/><\/a><\/div>\n<div><\/div>\n<\/div>\n<div class=\"preparacion\">\n<h2>PREPARACI\u00d3N<\/h2>\n<ul>\n<li>Pela la cebolla y la cortas en juliana.<\/li>\n<\/ul>\n<\/div>\n<div class=\"elaboracion\">\n<h2>ELABORACI\u00d3N<\/h2>\n<div>Echa el aceite en una cazuela y la pones a fuego medio-bajo.<\/div>\n<div><\/div>\n<div>Cuando est\u00e9 caliente a\u00f1ade la cebolla.<\/div>\n<div><\/div>\n<div>Le echas un poco de sal y la sofr\u00edes unos 8 \u00f3 10 minutos.<\/div>\n<div>Hasta que este bien pochada.<\/div>\n<div><\/div>\n<div>Vierte el vino tinto.<\/div>\n<div><\/div>\n<div>Lo remueves bien y que reduzca unos 5 minutos.<\/div>\n<div><\/div>\n<div>Cuando haya reducido echas el caldo.<\/div>\n<div><\/div>\n<div>Echas sal al gusto y lo remueves bien.<\/div>\n<div><\/div>\n<div>Lo dejas que se cocina a fuego medio-bajo durante 30 minutos.<\/div>\n<div><\/div>\n<div>Pasado este tiempo retira la cazuela del fuego.<\/div>\n<div><\/div>\n<div>Vierte el la salsa en la trituradora.<\/div>\n<div><\/div>\n<div>Lo trituras bien hasta que te quede una salsa suave y sin grumos.<\/div>\n<div><\/div>\n<div>Ya la puedes servir.<\/div>\n<\/div>\n<div class=\"consejos\">\n<h2>CONSEJO<\/h2>\n<ul>\n<li>Puedes utilizar caldo de carne o de ave.<\/li>\n<li>El vino tinto que tenga cuerpo as\u00ed le dar\u00e1 mas sabor a la salsa.<\/li>\n<\/ul>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si necesitas una salsa con un gran sabor para aderezar tus carnes, no busques mas, aqu\u00ed tienes una elaboraci\u00f3n sencilla y con la que conseguir\u00e1s que tus carnes resalten todo su sabor, sean del tipo que sean, ya que les aporta mucho cuerpo e intensidad.<\/p>\n","protected":false},"author":3,"featured_media":34420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-34419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=34419"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34419\/revisions"}],"predecessor-version":[{"id":34421,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34419\/revisions\/34421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/34420"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=34419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=34419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=34419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}