{"id":34536,"date":"2014-12-18T13:00:01","date_gmt":"2014-12-18T17:00:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=34536"},"modified":"2014-12-18T11:24:58","modified_gmt":"2014-12-18T15:24:58","slug":"la-primera-fase-del-operativo-se-pondra-en-ejecucion-a-partir-del-23-a-las-200-de-la-tarde-y-concluira-el-jueves-25-a-las-600-de-la-tarde-mientras-que-la-segunda-fase-inicia-el-martes-30-a-las-200","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-primera-fase-del-operativo-se-pondra-en-ejecucion-a-partir-del-23-a-las-200-de-la-tarde-y-concluira-el-jueves-25-a-las-600-de-la-tarde-mientras-que-la-segunda-fase-inicia-el-martes-30-a-las-200\/","title":{"rendered":"Los 15 r\u00e9cords mundiales m\u00e1s extra\u00f1os"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/svetlana.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34537 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/svetlana-300x200.jpg\" alt=\"svetlana\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/svetlana-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/svetlana.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Algunas personas est\u00e1n dispuestas a hacer cualquier cosa para aparecer en las noticias, quedar registrado en un libro y hacerse famosas. Existen r\u00e9cords mundiales realmente notorios y destacados, pero otros parecen descabellados y sin sentido. Estos son algunos de los r\u00e9cords m\u00e1s rid\u00edculos.<!--more--><\/p>\n<p>Para todos ellos est\u00e1 el libro Guinness de marcas mundiales, donde van parar las personas que tienen la maravillosa capacidad de hacer cosas extraordinarias que no le importan a nadie. F\u00edjate, <label>seguro<\/label> no conoc\u00edas ninguno de estos r\u00e9cords. Pero no te sientas culpable, la mayor\u00eda de ellos<\/p>\n<p><strong>15 La <label>cebolla<\/label> m\u00e1s grande<\/strong><\/p>\n<p>Inglaterra, 16 de septiembre de 2011. Pes\u00f3 8.150kg.<\/p>\n<p><strong>14 La maleta m\u00e1s grande<\/strong><\/p>\n<p><label>China<\/label>, 15 de octubre de 2006. Med\u00eda 175 cm de alto, 115 de ancho y 46 de profundidad.<\/p>\n<p><strong>13 El taz\u00f3n de <label>arroz<\/label> m\u00e1s grande<\/strong><\/p>\n<p>Costa Rica, 12 de febrero de 2013. El taz\u00f3n de arroz pes\u00f3 1.345,50 kilogramos.<\/p>\n<p><strong>12 La bufanda tejida m\u00e1s larga<\/strong><\/p>\n<p>Helge Johansen, de Noruega, teji\u00f3 la bufanda m\u00e1s larga del mundo y mide nada m\u00e1s ni nada menos que 4.565,46 metros.<\/p>\n<p><strong>11 La torre de Lego m\u00e1s alta<\/strong><\/p>\n<p>Noruega, 24 de abril de 2010.<\/p>\n<p><strong>10 El mosaico de sushi m\u00e1s grande<\/strong><\/p>\n<p>Hong Kong, 8 de enero de 2014.<\/p>\n<p><strong>9 Im\u00e1n humano<\/strong><\/p>\n<p>Georgia, 28 de diciembre de 2008. Logr\u00f3 sostener 53 <label>cucharas<\/label> magnetizadas sobre su cuerpo.<\/p>\n<p><strong>8 Mayor cantidad de personas bailando Thriller<\/strong><\/p>\n<p>M\u00e9xico, 29 de agosto de 2009. 13 597 personas se reunieron para bailar Thriller, de Michael Jackson.<\/p>\n<p><strong>7 El capucchino m\u00e1s grande<\/strong><\/p>\n<p>Bonfanti-Julius Meinl, Croacia 2012, el capucchino m\u00e1s grande fue de 2.012 litros.<\/p>\n<p><strong>6 Mayor cantidad de calabazas talladas<\/strong><\/p>\n<p>Estados Unidos, 18 de octubre de 2013.<\/p>\n<p><strong>5 Las piernas m\u00e1s largas<\/strong><\/p>\n<p>Svetlana Pankratova, de Rusia, sostiene el r\u00e9cord mundial de las piernas m\u00e1s largas, con 132 cent\u00edmetros de largo.<\/p>\n<p><strong>4 Mayor cantidad de personas bailando el ula-ula<\/strong><\/p>\n<p>Tailandia, 12 de febrero de 2013. 4.483 bailaron el ula-ula durante 7 minutos<\/p>\n<p><strong>3 La cabellera m\u00e1s larga<\/strong><\/p>\n<p>Xie Qiuping, de China, sostiene el r\u00e9cord mundial de la cabellera femenina m\u00e1s larga. Desde 1973 no se corta el cabello y actualmente mide unos 5.6 metros de largo.<\/p>\n<p><strong>2 La salchicha m\u00e1s grande<\/strong><\/p>\n<p>Mide 40.64 cm de largo, 10.16 cm de di\u00e1metro y pesa 3.18 kg.<\/p>\n<p><strong>1 El algod\u00f3n de az\u00facar m\u00e1s grande<\/strong><\/p>\n<p>Alemania, 13 de julio de 2013. Midi\u00f3 5.45 metros de altura.<\/p>\n<p>Fuente: <a href=\"http:\/\/curiosidades.batanga.com\/7670\/los-15-records-mundiales-mas-dementes-y-ridiculos\" target=\"_blank\">Ojo Curioso<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Algunas personas est\u00e1n dispuestas a hacer cualquier cosa para aparecer en las noticias, quedar registrado en un libro y hacerse famosas. Existen r\u00e9cords mundiales realmente notorios y destacados, pero otros parecen descabellados y sin sentido. Estos son algunos de los r\u00e9cords m\u00e1s rid\u00edculos.<\/p>\n","protected":false},"author":3,"featured_media":34537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-34536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=34536"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34536\/revisions"}],"predecessor-version":[{"id":34540,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34536\/revisions\/34540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/34537"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=34536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=34536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=34536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}