{"id":34544,"date":"2014-12-18T17:00:09","date_gmt":"2014-12-18T21:00:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=34544"},"modified":"2014-12-18T11:34:09","modified_gmt":"2014-12-18T15:34:09","slug":"7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron\/","title":{"rendered":"7 profec\u00edas sobre el fin del mundo que, obviamente, no se cumplieron"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-34545 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron-4-300x200.jpg\" alt=\"7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron-4\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron-4-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/12\/7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron-4.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Todos los a\u00f1os se va a acabar el mundo, de acuerdo a las miles de profec\u00edas que se han dicho sobre la destrucci\u00f3n del planeta. Si fuera por ellas, hace tiempo no deber\u00edas existir pero, menos mal, son falsas. A continuaci\u00f3n, te presentamos 7 profec\u00edas sobre el fin del mundo que, obviamente, no se cumplieron.<!--more--><\/p>\n<p>Tanto la distribuci\u00f3n lineal del tiempo, como el hecho de que no podamos saber qu\u00e9 suceder\u00e1 en el futuro son aspectos que causan mucha ansiedad en el ser humano. Es por ello que a lo largo del tiempo, muchas personas han intentado adelantarse a los acontecimientos con profec\u00edas sobre distintos eventos catastr\u00f3ficos. Lamentablemente, el \u00fanico factor com\u00fan entre estas supuestas visiones es que son falsas. Veamos pues algunas predicciones que la gente esperaba y nunca se cumplieron.<\/p>\n<p><strong>7. El Armaged\u00f3n de los mormones<\/strong><\/p>\n<p>En 1835, el fundador de los Mormones, Joseph Smith, humildemente convoc\u00f3 a sus fieles y les dijo que Dios le hab\u00eda hecho una <label>visita<\/label> inform\u00e1ndole que Jes\u00fas regresar\u00eda a la tierra a lo largo del siglo y el mundo acabar\u00eda. Como se comprob\u00f3 finalmente, el Armaged\u00f3n de los Mormones fue <label>solo<\/label> un sue\u00f1o de su primer l\u00edder.<\/p>\n<p><strong>6. El cometa Halley provoca una crisis<\/strong><\/p>\n<p>A principios del siglo XX, la <label>vida<\/label> de todos los habitantes del planeta se vio bastante revolucionada, debido a que los medios difundieron que la <label>cola<\/label> del cometa Halley rozar\u00eda la Tierra, acabando con la vida del planeta. T\u00fa y yo sabemos que no fue una buena predicci\u00f3n.<\/p>\n<p><strong>5. Las <label>puertas<\/label> del cielo: consecuencias fatales de una profec\u00eda<\/strong><\/p>\n<p>Por desgracia, no siempre las profec\u00edas tienen un final tan pac\u00edfico, como el simple hecho de que no sucedan. A fines del XX, todo los integrantes de una secta llamada Las puertas del cielo se suicidaron ante la supuesta predicci\u00f3n de que el mundo acabar\u00eda tras el paso del cometa Hale-Bopp, una evento que cualquiera, con el m\u00e1s simple telescopio, habr\u00eda podido refutar.<\/p>\n<p><strong>4. Predicciones sobre el caos inform\u00e1tico<\/strong><\/p>\n<p>Tambi\u00e9n sobre el universo inform\u00e1tico se han hecho predicciones fallidas. A principios de los 70, algunos notaron que al finalizar el siglo las computadoras podr\u00edan no poder identificar la diferencia de datos entre el 2000 y los a\u00f1os anteriores. Sobrevino la alarma y, con ella, la idea de que el mundo terminar\u00eda acabando en un holocausto provocado por el caos inform\u00e1tico. Parece que estas predicciones no eran muy certeras, despu\u00e9s de todo.<\/p>\n<p><strong>3. Nostradamus se equivoc\u00f3<\/strong><\/p>\n<p>Salvo a los devotos a las profec\u00edas de Nostradamus, a nadie tom\u00f3 por sorpresa que en julio del buen a\u00f1o de 1999, fecha en la cual, seg\u00fan se predijera 80 lustros antes, deber\u00eda producirse el Armaged\u00f3n pues \u201cdel cielo llover\u00eda el terror\u201d, no sucediera absolutamente nada. Nostradamus definitivamente se equivoc\u00f3.<\/p>\n<p><strong>2. 2008: el fin del mundo se cern\u00eda sobre todos<\/strong><\/p>\n<p>En el 2006, un ministro de la Iglesia de Dios vaticin\u00f3 que el fin del mundo se cern\u00eda sobre todos y que ya en el 2008 estar\u00edamos condenados por el peor tiempo de la historia de la humanidad, colapsar\u00edan los poderes del planeta y Estados Unidos se desmembrar\u00eda como naci\u00f3n. A pesar de nuestro temor a una gran afectaci\u00f3n de la Tierra por los desmanes del hombre, no podemos decir que tal predicci\u00f3n se haya cumplido.<\/p>\n<p><strong>1. Octubre del 2011: \u00a1Y otra vez el fin!<\/strong><\/p>\n<p>En mayo del 2011, volvi\u00f3 a ser anunciado por un predicador radial que en octubre de ese mismo a\u00f1o comenzar\u00edan una serie de terremotos, hundiendo al planeta en un caos y falta de fe. Se iniciar\u00edan tormentas y llegar\u00eda una vez m\u00e1s el fin del mundo. Raz\u00f3n no le sobraba.<\/p>\n<p>Podr\u00edamos estar horas enumerando profec\u00edas sobre el fin del mundo, lo cierto es que la ciencia prueba que se pueden hacer estimaciones predictivas de fen\u00f3menos naturales y sociales usando herramientas matem\u00e1ticas, pero adivinar de manera m\u00edstica el futuro no es algo que nos est\u00e9 dado a los seres humanos, ministros de Dios o no.<\/p>\n<p>Francamente, ante tal c\u00famulo de predicciones que la gente esperaba y nunca se cumplieron a\u00fan me estoy preguntando si en realidad soy un fantasma. \u00bfY t\u00fa qu\u00e9 crees?<\/p>\n<p><a href=\"http:\/\/informe21.com\/predicciones\/las-impactantes-profecias-de-nostradamus-para-2015\" target=\"_blank\">Las impactantes profec\u00edas de Nostradamus para 2015<br \/>\n<\/a><\/p>\n<p>Fuente: <a href=\"http:\/\/curiosidades.batanga.com\/7651\/7-profecias-sobre-el-fin-del-mundo-que-obviamente-no-se-cumplieron\" target=\"_blank\">Ojo curioso<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los a\u00f1os se va a acabar el mundo, de acuerdo a las miles de profec\u00edas que se han dicho sobre la destrucci\u00f3n del planeta. Si fuera por ellas, hace tiempo no deber\u00edas existir pero, menos mal, son falsas. A continuaci\u00f3n, te presentamos 7 profec\u00edas sobre el fin del mundo que, obviamente, no se cumplieron.<\/p>\n","protected":false},"author":3,"featured_media":34545,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-34544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=34544"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34544\/revisions"}],"predecessor-version":[{"id":34546,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/34544\/revisions\/34546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/34545"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=34544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=34544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=34544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}