{"id":36467,"date":"2015-01-09T23:56:54","date_gmt":"2015-01-10T03:56:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=36467"},"modified":"2015-01-09T23:56:54","modified_gmt":"2015-01-10T03:56:54","slug":"por-que-deberias-de-tener-sexo-al-menos-una-vez-por-semana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/por-que-deberias-de-tener-sexo-al-menos-una-vez-por-semana\/","title":{"rendered":"\u00bfPor qu\u00e9 deber\u00edas de tener sexo al menos una vez por semana?"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_sexo_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-32653 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_sexo_1.jpg\" alt=\"sexo_1\" width=\"600\" height=\"400\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_sexo_1.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/02\/sosua_images_sexo_1-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>En tiempos recientes parece que el rush existencial que caracteriza la <label>vida<\/label> de una buena parte de la poblaci\u00f3n <label>mundial<\/label> ha provocado que la actividad sexual entre parejas se vea disminuida. La gran mayor\u00eda de nosotros dedicamos m\u00e1s tiempo a actividades ligadas a la frivolidad <label>digital<\/label>,<label>estilo<\/label> <label>Facebook<\/label>, que a nuestra vida sexual.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Por otro lado existe la tendencia del \u201cmoney making\u201d: estamos tan preocupados por escalar puestos en una compa\u00f1\u00eda o por encontrar maneras de generar mayores ingresos que inconscientemente terminamos por relegar la magia el coito a un gris segundo plano.<\/p>\n<p>De acuerdo con algunos estudios, 40 millones de estadounidenses se encuentran envueltos en matrimonios pr\u00e1cticamente asexuales. Entre las m\u00faltiples razones para explicar esta tendencia podr\u00edamos enlistar las siguientes:<\/p>\n<p>&#8211; Estr\u00e9s relacionado con temas laborales o econ\u00f3micos.<\/p>\n<p>-Excesivo cansancio producido por el fren\u00e9tico estilo de vida propio de las sociedades contempor\u00e1neas.<\/p>\n<p>&#8211; Efectos secundarios de diversos medicamentos industriales que debilitan el deseo sexual.<\/p>\n<p>&#8211; El aumento de condiciones fisiol\u00f3gicas como la obesidad o problemas cardiacos, factores que inhiben la b\u00fasqueda de un encuentro sexual.<\/p>\n<p>La lista podr\u00eda ser mucho mayor, pero sin duda estas cuatro causas son m\u00e1s que suficientes para delinear ese triste y asexual panorama. Sin embargo, y a pesar de que muchos consideran lo contrario, lo cierto es que una vida sexual activa (ya no digamos excelente) implica beneficios concretos para la mente, el cuerpo e incluso el esp\u00edritu de una persona, lo cual puede traducirse en una mayor plenitud social y laboral:<\/p>\n<p>&#8211; El sexo te rejuvenece.<\/p>\n<p>&#8211; Ayuda a combatir el estr\u00e9s.<\/p>\n<p>&#8211; Fortalece el sistema inmunol\u00f3gico.<\/p>\n<p>&#8211; Provoca la liberaci\u00f3n de bioqu\u00edmicos ben\u00e9ficos como las endorfinas.<\/p>\n<p>&#8211; Adem\u00e1s, seg\u00fan un estudio de la antrop\u00f3loga Helen Fisher, una vida sexual rebosante se traduce en un desempe\u00f1o mucho m\u00e1s exitoso en el entorno laboral.<\/p>\n<p>Tomando en cuenta todo lo anterior parece que esta nota debiera cerrar con una pregunta obvia: \u00bfQu\u00e9 haces leyendo esto en lugar de estar en la cama con tu esposa, tu novio o con esa linda amiga que emana un et\u00e9reo perfume oto\u00f1al? Recuerda que la c\u00f3pula te engrandece.<\/p>\n<p>Fuente: <a href=\"http:\/\/pijamasurf.com\/2010\/11\/%C2%BFpor-que-deberias-de-tener-sexo-al-menos-una-vez-por-semana\/\" target=\"_blank\">PijamaSurf<\/a> \/ VIC<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En tiempos recientes parece que el rush existencial que caracteriza la vida de una buena parte de la poblaci\u00f3n mundial ha provocado que la actividad sexual entre parejas se vea disminuida. La gran mayor\u00eda de nosotros dedicamos m\u00e1s tiempo a actividades ligadas a la frivolidad digital,estilo Facebook, que a nuestra vida sexual.<\/p>\n","protected":false},"author":3,"featured_media":32653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-36467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=36467"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36467\/revisions"}],"predecessor-version":[{"id":36469,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36467\/revisions\/36469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/32653"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=36467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=36467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=36467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}