{"id":36480,"date":"2015-01-10T17:51:01","date_gmt":"2015-01-10T21:51:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=36480"},"modified":"2015-01-10T17:51:01","modified_gmt":"2015-01-10T21:51:01","slug":"sabes-cuales-son-los-alimentos-que-curan-el-insomnio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sabes-cuales-son-los-alimentos-que-curan-el-insomnio\/","title":{"rendered":"\u00bfSabes cu\u00e1les son los alimentos que curan el insomnio?"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/curar-el-insomnio-una-dieta-adecuada-L-vdQpEn.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36494 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/curar-el-insomnio-una-dieta-adecuada-L-vdQpEn.jpeg\" alt=\"curar-el-insomnio-una-dieta-adecuada-L-vdQpEn\" width=\"320\" height=\"283\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/curar-el-insomnio-una-dieta-adecuada-L-vdQpEn.jpeg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/curar-el-insomnio-una-dieta-adecuada-L-vdQpEn-300x265.jpeg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a>Dormir es un proceso vital para <label>todo<\/label> ser vivo, ya que permite al <label>cuerpo<\/label> descansar, recuperando energ\u00eda y regenerando c\u00e9lulas necesarias para las actividades de la vigilia. De ese modo, el cuerpo puede optimizar el funcionamiento del sistema inmunol\u00f3gico, cardiovascular, end\u00f3crino, digestivo, sexual, etc. E inclusive, es <label>uno<\/label> de los mejores m\u00e9todos para quemar calor\u00edas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-field-image field-type-image field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<figure class=\"field-item\"><figcaption class=\"caption full-caption\">Con el fin de procurar una buena <label>salud<\/label> integral es importante desarrollar ciertos h\u00e1bitos de sue\u00f1o, como establecer un horario adecuado, realizar algunos estiramientos o practicar meditaci\u00f3n antes de acostarse y alejar todo estresante o estimulante 10 minutos antes de dormir, entre otros, incluyendo la <label>alimentaci\u00f3n<\/label>, para descansar mejor.<br \/>\n<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Por ello, te compartimos estos alimentos que fomentan el sue\u00f1o:<\/p>\n<p><strong>&#8211; Jugo de cereza. <\/strong>De acuerdo con un estudio de la Louisiana State University, al consumir este jugo dos veces al d\u00eda durante 2 semanas, es posible descansar en la noche durante 84 minutos m\u00e1s.<\/p>\n<p><strong>&#8211; Kiwi. <\/strong>Consumir esta fruta 1 hora antes de dormir puede generar resultados sorprendentes en relaci\u00f3n a las horas de sue\u00f1o (42.4% de mejor\u00eda, de acuerdo con Psychology Today).<\/p>\n<p><strong>&#8211; Algas. <\/strong>La Universidad de Oxford encontr\u00f3 una incidencia en el consumo de algas y el aumento de omega-3 DHA en la sangre, lo cual facilita el sue\u00f1o.<\/p>\n<p><strong>&#8211; Almendras.<\/strong>El Journal of Orthomolecular Medicine encontr\u00f3 que si un cuerpo sufre de bajos niveles de magnesio, normalmente presenta tambi\u00e9n problemas de sue\u00f1o, por lo que se recomienda incluir almendras en la dieta.<\/p>\n<p><strong>&#8211; Nueces,<\/strong> las cuales son una fuente incre\u00edble de melatonina (hormona del sue\u00f1o), fomentando la regulaci\u00f3n del ciclo cicardiano.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.ecoosfera.com\/2015\/01\/ya-sabes-cuales-son-los-alimentos-que-curan-el-insomnio\/\">Ecoosfera<\/a> \/ SAS<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dormir es un proceso vital para todo ser vivo, ya que permite al cuerpo descansar, recuperando energ\u00eda y regenerando c\u00e9lulas necesarias para las actividades de la vigilia. De ese modo, el cuerpo puede optimizar el funcionamiento del sistema inmunol\u00f3gico, cardiovascular, end\u00f3crino, digestivo, sexual, etc. E inclusive, es uno de los mejores m\u00e9todos para quemar calor\u00edas.<\/p>\n","protected":false},"author":3,"featured_media":36494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-36480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=36480"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36480\/revisions"}],"predecessor-version":[{"id":36495,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36480\/revisions\/36495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/36494"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=36480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=36480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=36480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}