{"id":36505,"date":"2015-01-11T07:17:41","date_gmt":"2015-01-11T11:17:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=36505"},"modified":"2015-01-10T18:22:11","modified_gmt":"2015-01-10T22:22:11","slug":"causas-del-ardor-al-orinar-en-las-mujeres","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/causas-del-ardor-al-orinar-en-las-mujeres\/","title":{"rendered":"Causas del ardor al orinar en las mujeres"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Ardor-al-orinar.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-36507 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Ardor-al-orinar.jpg\" alt=\"Ardor-al-orinar\" width=\"390\" height=\"252\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Ardor-al-orinar.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Ardor-al-orinar-300x193.jpg 300w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/a>\u00bfSientes dolor cuando vas al ba\u00f1o? \u00bfDolor al orinar? En ocasiones, esta realidad no se debe \u00fanicamente a una infecci\u00f3n. De hecho, debes saber que toda infecci\u00f3n en el tracto urinario tiene un origen que debemos conocer.Te damos todos los datos a continuaci\u00f3n y las posibles causas de dicha molestia.<!--more--><\/p>\n<h2>1. Infecci\u00f3n del tracto urinario<\/h2>\n<p>Por nuestra constituci\u00f3n femenina, somos nosotras quienes m\u00e1s solemos padecer de las cl\u00e1sicas infecciones de orina. Por lo general, se originan por bacterias que ingresan en la uretra y luego a la vejiga. Debemos ir con cuidado porque al iniciarse en la vejiga por ejemplo, puede proseguir despu\u00e9s en los ri\u00f1ones.<\/p>\n<p>Las mujeres, por lo general, tenemos la uretra un poco corta y situada cerca del ano, a diferencia de los hombres, que disponen de algo m\u00e1s de separaci\u00f3n. El ir a piscinas, el uso de diafragmas anticonceptivos, una mala higiene \u00edntima o incluso la actividad sexual, puede derivar en las molestas infecciones de orina. Vale la pena tenerlo en cuenta.<\/p>\n<p>Muchas veces un simple gesto es la causa, lo explicamos. Despu\u00e9s de orinar, debemos limpiarnos con el papel siempre desde la vagina hacia el ano, nunca en direcci\u00f3n inversa, pues de ese modo arrastrar\u00edamos bacterias que son propias del tracto digestivo al \u00e1rea genital que podr\u00edan causar una infecci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2014\/02\/s%C3%ADntomas-de-infecci%C3%B3n-urinaria1.jpg\" alt=\"s\u00edntomas-de-infecci\u00f3n-urinaria1\" width=\"495\" height=\"250\" \/><\/p>\n<h2>2. Una infecci\u00f3n de ri\u00f1\u00f3n<\/h2>\n<p>En ocasiones una infecci\u00f3n originada en la vejiga, y que no fue bien curada, puede extenderse al ri\u00f1\u00f3n. Como ya sabemos los ri\u00f1ones son los encargados de filtrar nuestra sangre, de producir la orina y eliminar aquello que el cuerpo no necesita. Puede suceder tambi\u00e9n, que en un momento dado, no realicemos tambi\u00e9n este filtrado de modo adecuado, que se acumulen toxinas y que con ello, se suceda una infecci\u00f3n que siempre deriva en el ardor al orinar.<\/p>\n<h2>3. C\u00e1lculos en la vejiga<\/h2>\n<p>Es algo no tan frecuente como la infecci\u00f3n del tracto urinario, pero debes saber que tambi\u00e9n es una causa directa del dolor al orinar. Pero \u00bfc\u00f3mo se producen los c\u00e1lculos en la vejiga? Los c\u00e1lculos vesicales aparecen cuando la orina que se encuentra en la vejiga se concentra, form\u00e1ndose cristales. A m\u00e1s cristales, m\u00e1s probabilidad de que aparezcan c\u00e1lculos.<\/p>\n<div>\n<div id=\"beacon_4494d11d8f\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ib.adnxs.com\/getuid?http%3a%2f%2fdis.ny.us.criteo.com%2frex%2fmatch.aspx%3fc%3d11%26uid%3d%24UID\" alt=\"\" width=\"0\" height=\"0\" \/><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/cat.ny.us.criteo.com\/delivery\/lg.php?cppv=1&amp;cpp=S5M7MHxiQ3BxZHhwTDVjclRaWXhXcXhyMzUyZlNVQ2FEWlVabHMrZWp0aVFud1E0S3R5QjVZYmpQMFQwb3F0S0owOGloQ08xczBJbUd6eGRyWWxtRzRXOGhUUW1HTTZDbzBmNU1US29rZmN0TndmMmgzQ1ZCSWJDbXQ2VGVzL3cwcjU2aFZQR0R4MnRTQVlVREJld1FiZ2VvMVczb2M1dy9uaTB5cHREQ1FMLzVDUjlyK3hkMmVjZzExcGl2c2Fkb3pEYVBJLytWN3FqNG9SNjJ5QnQ3bzlTLzRnPT18\" alt=\"\" width=\"0\" height=\"0\" \/><\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2013\/12\/Ri%C3%B1ones.jpg\" alt=\"Ri\u00f1ones\" width=\"500\" height=\"375\" \/><\/p>\n<h2>4. Vaginitis<\/h2>\n<p>Seg\u00fan nos dicen los m\u00e9dicos, la mayor\u00eda de nosotras padeceremos en alguna ocasi\u00f3n vaginitis. \u00bfDe qu\u00e9 se trata? Es una inflamaci\u00f3n de la pared mucosa de la vagina, ser\u00eda lo que se conoce como vulvovaginitis, un problema ginecol\u00f3gico muy habitual. Un s\u00edntoma para advertirlo es cuando nuestro flujo deja de tener el caracter\u00edstico tono blanquecino. Si alg\u00fan d\u00eda notas que es algo m\u00e1s oscuro, que adquiere un olor muy desagradable y sientes adem\u00e1s ardor al orinar, acude a tu m\u00e9dico para que te ofrezca el tratamiento m\u00e1s adecuado.<\/p>\n<h2>5. Clamidia<\/h2>\n<p>La clamidia es una enfermedad de transmisi\u00f3n sexual, se trata de una de las m\u00e1s comunes. La podemos padecer tanto nosotras como los hombres, y un modo en que nos daremos cuenta es sobre todo al ir al ba\u00f1o. Sentiremos ardor al orinar, adem\u00e1s de molestias en la parte baja de la espalda, las ingles y la cadera. Es una infecci\u00f3n, y como tal debe tratarse. Debemos ir con mucho cuidado con este tipo de enfermedades de trasmisi\u00f3n de sexual.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.mejorconsalud.com\/wp-content\/uploads\/2013\/10\/Infeccion-de-Orina-500x253.jpg\" alt=\"Infeccion-de-Orina\" width=\"500\" height=\"253\" \/><\/p>\n<h2>6. Herpes<\/h2>\n<p>El herpes genital puede ser otra causa a tener en cuenta a la hora de buscar los or\u00edgenes del ardor al orinar. Los m\u00e9dicos nos dicen que, en ocasiones, un herpes puede cursar sin demasiados s\u00edntomas, o incluso podemos confundirlos con una simple infecci\u00f3n del tracto urinario. Pero tarde o temprano nos aparecer\u00e1 alguna llaga, alguna ampolla. Esto se da cuando mantenemos relaciones con personas que a su vez, tambi\u00e9n tienen herpes genital. El contacto entre mucosas -y m\u00e1s si hay alg\u00fan tipo de llaga o ampolla- favorece esta aparici\u00f3n.<\/p>\n<p>Con ello, queremos decirte que hay ocasiones en que el ardor al orinar en la mujer puede deberse a enfermedades de trasmisi\u00f3n sexual.<\/p>\n<h2>7. Irritaci\u00f3n de los tejidos vaginales<\/h2>\n<p>Hay veces en que se nos pasa por alto y no pensamos en ello. De pronto sentimos ardor al orinar y pensamos de inmediato en una infecci\u00f3n, en un problema de ri\u00f1\u00f3n. Pero ten en cuenta que hay muchos elementos que utilizamos para nuestra higiene \u00edntima que puede causarnos reacciones al\u00e9rgicas, adem\u00e1s de irritaci\u00f3n.<\/p>\n<p>Lociones, jabones, cremas, e incluso alg\u00fan tipo de compresas o ropa interior, puede ocasionar una repentina reacci\u00f3n en nuestro cuerpo. Debes ser t\u00fa misma la que deduzca qu\u00e9 ha podido ser. Si ves que pasan dos d\u00edas y la molestia no desaparece, acude a tu m\u00e9dico.<\/p>\n<p>Para concluir, cada vez que sientas ardor al orinar, lo mejor es ir al m\u00e9dico para que nos hagan un an\u00e1lisis de orina con el cual, deducir a qu\u00e9 se debe y cu\u00e1l es su origen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSientes dolor cuando vas al ba\u00f1o? \u00bfDolor al orinar? En ocasiones, esta realidad no se debe \u00fanicamente a una infecci\u00f3n. De hecho, debes saber que toda infecci\u00f3n en el tracto urinario tiene un origen que debemos conocer.Te damos todos los datos a continuaci\u00f3n y las posibles causas de dicha molestia.<\/p>\n","protected":false},"author":3,"featured_media":36507,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-36505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=36505"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36505\/revisions"}],"predecessor-version":[{"id":36508,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36505\/revisions\/36508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/36507"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=36505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=36505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=36505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}