{"id":36572,"date":"2015-01-11T16:00:17","date_gmt":"2015-01-11T20:00:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=36572"},"modified":"2015-01-11T11:35:07","modified_gmt":"2015-01-11T15:35:07","slug":"que-nos-dicen-los-perros-cuando-ladran","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-nos-dicen-los-perros-cuando-ladran\/","title":{"rendered":"\u00bfQu\u00e9 nos dicen los perros cuando ladran?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Que-nos-dicen-los-perros-cuando-ladran-000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36573 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Que-nos-dicen-los-perros-cuando-ladran-000-300x200.jpg\" alt=\"Que-nos-dicen-los-perros-cuando-ladran-000\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Que-nos-dicen-los-perros-cuando-ladran-000-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Que-nos-dicen-los-perros-cuando-ladran-000.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La forma de comunicarse de los perros es mediante el ladrido, pero \u00bfpor qu\u00e9 lo hacen? En realidad no tenemos una forma de saber exactamente qu\u00e9 quieren decir con cada ladrido&#8230; \u00bfo si? Parece que los d\u00edas de incertidumbre se han acabado, un grupo de cient\u00edficos tiene la respuesta.<!--more--><\/p>\n<p><strong>Perro que ladra no muerde&#8230; y dice muchas cosas<\/strong><\/p>\n<p>Luego de haber analizado unos 6000 ladridos emitidos por la raza Mudi, cient\u00edficos de la Universidad E\u00f6tv\u00f6vs, de Hungr\u00eda, ha elaborado un <label>software<\/label> capaz de adivinar qu\u00e9 es lo que los perros nos quieren decir con sus ladridos. Antes de profundizar sobre la investigaci\u00f3n, es importante hacer una aclaraci\u00f3n. Esta universidad h\u00fangara se caracteriza por dedicarse a investigaciones absurdas y bizarras.<\/p>\n<p>El margen de acierto de este programa es de un 43%, pues se encuentra en pleno desarrollo, aunque se espera que logre un 100% de efectividad cuando se complete su elaboraci\u00f3n. Fueron analizados los 6000 ladridos y las situaciones que pudieron ser codificadas por el software son palabras como \u201cjugar\u201d, \u201cpaseo\u201d, \u201cextra\u00f1o\u201d, \u201cataque\u201d, \u201csolo\u201d y \u201cpelota\u201d.<\/p>\n<p>Seg\u00fan los cient\u00edficos, las m\u00e1s sencillas de codificar fueron \u201cataque\u201d y \u201cextra\u00f1o\u201d, mientras que la m\u00e1s compleja fue \u201cjugar\u201d. Interesante, \u00bfno lo crees? \u00bfTe imaginas comunic\u00e1ndote as\u00ed con tu perro? \u00bfCrees que es posible?<\/p>\n<p>Sin dudas estos cient\u00edficos han ido demasiado lejos&#8230; \u00bfno ser\u00e1 mucho intentar decodificar los ladridos de un perro? Si ladra simplemente d\u00e9jalo salir a hacer sus necesidades y dale el <label>alimento<\/label> que necesita. <label>Seguro<\/label> se deja de molestar. \u00bfT\u00fa qu\u00e9 opinas? \u00bfTe gustan los perros?<\/p>\n<p>Fuente: <a href=\"http:\/\/curiosidades.batanga.com\/2008\/01\/21\/%C2%BFque-dicen-los-perros-cuando-ladran\" target=\"_blank\">Ojo Cient\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La forma de comunicarse de los perros es mediante el ladrido, pero \u00bfpor qu\u00e9 lo hacen? En realidad no tenemos una forma de saber exactamente qu\u00e9 quieren decir con cada ladrido&#8230; \u00bfo si? Parece que los d\u00edas de incertidumbre se han acabado, un grupo de cient\u00edficos tiene la respuesta.<\/p>\n","protected":false},"author":3,"featured_media":36573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-36572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=36572"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36572\/revisions"}],"predecessor-version":[{"id":36574,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36572\/revisions\/36574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/36573"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=36572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=36572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=36572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}