{"id":36585,"date":"2015-01-11T18:05:28","date_gmt":"2015-01-11T22:05:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=36585"},"modified":"2015-01-11T12:08:22","modified_gmt":"2015-01-11T16:08:22","slug":"cuantos-anos-tienen-las-estrellas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuantos-anos-tienen-las-estrellas\/","title":{"rendered":"\u00bfCu\u00e1ntos a\u00f1os tienen las estrellas?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Cuantos-anos-tienen-las-estrellas-000.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36586 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Cuantos-anos-tienen-las-estrellas-000-300x200.jpg\" alt=\"Cuantos-anos-tienen-las-estrellas-000\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Cuantos-anos-tienen-las-estrellas-000-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/Cuantos-anos-tienen-las-estrellas-000.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Los investigadores de la NASA descubrieron que se puede calcular la edad de una estrella bas\u00e1ndose en la <label>velocidad<\/label> a la que parece trasladarse. Las estrellas pierden velocidad a medida que envejecen y gracias a ello los cient\u00edficos se pueden acercar a la edad exacta de cada una con tan <label>solo<\/label> un 10% de margen de error.<!--more--><\/p>\n<p>\u00bfSiempre existieron las mismas estrellas? Hoy en <label>d\u00eda<\/label> sabemos que no. Las estrellas \u00abnacen\u00bb y \u00abmueren\u00bb y las que hoy vemos en el <label>cielo<\/label> no siempre estuvieron y de hecho, quiz\u00e1s ya no existan m\u00e1s. Por ejemplo, hace unos a\u00f1os los cient\u00edficos anunciaron que una de las Tres Mar\u00edas ha muerto, sin embargo, si miramos el cielo en la noche, todav\u00eda la podemos ver. Esto es porque las estrellas est\u00e1n tan lejos nuestro, que su luz demora cientos de miles de a\u00f1os en llegar, por lo tanto, la luz que vemos cada noche, es en realidad la luz de hace millones de a\u00f1os.<\/p>\n<p><strong>Dime qu\u00e9 tan r\u00e1pido gira y te dir\u00e9 cu\u00e1ntos a\u00f1os tiene<\/strong><\/p>\n<p>En el espacio <label>todo<\/label> est\u00e1 en movimiento, y gracias a ello los cient\u00edficos lograron determinar la edad de cada estrella. Los investigadores de la NASA descubrieron que se puede calcular la edad de una estrella bas\u00e1ndose en la velocidad a la que parece trasladarse.<\/p>\n<p>Al igual que los humanos, las estrellas pierden velocidad a medida que envejecen y gracias a ello los cient\u00edficos se pueden acercar a la edad exacta de cada una con tan solo un 10% de margen de error. Vale tener en cuenta, adem\u00e1s, que un 10% en tantos cientos de millones de a\u00f1os no representa un margen de error tan grave.<\/p>\n<p>Conocer la edad de las estrellas es de fundamental importancia para el estudio de los exoplanetas, las posibilidades de vida extraterrestre y el conocimiento sobre el espacio en general. Pero \u00bfpor qu\u00e9?<\/p>\n<p>Bueno, t\u00e9cnicamente los planetas de un sistema se forman junto con su estrella. Es decir, al mismo tiempo: si podemos calcular la edad de una estrella, sabremos la edad de sus planetas. Adem\u00e1s, sabemos que cuanto m\u00e1s longevo es un planeta, m\u00e1s posibilidades existen de que se desarrolle la vida.<\/p>\n<p>Los cient\u00edficos sostienen que existe una fuerte relaci\u00f3n entre la masa, la velocidad y la edad de una estrella y aseguran que si las dos primeras variables pueden ser conocidas, la tercera -la edad- puede ser calculada. Interesante, \u00bfno lo crees?<\/p>\n<p><a href=\"http:\/\/informe21.com\/sites\/default\/files\/imagepicker\/e\/Editor%20AJ\/Cuantos-anos-tienen-las-estrellas-003.png\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"imgp_img\" src=\"http:\/\/informe21.com\/sites\/default\/files\/imagepicker\/e\/Editor%20AJ\/thumbs\/Cuantos-anos-tienen-las-estrellas-003.png\" alt=\"Image\" width=\"600\" height=\"404\" \/><\/a><\/p>\n<p>Ellos est\u00e1n especialmente interesados en las estrellas como nuestro sol, brillantes y relativamente fr\u00edas, ya que son el tipo m\u00e1s abundante de estrella en nuestra galaxia, la V\u00eda L\u00e1ctea. Estas estrellas no cambian radicalmente a lo largo de su \u00abvida\u00bb por lo tanto es muy dif\u00edcil para los astr\u00f3nomos determinar su edad.<\/p>\n<p>Desde el a\u00f1o 2009 el Sat\u00e9lite Kepler, que busca planetas extrasolares y ayuda a medir el brillo de las estrellas, los cient\u00edficos han podido acercarse cada vez m\u00e1s al c\u00e1lculo de la edad exacta de una estrella.<\/p>\n<p>El estudio de cada estrella puede llevar meses e incluso a\u00f1os de observaci\u00f3n y an\u00e1lisis. Calcular la edad exacta de una estrella es muy dif\u00edcil, adem\u00e1s, por las magn\u00edficas unidades de medida que los cient\u00edficos deben utilizar. No sirve de mucho hablar de kil\u00f3metros o a\u00f1os cuando estamos pensando en cuerpos celestes que se encuentran a semejantes distancias.<\/p>\n<p>A\u00fan as\u00ed, vale la pena intentarlo, \u00bfno lo crees? Quiz\u00e1s de esta forma estemos m\u00e1s cerca de conocer las formas de vida que seguramente existen en otras partes del universo.<\/p>\n<p>Fuente: <a href=\"http:\/\/curiosidades.batanga.com\/7806\/cuantos-anos-tienen-las-estrellas\" target=\"_blank\">Ojo cient\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los investigadores de la NASA descubrieron que se puede calcular la edad de una estrella bas\u00e1ndose en la velocidad a la que parece trasladarse. Las estrellas pierden velocidad a medida que envejecen y gracias a ello los cient\u00edficos se pueden acercar a la edad exacta de cada una con tan solo un 10% de margen de error.<\/p>\n","protected":false},"author":3,"featured_media":36586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-36585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=36585"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36585\/revisions"}],"predecessor-version":[{"id":36587,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36585\/revisions\/36587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/36586"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=36585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=36585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=36585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}