{"id":36890,"date":"2015-01-18T17:01:17","date_gmt":"2015-01-18T21:01:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=36890"},"modified":"2015-01-17T21:28:29","modified_gmt":"2015-01-18T01:28:29","slug":"el-picante-del-pimiento-tiene-propiedades-y-potenciales-beneficios-para-la-salud","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-picante-del-pimiento-tiene-propiedades-y-potenciales-beneficios-para-la-salud\/","title":{"rendered":"El picante del pimiento tiene propiedades y potenciales beneficios para la salud"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/pimientos-picantes.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-36894 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/pimientos-picantes.jpg\" alt=\"pimientos picantes\" width=\"273\" height=\"185\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/pimientos-picantes.jpg 273w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/pimientos-picantes-75x52.jpg 75w\" sizes=\"auto, (max-width: 273px) 100vw, 273px\" \/><\/a>Los amantes del picante disfrutan de las bondades del chile o pimiento, una pieza fundamental en culturas gastron\u00f3micas de todo el planeta. Detr\u00e1s de la sensaci\u00f3n de picor est\u00e1\u00a0<strong>la capsaicina, una sustancia que abre las puertas de la investigaci\u00f3n<\/strong>\u00a0por los potenciales beneficios vinculados a su consumo moderado.<!--more--><\/p>\n<p><span class=\"auxiliary float right\">Enga\u00f1a al sistema nervioso central y cambia el foco de atenci\u00f3n del dolor<\/span>Son muchos los usos y beneficios que asocian a los pimientos ricos en capsaicina. Entre ellos, su empleo como<strong>\u00a0analg\u00e9sico en patolog\u00edas como psoriasis, artritis reumatoide o neuralgias<\/strong>. El director en\u00a0Instituto de Nutrici\u00f3n y Tecnolog\u00eda de los Alimentos\u00a0de la Universidad de Granada y Catedr\u00e1tico de Fisiolog\u00eda en la misma, Jes\u00fas Rodr\u00edguez Huertas, explica que la acci\u00f3n calmante de esta sustancia se debe a que \u201cen dosis bajas y controladas act\u00faa sobre los receptores del dolor y cambia el foco de atenci\u00f3n enga\u00f1ando al sistema nervioso central\u201d.<\/p>\n<p>A esta sustancia qu\u00edmica tambi\u00e9n se le atribuyen otras virtudes, desde poder anticancer\u00edgeno hasta su acci\u00f3n como adelgazante, pasando por cualidades de afrodis\u00edaco. Sin embargo, Rodr\u00edguez advierte que\u00a0<strong>hay que ser cauto porque \u201clo que conocemos es muy poco<\/strong>, hay que investigar y trabajar mucho, lo que s\u00ed es cierto es que tiene un potencial enorme en distintas aplicaciones\u201d.<\/p>\n<p>El especialista se\u00f1ala que las investigaciones que han demostrado los\u00a0<strong>beneficios de la capsaicina en el tratamiento de algunos c\u00e1nceres como el de pulm\u00f3n<\/strong>\u00a0son todos estudios en cultivos celulares. Estos hallazgos apuntan que, selectivamente, la capsaicina es capaz de destruir muchas de las c\u00e9lulas cancer\u00edgenas sin alterar mucho las sanas.<\/p>\n<p>La capsaicina tiene acci\u00f3n adelgazante y poder afrodis\u00edacoEl especialista afirma: \u201cEstamos intentando hacer un proyecto de investigaci\u00f3n para probar que la quimioterapia y la radioterapia\u00a0<strong>ser\u00edan m\u00e1s eficientes si a trav\u00e9s de la dieta incrementamos la cantidad de capsaicina<\/strong>\u00a0como coadyuvante, pero est\u00e1 una fase inicial\u201d.<\/p>\n<p>Pero al mismo tiempo, la capsaicina\u00a0<strong>puede incrementar la incidencia en algunos tipos de c\u00e1ncer del tubo digestivo<\/strong>, sobre todo de la parte media-superior. Rodriguez no recomienda la ingesta de pimientos picantes a personas con propensi\u00f3n al\u00a0c\u00e1ncer\u00a0de colon o est\u00f3mago.<\/p>\n<p>Aunque parezca una paradoja, el especialista se\u00f1ala que \u201cen el est\u00f3mago se produce un gran contacto con la capsaicina y cuando las cantidades son elevadas y mantenidas en el tiempo act\u00faan sobre los epitelios y\u00a0<strong>pueden alterarlos en un porcentaje bajo que es preocupante<\/strong>\u201d.<\/p>\n<h2>El picante adelgaza y \u201cexcita\u201d<\/h2>\n<p>La acci\u00f3n adelgazante asociada a la capsaicina se basa en realidad\u00a0<strong>en la quema de grasa derivada del incremento del estr\u00e9s oxidativo<\/strong>; \u00e9ste siempre genera una serie de da\u00f1os en c\u00e9lulas sanas que aunque son tolerables y no pueden inducir otras patolog\u00edas, han de ser reparados y, para lograrlo, las c\u00e9lulas invierten una cantidad de energ\u00eda extra que requiere consumir m\u00e1s triglic\u00e9ridos.<\/p>\n<p>En cuanto al\u00a0<strong>poder de la capsaicina como afrodis\u00edaco<\/strong>, Rodr\u00edguez sostiene que aunque de forma emp\u00edrica el efecto es muy fuerte en sujetos que est\u00e1n relativamente habituados a una ingesta media de la sustancia, no hay estudios cient\u00edficos que lo demuestren. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los amantes del picante disfrutan de las bondades del chile o pimiento, una pieza fundamental en culturas gastron\u00f3micas de todo el planeta. Detr\u00e1s de la sensaci\u00f3n de picor est\u00e1\u00a0la capsaicina, una sustancia que abre las puertas de la investigaci\u00f3n\u00a0por los potenciales beneficios vinculados a su consumo moderado.<\/p>\n","protected":false},"author":3,"featured_media":36894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-36890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=36890"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36890\/revisions"}],"predecessor-version":[{"id":36895,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/36890\/revisions\/36895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/36894"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=36890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=36890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=36890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}