{"id":37153,"date":"2015-01-20T10:25:55","date_gmt":"2015-01-20T14:25:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=37153"},"modified":"2015-01-20T10:25:55","modified_gmt":"2015-01-20T14:25:55","slug":"perez-y-sierra-guian-el-triunfo-de-gigantes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/perez-y-sierra-guian-el-triunfo-de-gigantes\/","title":{"rendered":"P\u00e9rez y Sierra gu\u00edan el triunfo de Gigantes"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/gigantes-ganan-primero.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37154 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/gigantes-ganan-primero.jpeg\" alt=\"gigantes ganan primero\" width=\"294\" height=\"196\" \/><\/a>Las rachas llegaron a su fin. Los Gigantes del Cibao, que habian perdido seis partidos seguidos finalmente dejaron atr\u00e1s la pesadilla por la cual atravesaban y conquistaron su primera victoria de la serie final, tras blanquear 4-0 a las Estrellas Orientales en el tercer choque del evento.<!--more--><\/p>\n<p>El zurdo Rafael P\u00e9rez encabez\u00f3 a cuatro lanzadores, quienes se combinaron para detener el gran empuje mostrado por los paquidermos en los dos primeros encuentros y colocarle un mayor ritmo a la final, que en los dos primeros choques solo hab\u00eda sentido la gran algarab\u00eda de los parciales verdes.<\/p>\n<p>A diferencias de sus dos colegas anteriores, el espigado P\u00e9rez si fue capaz de navegar una larga ruta, de 6.2 de entradas en su caso y con una mezcla magistral de sus pitcheos pudo dominar a unas Estrellas, que en los dos primeros compromisos habian desplegado una soberbia ofensiva, con 18 vueltas, al comp\u00e1s de 29 imparables, de los cuales nueve fueron dobletes y cuatro jonrones.<\/p>\n<p>El ex- grandesligas apenas permiti\u00f3 dos aislados imparables, un sencillo de Gustavo N\u00fa\u00f1ez, leugo de un out en el primero y otro de Robinson Can\u00f3 iniciado el segundo cap\u00edtulo. Otorg\u00f3 dos boletos y abanic\u00f3 a tres. Su labor recibi\u00f3 el soporte de los relevistas Michael Mariot, Zach Jackson y Ram\u00f3n Ram\u00edrez, quien acept\u00f3 un triple de Junior Lake en el noveno, siendo esta una de las principales amenazas.<\/p>\n<p>En la ofensiva, Mois\u00e9s Sierra bate\u00f3 de 3-3, incluyendo un doble, Jean Segura y Maikel Franco conectaron dos imparables cada uno para los Gigantes, que produjeron ocho incogibles y se aprovecharon de un par de costosos errores por parte de la defensa oriental.<\/p>\n<p>Por primera vez en la serie, Los nordestanos se vieron en la jornada delante en la serie, tras su rally de tres vueltas en el quinto episodio.<\/p>\n<p>Evan MaClane, el abridor de las Estrellas permaneci\u00f3 durante cinco entradas en el box, acept\u00f3 cinco imparables, permiti\u00f3 tres carreras, pero solo una de ella fue limpia, abanic\u00f3 a uno. Las Estrellas tuvieron escasas amenazas de anotar carreras.<\/p>\n<p><b>Las carreras<\/b><br \/>\nEn el quinto inning los Gigantes anotaron tres carreras. Mois\u00e9s Sierra dio sencillo y lleg\u00f3 a tercera con imparable al prado derecho de Hansel Alberto y en el tiro del jardinero Mike \u00a0Bianucci, Alberto arrib\u00f3 a segunda. Carlos Paulino fue dominado con elevado corto al jard\u00edn central que Bianucci no pudo retener, anotando Sierra, y Alberto tambi\u00e9n anot\u00f3 por error en tiro del segunda base Michael Mart\u00ednez. En la jugada, Paulino se instal\u00f3 en tercera y anot\u00f3 tras elevado de sacrificio de Mel Rojas al prado derecho.<\/p>\n<p>La cuarta carrera de los Gigantes aconteci\u00f3 en el noveno ante el relevista Ram\u00f3n Benjam\u00edn, quien otorg\u00f3 boleto a Carlos Paulino, el cual se instal\u00f3 en segunda por sacrificio de Mel Rojas y luego anot\u00f3 con doble al bosque de la izquierda de Jean Segura.<\/p>\n<p><a href=\"http:\/\/www.listindiario.com\/el-deporte\/2015\/1\/20\/353266\/Rafael-Perez-y-Moises-Sierra-guian-el-triunfo-de-Gigantes\">FUENTE<\/a><br \/>\nPor:\u00a0<b>Pedro G. Brice\u00f1o<br \/>\n<\/b><b>Santo Domingo<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las rachas llegaron a su fin. Los Gigantes del Cibao, que habian perdido seis partidos seguidos finalmente dejaron atr\u00e1s la pesadilla por la cual atravesaban y conquistaron su primera victoria de la serie final, tras blanquear 4-0 a las Estrellas Orientales en el tercer choque del evento.<\/p>\n","protected":false},"author":12,"featured_media":37154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-37153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=37153"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37153\/revisions"}],"predecessor-version":[{"id":37155,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37153\/revisions\/37155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/37154"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=37153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=37153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=37153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}