{"id":37710,"date":"2015-04-05T00:55:09","date_gmt":"2015-04-05T04:55:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=37710"},"modified":"2015-01-29T22:14:19","modified_gmt":"2015-01-30T02:14:19","slug":"sientes-calor-en-la-noche-sigue-estos-consejos-para-dormir-fresco","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sientes-calor-en-la-noche-sigue-estos-consejos-para-dormir-fresco\/","title":{"rendered":"\u00bfSientes calor en la noche? Sigue estos consejos para dormir fresco"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-long field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/secondaryimage_650.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37713 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/secondaryimage_650.jpg\" alt=\"secondaryimage_650\" width=\"392\" height=\"294\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/secondaryimage_650.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/secondaryimage_650-300x225.jpg 300w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/a>Es normal que la temperatura se eleve considerablemente, lo que puede generar cierto fastidio, sobre <label>todo<\/label> por las noches cuando nos vamos a la cama a descansar. Y es que muchas veces ni abriendo las ventanas se logra tener un ambiente fresco, lo que puede dificultar el sue\u00f1o o incluso causar insomnio.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden view-mode-full\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Es por eso que el portal <label>web<\/label>biobiochile.cl, entreg\u00f3 una lista con 8 consejos para combatir el calor durante las noches y poder dormir fresco.<\/p>\n<p>&#8211; Durante el <label>d\u00eda<\/label>hay que hidratarse tomando por lo menos tres litros de <label>agua<\/label>, as\u00ed el<label>cuerpo<\/label> se mantendr\u00e1 hidratado hasta la noche.<\/p>\n<p>&#8211; Se debe mantener ventilada la habitaci\u00f3n para que no se concentre calor.<\/p>\n<p>&#8211; No hay que hacer ejercicios antes de dormir pues la pr\u00e1ctica de deportes libera adrenalina y noradrenalina lo que hace que el cuerpo se sienta activo. Es mejor hacer alguna t\u00e9cnica de relajaci\u00f3n que permita conciliar el sue\u00f1o m\u00e1s r\u00e1pido.<\/p>\n<p>&#8211; Antes de dormir es recomendable tomar una ducha tibia de cinco minutos, el agua a esa temperatura ayuda a tener una sensaci\u00f3n de frescura m\u00e1s duradera.<\/p>\n<p>&#8211; Dormir con pijama de algod\u00f3n es lo mejor para las noches de calor ya que permite la absorci\u00f3n de la transpiraci\u00f3n. Al contrario de lo que se cree, dormir desnudo no es lo m\u00e1s recomendable puesto que no se evapora la humedad que existe entre el cuerpo y la cama.<\/p>\n<p>&#8211; Dormir de costado es una buena idea ya que es la posici\u00f3n que menos se pega a las s\u00e1banas, prolongando la sensaci\u00f3n de frescura.<\/p>\n<p>&#8211; Durante la noche es mejor consumir comidas livianas a base de verduras. Hay que evitar las grasas saturadas porque necesitan mucha agua para digerir.<\/p>\n<p>&#8211; De ser posible, usa un ventilador o aire acondicionado peque\u00f1o en la habitaci\u00f3n que refresque el ambiente. Ten en cuenta que no debes colocarlo frente a ti sino de forma indirecta.<\/p>\n<p><strong>Fuente:<\/strong> <a href=\"http:\/\/www.rpp.com.pe\/2015-01-28--sientes-calor-en-la-noche--sigue-estos-consejos-para-dormir-fresco-noticia_764204.html\" target=\"_blank\">RPP<\/a> \/ AM<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Es normal que la temperatura se eleve considerablemente, lo que puede generar cierto fastidio, sobre todo por las noches cuando nos vamos a la cama a descansar. Y es que muchas veces ni abriendo las ventanas se logra tener un ambiente fresco, lo que puede dificultar el sue\u00f1o o incluso causar insomnio.<\/p>\n","protected":false},"author":12,"featured_media":37713,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-37710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=37710"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37710\/revisions"}],"predecessor-version":[{"id":37714,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37710\/revisions\/37714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/37713"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=37710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=37710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=37710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}