{"id":37839,"date":"2015-01-31T00:09:45","date_gmt":"2015-01-31T04:09:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=37839"},"modified":"2015-01-31T00:09:45","modified_gmt":"2015-01-31T04:09:45","slug":"robbie-coltrane-hagrid-en-harry-potter-hospitalizado-tras-un-vuelo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/robbie-coltrane-hagrid-en-harry-potter-hospitalizado-tras-un-vuelo\/","title":{"rendered":"Robbie Coltrane, Hagrid en \u00abHarry Potter\u00bb, hospitalizado tras un vuelo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/hagrid-harry-potter-hospitalizado-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37842 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/hagrid-harry-potter-hospitalizado-644x362.jpg\" alt=\"hagrid-harry-potter-hospitalizado--644x362\" width=\"644\" height=\"362\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/hagrid-harry-potter-hospitalizado-644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/hagrid-harry-potter-hospitalizado-644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><br \/>\nEl actor escoc\u00e9s Robbie Coltrane, conocido por su papel de Hagrid en la saga \u00abHarry Potter\u00bb, fue hospitalizado este jueves con s\u00edntomas similares a una fuerte gripe, tras un vuelo de Londres a Orlando (Florida), seg\u00fan informa la web TMZ, que cita a un representante del int\u00e9rprete.<!--more--><\/p>\n<p>Coltrane, de 64 a\u00f1os, se encontr\u00f3 mal durante el vuelo y un equipo de param\u00e9dicos, que se encontraba preparado en el aeropuerto de la ciudad estadounidense, le traslad\u00f3 de inmediato a un hospital, donde qued\u00f3 ingresado para su tratamiento.<\/p>\n<p>El actor viajaba a Orlando para acudir a una convenci\u00f3n sobre Harry Potter en compa\u00f1\u00eda de otro de los actores de la franquicia, Michael Gambon, quien interpret\u00f3 a Dumbledore, el director de la escuela Hogwarts, donde estudian los protagonistas de las historias ideadas por la escritora J. K. Rowling.<\/p>\n<p>Coltrane, que debut\u00f3 en el cine en 1980, es mundialmente conocido por encarnar a Hagrid, el enorme guardabosques y posteriormente profesor que a menudo act\u00faa como protector de Harry y sus amigos Hermione y Ron. En su carrera se cuentan tambi\u00e9n papeles como \u00abGoldenEye\u00bb, \u00abDesde el infierno\u00bb e \u00abBrave (Indomable)\u00bb (en esta \u00faltima, de animaci\u00f3n, presta su voz). Su \u00faltimo trabajo hasta la fecha es \u00abEffie Gray\u00bb, protagonizada porEmma Thompson y Dakota Fannin<a href=\"http:\/\/hoycinema.abc.es\/perfil-tv\/dakota-fanning-122214\/\">g<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor escoc\u00e9s Robbie Coltrane, conocido por su papel de Hagrid en la saga \u00abHarry Potter\u00bb, fue hospitalizado este jueves con s\u00edntomas similares a una fuerte gripe, tras un vuelo de Londres a Orlando (Florida), seg\u00fan informa la web TMZ, que cita a un representante del int\u00e9rprete.<\/p>\n","protected":false},"author":12,"featured_media":37842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-37839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=37839"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37839\/revisions"}],"predecessor-version":[{"id":37845,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37839\/revisions\/37845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/37842"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=37839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=37839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=37839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}