{"id":37897,"date":"2015-01-31T19:29:32","date_gmt":"2015-01-31T23:29:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=37897"},"modified":"2015-01-31T19:29:32","modified_gmt":"2015-01-31T23:29:32","slug":"empanadas-de-salchichas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/empanadas-de-salchichas\/","title":{"rendered":"Empanadas de salchichas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-37903 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/empanadas-de-sanchichas.jpg\" alt=\"empanadas de sanchichas\" width=\"486\" height=\"324\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/empanadas-de-sanchichas.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/01\/empanadas-de-sanchichas-300x200.jpg 300w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><br \/>\nUna <strong>empanada<\/strong> con forma de trenza y rellena de salchichas. Un estupendo segundo plato para los m\u00e1s peque\u00f1os de la casa.<!--more--><\/p>\n<p>La <strong>masa de la empanada<\/strong> es totalmente casera que hicimos en la Thermomix pero que se puede hacer a mano perfectamente. Solo tienes que poner los ingredientes en un bol y primero ligar y luego amasar hasta tener una masa bien lisa y el\u00e1stica para comenzar con la empanada.<\/p>\n<p>El relleno bien sencillo, un sofrito de verduras y salchichas tipo Frankfurt.<\/p>\n<p>Para los m\u00e1s peque\u00f1os o para los m\u00e1s grandes, a tu gusto. \u00bfTe animas con esta <strong>trenza de empanada de salchichas<\/strong>? Pues comenzamos.<\/p>\n<div class=\"easyrecipe\">\n<div class=\"ERSSavePrint\"><\/div>\n<div class=\"ERSDetails\">\n<div class=\"ERSAuthor\"><strong>Ingredientes<\/strong><\/div>\n<\/div>\n<div class=\"ERSIngredients\">\n<ul>\n<li class=\"ingredient\">Para la masa: 25 gr de agua<\/li>\n<li class=\"ingredient\">25 gr de aceite de oliva virgen extra<\/li>\n<li class=\"ingredient\">25 gr de vino blanco<\/li>\n<li class=\"ingredient\">45 gr de manteca de cerdo o de mantequilla<\/li>\n<li class=\"ingredient\">1 huevo peque\u00f1o<\/li>\n<li class=\"ingredient\">15 gr de levadura fresca<\/li>\n<li class=\"ingredient\">250 gr de harina de trigo<\/li>\n<li class=\"ingredient\">1 poco de sal<\/li>\n<li class=\"ingredient\">Para el relleno 1 cebolla<\/li>\n<li class=\"ingredient\">1 zanahoria<\/li>\n<li class=\"ingredient\">1 diente de ajo<\/li>\n<li class=\"ingredient\">1 pimiento verde<\/li>\n<li class=\"ingredient\">2 tomates rojos y maduros<\/li>\n<li class=\"ingredient\">50 gr de aceite<\/li>\n<li class=\"ingredient\">Sal<\/li>\n<li class=\"ingredient\">Pimienta molida<\/li>\n<li class=\"ingredient\">1 paquete de salchichas<\/li>\n<\/ul>\n<div class=\"ERSClear\"><\/div>\n<\/div>\n<div class=\"ERSInstructions\">\n<div class=\"ERSInstructionsHeader ERSHeading\"><strong>Instrucciones<\/strong><\/div>\n<ol>\n<li class=\"instruction\">Ponemos en el vaso de la Thermomix el agua con el aceite, el vino y la manteca. Seleccionamos 1 minutos velocidad 2, 37 grados.<\/li>\n<li class=\"instruction\">Agregamos el huevo y la levadura. Seleccionamos 5 segundos velocidad 4.<\/li>\n<li class=\"instruction\">A\u00f1adimos la sal y la harina.<\/li>\n<li class=\"instruction\">Mezclamos seleccionando 15 segundos velocidad 6 y 2 minutos vaso cerrado, velocidad espiga.<\/li>\n<li class=\"instruction\">Sacamos la masa y reservamos.<\/li>\n<li class=\"instruction\">Ahora ponemos en el vaso limpio y seco la cebolla pelada y en cuartos, el ajo pelado, el pimiento sin semillas , la zanahoria pelada y troceada y el tomate en cuartos.<\/li>\n<li class=\"instruction\">Seleccionamos 5 segundos velocidad 5.<\/li>\n<li class=\"instruction\">Bajamos las verduras, ponemos el aceite y seleccionamos 7 minutos, velocidad 1, temperatura varoma.<\/li>\n<li class=\"instruction\">Agregamos las salchichas en rodajas, salpimentamos y seleccionamos 3 minutos, velocidad cuchara, giro a la izquierda, temperatura varoma.<\/li>\n<li class=\"instruction\">Extendemos la masa en forma de rect\u00e1ngulo.<\/li>\n<li class=\"instruction\">Ponemos en el centro el relleno del vaso.<\/li>\n<li class=\"instruction\">Damos unos cortes en los laterales de la masa en forma inclinada y vamos echando cada tira hacia encima del relleno, tap\u00e1ndolo y haciendo la forma de la trenza.<\/li>\n<li class=\"instruction\">Metemos la empanada con forma de trenza en el horno.<\/li>\n<li class=\"instruction\">Horneamos a 180 grados unos 30 minutos m\u00e1s o menos o hasta que veamos la empanada dorada.<\/li>\n<li class=\"instruction\">Sacamos y servimos.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una empanada con forma de trenza y rellena de salchichas. Un estupendo segundo plato para los m\u00e1s peque\u00f1os de la casa.<\/p>\n","protected":false},"author":12,"featured_media":37903,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-37897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=37897"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37897\/revisions"}],"predecessor-version":[{"id":37904,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37897\/revisions\/37904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/37903"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=37897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=37897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=37897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}