{"id":37954,"date":"2015-02-01T12:58:38","date_gmt":"2015-02-01T16:58:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=37954"},"modified":"2015-02-01T12:58:38","modified_gmt":"2015-02-01T16:58:38","slug":"arrancan-los-carnavales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/arrancan-los-carnavales\/","title":{"rendered":"\u00a1Arrancan los Carnavales!"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/carnaval05b13.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-14946 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/carnaval05b13.jpg\" alt=\"carnaval05b13\" width=\"600\" height=\"400\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/carnaval05b13.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/02\/carnaval05b13-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><br \/>\nSANTIAGO. El escenario ya est\u00e1 listo para que los pueblos de la regi\u00f3n del Cibao reciban a miles de personas en el primer desfile de carnaval este domingo 1ro de febrero, la fiesta popular que acoge a grandes y chicos, sin importar su estrato social.<!--more--><\/p>\n<p>La Vega, Santiago, Bonao y Cotu\u00ed son cuatro ciudades que atraen la atenci\u00f3n de la poblaci\u00f3n durante estas fiestas. Como cada a\u00f1o, el Carnaval ser\u00e1 celebrado durante todo el mes de febrero, donde se pone de manifiesto la creatividad del dominicano.<\/p><\/div>\n<p>En la ciudad Ol\u00edmpica, la celebraci\u00f3n del Carnaval empez\u00f3 desde el domingo 25 con el desfile de apertura, y continuar\u00e1 este s\u00e1bado con la presentaci\u00f3n de Eddy Herrera, Shellow Chaq, El Chaval y Dito Bernard. Tambi\u00e9n Los Teke Teke. Mientras, la salida oficial de los famosos Diablos Cojuelos ser\u00e1 este domingo.<\/p>\n<div>En Santiago, el \u00e1rea Monumental, donde se realiza el carnaval, ha sido convertida en un escenario ideal para la imaginaci\u00f3n, la creatividad y las tradiciones, donde todos son protagonistas, y convergen en el espacio m\u00e1s popular de la ciudad. All\u00ed en el VIP Presidente Divas by Jim\u00e9nez estar\u00e1 amenizando con sus merengues desde las 6:00 de la tarde.<\/div>\n<div>\nEl montaje popular, dedicado en esta versi\u00f3n al Comit\u00e9 de Fiestas y Costumbres de Santiago, cuanta con una plataforma t\u00e9cnica y de seguridad para garantizar el sano entretenimiento a toda la familia.<\/div>\n<div>\nEn este calentamiento se espera la participaci\u00f3n de todos los grupos de lechones, personajes independientes y la poblaci\u00f3n en sentido general que disfruta del carnaval.<\/div>\n<div>\nEn Bonao, esta festividad tambi\u00e9n involucra a las grandes masas, quienes acuden a las principales calles y avenidas para ver pasar a los Macaraos, grupos y personajes.<\/div>\n<div>\nEl carnaval de Cotu\u00ed, en la provincia Juan S\u00e1nchez Ram\u00edrez, es uno de los m\u00e1s antiguos y sus personajes principales son los papeluses y platanuses, ya que los trajes son confeccionados con ese tipo de material.<\/div>\n<div>\nEn otros pueblos donde se celebra esta fiesta popular son Puerto Plata, Fantino, Saman\u00e1, San Francisco de Macor\u00eds, Salcedo, Valverde, Dajab\u00f3n, Moca, R\u00edo San Juan, Montecristi, entre otros.<\/div>\n<div>\nEn cada uno de estos lugares, durante los cuatro domingos del mes de febrero se realizan desfiles llenos de color que inundan sus calles con un ambiente musical y festivo.<\/div>\n<div>\nEn La Vega<\/div>\n<div>La primera salida de los diablos cojuelos del carnaval Vegano este domingo 1ro de febrero finaliza con el acostumbrado concierto masivo en el Estadio Ol\u00edmpico de la Vega a las 8:00 de la noche en una producci\u00f3n del Grupo Medrano.<\/div>\n<div>\nLa apertura musical de la fiesta popular organizada por el Comit\u00e9 Organizador del Carnaval Vegano (Cocave), el Comit\u00e9 de Apoyo al Carnaval y el Ayuntamiento del municipio La Vega, contar\u00e1 con la m\u00fasica del cantante puertorrique\u00f1o de reggaet\u00f3n Farruko, la bachata de Elvis Mart\u00ednez y el cantante de urbano Mozart La Para.<\/div>\n<div>\nEl Carnaval Vegano estar\u00e1 en las calles con el brillo y el colorido de m\u00e1s de 100 comparsas durante los cuatro domingos de febrero, y al final de cada una de las salidas el p\u00fablico se traslada, como todos los a\u00f1os, hasta el Estadio Ol\u00edmpico para disfrutar de los conciertos.<\/div>\n<div>\nLa animaci\u00f3n de esta masiva velada que re\u00fane a decenas de miles de personas cada domingo en La Vega estar\u00e1 a cargo de Roberto Rodr\u00edguez, Yokasta y Carolyn Aquino, entre otros.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTIAGO. El escenario ya est\u00e1 listo para que los pueblos de la regi\u00f3n del Cibao reciban a miles de personas en el primer desfile de carnaval este domingo 1ro de febrero, la fiesta popular que acoge a grandes y chicos, sin importar su estrato social.<\/p>\n","protected":false},"author":12,"featured_media":14946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-37954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=37954"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37954\/revisions"}],"predecessor-version":[{"id":37955,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/37954\/revisions\/37955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/14946"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=37954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=37954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=37954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}