{"id":38006,"date":"2015-02-02T11:38:31","date_gmt":"2015-02-02T15:38:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38006"},"modified":"2015-02-02T11:38:31","modified_gmt":"2015-02-02T15:38:31","slug":"por-que-el-2-de-febrero-es-un-dia-clave-del-invierno","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/por-que-el-2-de-febrero-es-un-dia-clave-del-invierno\/","title":{"rendered":"\u00bfPor qu\u00e9 el 2 de febrero es un d\u00eda clave del invierno?"},"content":{"rendered":"<p class=\"p\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/meteo2-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38008 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/meteo2-644x362.jpg\" alt=\"meteo2--644x362\" width=\"644\" height=\"362\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/meteo2-644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/meteo2-644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><br \/>\nDesde antiguo, los agricultores miraban al cielo el 2 de febrero, una fecha clave para predecir c\u00f3mo ser\u00e1 lo que queda de invierno en este d\u00eda que coincide con el ecuador de esta estaci\u00f3n meteorol\u00f3gica. A partir de hoy quedan m\u00e1s o menos los mismos d\u00edas de invierno que los ya transcurridos desde el 21 de diciembre, el d\u00eda m\u00e1s corto del a\u00f1o, es el solsticio de invierno, que marca el comienzo de la estaci\u00f3n invernal.<!--more--><\/p>\n<p class=\"p\">A principios de febrero, los d\u00edas ya tienen una hora m\u00e1s, como recuerda el refranero (por San Blas, ma\u00f1ana d\u00eda 3, una horam\u00e1s), y las g\u00e9lidas noches de enero, que suelen ser despejadas, se van acortando. Por eso la Candelaria marcaba el momento de volver a sembrar los campos, despu\u00e9s de dejar atr\u00e1s la primera mitad del invierno, m\u00e1s fr\u00eda y oscura. Pero hab\u00eda que estar seguro antes de sembrar.<\/p>\n<p class=\"p\">Son varios los refranes que, como un registro meteorol\u00f3gico oral, recuerdan que este d\u00eda predice c\u00f3mo ser\u00e1 lo que queda de invierno: El m\u00e1s conocido: Si por la candelaria plora [llueve], ya est\u00e1 el invierno fora. Y si no plora, ni dentro ni fora. Pero si da en re\u00edr [hacer sol], el inverno por venir. Y si no ha nevado y quiere nevar, invierno por comenzar.<\/p>\n<p class=\"p\">Y es que, si en esta \u00e9poca del a\u00f1o los d\u00edas son soleados, y en especial las noches despejadas, se producen heladas, explica el meteor\u00f3logo Jos\u00e9 Miguel Vi\u00f1as, en su libro \u201cPreguntas al aire\u201d (Alianza Editorial). De nuevo el refranero lo refleja: \u201cM\u00e1s vale ver al lobo entre las ovejas que el sol el d\u00eda de Candelas\u201d<\/p>\n<p class=\"p\">Por la trascendencia de ese d\u00eda sobre la agricultura, en los pa\u00edses detradici\u00f3n cat\u00f3lica en la Candelaria, Patrona de Canarias, se celebra la fiesta de las candelas [velas], o del triunfo de la luz, durante la cual se bendec\u00edan velas para conmemorar esta fecha tan se\u00f1alada para los agricultores. Las velas, una vez bendecidas, se guardaban en las casas para alejar los malos esp\u00edritus y las tormentas, sobre todo de granizo, que pod\u00edan da\u00f1ar las cosechas.<\/p>\n<h4 class=\"ladillo\">El equivalente americano<\/h4>\n<p class=\"p\">En Estados Unidos y Canad\u00e1 este d\u00eda se celebra la conocida fiesta de la Marmota, equivalente a la Candelaria. Los granjeros utilizan a estos roedores para predecir el tiempo. Las marmotas, como los osos, hibernan durante el inverno y desde antiguo, tanto en el Viejo como en el Nuevo Continente, se ha observado su reacci\u00f3n en este d\u00eda especial. La televisi\u00f3n estadounidense transmite esta tradici\u00f3n en la que a primera hora de la ma\u00f1ana se saca de su madriguera a una marmota, apodada Phil. Si hay sol y el roedor ve proyectada su sombra, quedan seis semanas m\u00e1s de invierno [la candelaria da en re\u00edr, seg\u00fan nuestro refranero, el invierno por vernir]. Si amanece cubierto y Phil no proyecta ninguna sombra, lo peor del invierno ya ha pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde antiguo, los agricultores miraban al cielo el 2 de febrero, una fecha clave para predecir c\u00f3mo ser\u00e1 lo que queda de invierno en este d\u00eda que coincide con el ecuador de esta estaci\u00f3n meteorol\u00f3gica. A partir de hoy quedan m\u00e1s o menos los mismos d\u00edas de invierno que los ya transcurridos desde el 21 de diciembre, el d\u00eda m\u00e1s corto del a\u00f1o, es el solsticio de invierno, que marca el comienzo de la estaci\u00f3n invernal.<\/p>\n","protected":false},"author":12,"featured_media":38008,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-38006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38006"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38006\/revisions"}],"predecessor-version":[{"id":38009,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38006\/revisions\/38009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38008"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}