{"id":38047,"date":"2015-02-03T07:29:54","date_gmt":"2015-02-03T11:29:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=38047"},"modified":"2015-02-02T18:33:18","modified_gmt":"2015-02-02T22:33:18","slug":"solo-el-10-de-los-usuarios-aprovecha-sus-smartphones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/solo-el-10-de-los-usuarios-aprovecha-sus-smartphones\/","title":{"rendered":"S\u00f3lo el 10% de los usuarios aprovecha sus smartphones"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/motorola-droid-maxx.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38048 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/motorola-droid-maxx.jpg\" alt=\"motorola-droid-maxx\" width=\"660\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/motorola-droid-maxx.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/02\/motorola-droid-maxx-300x159.jpg 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a><br \/>\nHoy por hoy, los tel\u00e9fonos inteligentes o <strong><em>smartphones <\/em><\/strong>integran funciones similares a los de un ordenador de sobremesa; sin embargo, estos no resultan pr\u00e1cticos para la mayor\u00eda de personas. Una encuesta de Gabinete y Comunicaci\u00f3n Estrat\u00e9gica (GCE) revel\u00f3 que s\u00f3lo el diez por ciento de los usuarios <strong>aprovecha la capacidad de estos dispositivos<\/strong>.<!--more--><\/p>\n<p>El informe de la GCE revel\u00f3 que\u00a074.4 por ciento de los entrevistados v\u00eda telef\u00f3nica en todo el pa\u00eds cuenta con un tel\u00e9fono m\u00f3vil y 53.3 por ciento poseen un <em>smartphone <\/em>o una tableta.\u00a0Al indagar cu\u00e1les son los usos que le dan, 29 por ciento afirm\u00f3 que los emplean para hablar; 24 por ciento manda mensajes SMS y <em>apps <\/em>de mensajer\u00eda, 15 por ciento revisa las redes sociales, 12 por ciento buscan informaci\u00f3n y tres por ciento leen noticias o ven v\u00eddeos.<\/p>\n<p>Los avances tecnol\u00f3gicos han convertido a los tel\u00e9fonos m\u00f3viles en herramientas que agilizan los h\u00e1bitos de consumo; por ejemplo, buscar un producto, acceder a mapas y usar aplicaciones que brindan servicios similares a los de las computadoras de escritorio.<\/p>\n<p>Aunque el acceso a Internet a\u00fan es bajo en todo el pa\u00eds, 90 por ciento de los entrevistados por GCE considera importante estar conectados la s\u00faper carretera de la informaci\u00f3n y 57.6 por ciento ve positivo tener una conexi\u00f3n permanente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy por hoy, los tel\u00e9fonos inteligentes o smartphones integran funciones similares a los de un ordenador de sobremesa; sin embargo, estos no resultan pr\u00e1cticos para la mayor\u00eda de personas. Una encuesta de Gabinete y Comunicaci\u00f3n Estrat\u00e9gica (GCE) revel\u00f3 que s\u00f3lo el diez por ciento de los usuarios aprovecha la capacidad de estos dispositivos.<\/p>\n","protected":false},"author":12,"featured_media":38048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-38047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=38047"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38047\/revisions"}],"predecessor-version":[{"id":38049,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/38047\/revisions\/38049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/38048"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=38047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=38047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=38047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}